{"id":58096,"date":"2016-08-17T09:27:41","date_gmt":"2016-08-17T13:27:41","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=58096"},"modified":"2016-08-17T09:27:41","modified_gmt":"2016-08-17T13:27:41","slug":"pujols-esta-a-un-jonron-de-alcanzar-a-mcgwire","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/pujols-esta-a-un-jonron-de-alcanzar-a-mcgwire\/","title":{"rendered":"Pujols est\u00e1 a un jonr\u00f3n de alcanzar a McGwire"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_mlb_g_pujols_gb1_200.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17166 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2012\/05\/sosua_images_mlb_g_pujols_gb1_200.jpg\" alt=\"mlb_g_pujols_gb1_200\" width=\"200\" height=\"300\" \/><\/a>Houston (EEUU), (EFE).- El dominicano Albert Pujols se vol\u00f3 la barda y queda a s\u00f3lo un cuadrangular de ingresar a la lista de los 10 mejores toleteros en la historia de la Grandes Ligas y se convirti\u00f3 en el pelotero latinoamericano m\u00e1s destacado de la jornada en el b\u00e9isbol profesional de las mayores.<!--more--><\/p>\n<p>Mientras que el segunda base venezolano Jos\u00e9 Altuve lleg\u00f3 a los 1.000 imparables de por vida e impone marca de franquicia con los Astros de Houston. \u00a0 Pujols conect\u00f3 su cuadrangular n\u00famero 582 de por vida y los Angelinos de Los \u00c1ngeles vencieron 7-6 a los Marineros de Seattle, que luchan por estar en la fase final de la Liga Americana. \u00a0 Para Pujols (22) fue el primero que peg\u00f3 desde el pasado 3 de agosto cuando conect\u00f3 contra los Atl\u00e9ticos de Oakland.<\/p>\n<p>Esta vez lo hizo en el sexto episodio con dos corredores por delante y sigue acerc\u00e1ndose a marca hist\u00f3rica en el apartado de cuadrangulares.<\/p>\n<p>El toletero dominicano se queda a s\u00f3lo un cuadrangular de igualar a Mark McGwire (583) en el d\u00e9cimo lugar de la lista de todos los tiempos de las mayores. \u00a0 Pujols ingresar\u00eda al Club de los mejores 10 jonrones en la historia de las Grandes Ligas y ser\u00eda el \u00fanico jugador en activo que se encuentra en ese grupo selecto.<\/p>\n<p>Su compatriota el primera base Jeffry Marte (9) peg\u00f3 de cuatro esquinas en el octavo episodio, solitario. \u00a0 El cerrador mexicano Fernando Salas (3) lanz\u00f3 un episodio, permiti\u00f3 imparable y se acredit\u00f3 el rescate.<\/p>\n<p>El abridor mexicano Jaime Garc\u00eda lanz\u00f3 cinco episodios y con el respaldo de dos cuadrangulares llev\u00f3 a los Cardenales de San Luis a una victoria por 8-5 sobre los Astros de Houston. \u00a0 Garc\u00eda (10-8) permiti\u00f3 siete imparables, tres vuelacercas, cinco carreras, dio tres bases y sac\u00f3 dos ponches, realiz\u00f3 97 env\u00edos, 61 perfectos contra 26 enemigos y dej\u00f3 en 4.11 su efectividad.<\/p>\n<p>Por los Astros el primera base venezolano Marwin Gonz\u00e1lez (11) mand\u00f3 la pelota fuera de campo en el tercero, solo. \u00a0 Altuve peg\u00f3 sencillo en la novena entrada y lleg\u00f3 a 1.000 imparables de por vida, convirti\u00e9ndose en el jugador que llega m\u00e1s r\u00e1pido en la historia de la franquicia en alcanzar esa marca.<\/p>\n<p>El segunda base venezolano de los Astros lo hizo en 786 juegos y supera la marca del dominicano C\u00e9sar Cede\u00f1o, que alcanz\u00f3 los 1.000 imparables en 889 juegos, un partido m\u00e1s r\u00e1pido que Jeff Bagwell. \u00a0 Encarnaci\u00f3n se vol\u00f3 la barda en el triunfo de los Azulejos de Toronto, que vencieron 12-6 a los Yanquis de Nueva York.<\/p>\n<p>Con su bambinazo Encarnaci\u00f3n (34) lleg\u00f3 a 302 cuadrangulares de por vida, superando a su compatriota Jos\u00e9 Bautista y a Rogers Hornsby y queda en el lugar 137 en la lista de todos los tiempos en solitario.<\/p>\n<p>Encarnaci\u00f3n queda a dos jonrones de empatar a Steve Finley en el lugar 136 de las mayores. \u00a0 Esta vez lo hizo en el octavo episodio con un corredor por delante. \u00a0 El cerrador dominicano Jeurys Familia se afianza l\u00edder en rescates al acreditarse salvamento en el triunfo de los Mets de Nueva York por 7-5 sobre los Diamondbacks de Arizona. \u00a0 Familia (40) lanz\u00f3 una entrada y se apunt\u00f3 el rescate, retir\u00f3 a un bateador rival por la v\u00eda del ponche y con su salvamento, se afianza como l\u00edder de las mayores en ese apartado.<\/p>\n<p>El dominicano supera a su m\u00e1s cercano seguidor Zach Britton, de los Orioles de Baltimore, con tres rescates, luego de que \u00e9ste suma 37 en la competici\u00f3n. \u00a0 Por los Diamondbacks el guardabosques cubano Yasmany Tom\u00e1s (23) conect\u00f3 de vuelta entera en el cuarto episodio contra el abridor Noah Syndergaard, solo.<\/p>\n<p>El abridor dominicano Ervin Santana lanz\u00f3 siete episodios en blanco, super\u00f3 a su compatriota Joel de la Cruz, y llev\u00f3 a los Mellizos de Minnesota a un triunfo por 4-2 sobre los Bravos de Atlanta, en duelo de equipos perdedores. \u00a0 Santana (6-9) permiti\u00f3 cuatro imparables, dio dos bases y abanic\u00f3 a seis para ganar, con 107 lanzamientos, 64 perfectos contra 27 enemigos y dej\u00f3 en 3.43 su efectividad.<\/p>\n<p>El cubano Yasmani Grandal peg\u00f3 de vuelta entera en el triunfo de los Dodgers de Los \u00c1ngeles por 15-5 sobre los Filis de Filadelfia, que recuperaron el liderato en la Divisi\u00f3n Oeste de la Liga Nacional. \u00a0 Grandal (19) peg\u00f3 de cuatro esquinas en la sexta entrada, solo, contra Vince Vel\u00e1squez, con dos outs en el episodio.<\/p>\n<p>Por los Filis el segunda base venezolano C\u00e9sar Hern\u00e1ndez (3) conect\u00f3 de vuelta entera en el sexto, solo. \u00a0 El parador en corto puertorrique\u00f1o Javier B\u00e1ez peg\u00f3 de cuatro esquinas en el triunfo de los Cachorros de Chicago por 4-1 sobre los Cerveceros de Milwaukee en el segundo partido de una doble jornada. \u00a0 El cerrador cubano Aroldis Chapman (6) trabaj\u00f3 un tercio de episodio y se apunt\u00f3 el rescate, dando una base y retir\u00f3 a un bateador por la v\u00eda del ponche.<\/p>\n<p>Mientras que B\u00e1ez (13) mand\u00f3 la pelota a la calle en el sexto contra el relevo Rob Scahill, con uno en base. \u00a0 Por los Cerveceros el antesalista venezolano Hern\u00e1n P\u00e9rez (10) conect\u00f3 de cuatro esquinas en la novena entrada, solo.<\/p>\n<p>El relevo dominicano Antonio Bastardo se acredit\u00f3 el triunfo de los Piratas de Pittsburgh por 4-3 sobre los Gigantes de San Francisco. \u00a0 Bastardo (1-0) se apunt\u00f3 la victoria en un episodio, permitiendo un imparable.EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Houston (EEUU), (EFE).- El dominicano Albert Pujols se vol\u00f3 la barda y queda a s\u00f3lo un cuadrangular de ingresar a la lista de los 10 mejores toleteros en la historia de la Grandes Ligas y se convirti\u00f3 en el pelotero latinoamericano m\u00e1s destacado de la jornada en el b\u00e9isbol profesional de las mayores.<\/p>\n","protected":false},"author":12,"featured_media":17166,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-58096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=58096"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58096\/revisions"}],"predecessor-version":[{"id":58097,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58096\/revisions\/58097"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/17166"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=58096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=58096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=58096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}