{"id":58115,"date":"2016-08-17T12:46:20","date_gmt":"2016-08-17T16:46:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=58115"},"modified":"2016-08-17T09:50:29","modified_gmt":"2016-08-17T13:50:29","slug":"es-este-el-campeon-olimpico-mas-triste-de-la-historia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/es-este-el-campeon-olimpico-mas-triste-de-la-historia\/","title":{"rendered":"\u00bfEs este el campe\u00f3n ol\u00edmpico m\u00e1s triste de la historia?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/08\/ganador-mas-triste-de-las-olimpiadas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-58118\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/08\/ganador-mas-triste-de-las-olimpiadas.jpg\" alt=\"ganador mas triste de las olimpiadas\" width=\"750\" height=\"422\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/08\/ganador-mas-triste-de-las-olimpiadas.jpg 750w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/08\/ganador-mas-triste-de-las-olimpiadas-300x169.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a>El atleta norcoreano Ri Se-gwang ha ganado el oro para su pa\u00eds, pero su reacci\u00f3n tras la victoria dista de la habitual entre los deportistas vencedores.<!--more--><\/p>\n<div class=\"arcticle-content\">\n<p>El atleta norcoreano Ri Se-gwang ha triunfado con una medalla de oro en las finales de salto en los\u00a0<a href=\"https:\/\/actualidad.rt.com\/actualidad\/215188-debes-saber-jjoo-rio-janeiro\" target=\"_blank\">Juegos Ol\u00edmpicos<\/a>\u00a0en R\u00edo de Janeiro este\u00a015 de agosto, informa\u00a0<a href=\"http:\/\/www.reuters.com\/article\/us-olympics-rio-agymnastics-m-vault-idUSKCN10Q1TF\" target=\"_blank\">Reuters<\/a>. Su reacci\u00f3n ante la victoria ha sugerido varias opiniones acerca de sus sentimientos sobre los resultados logrados.<\/p>\n<p>\u00abEsta medalla de oro es una alegr\u00eda para mi pa\u00eds y creo que dar\u00e1 un sentido de victoria y coraje a mi pueblo\u00bb, declar\u00f3 Ri Se-gwang tras realizar su salto ganador.\u00a0Este bicampe\u00f3n mundial de 31 a\u00f1os se ha convertido en el segundo atleta norcoreano que ha ganado el oro ol\u00edmpico en gimnasia.<\/p>\n<div class=\"arcticle__read-more read-more\">\n<div class=\"read-more__title\">Sin embargo, el campe\u00f3n no solo ha atra\u00eddo la atenci\u00f3n del p\u00fablico por su victoria, sino por el hecho de que se mostr\u00f3 reservado tras las competiciones y algunos medios calificaron su reacci\u00f3n de \u00abtriste\u00bb e incluso de \u00abmiserable\u00bb ya que, a diferencia de otros ganadores y sus competidores de salto, no sonre\u00eda y no presentaba las se\u00f1ales de gran alegr\u00eda caracter\u00edsticas de los campeones ol\u00edmpicos.<\/div>\n<\/div>\n<p>Por ejemplo, el diario brit\u00e1nico\u00a0<a href=\"http:\/\/www.mirror.co.uk\/news\/world-news\/athlete-saddest-gold-medallist-rio-8643403#ICID=sharebar_twitter\" target=\"_blank\">&#8216;Mirror&#8217;<\/a>\u00a0sugiere que el atleta de hecho \u00abera m\u00e1s emocional tras haber probado el mundo libre\u00bb. Seg\u00fan el peri\u00f3dico,\u00a0Ri Se-gwang\u00a0\u00absabe que pronto volver\u00e1 a la empobrecida Corea del Norte\u00bb y \u00abtrocar\u00e1 el espl\u00e9ndido alojamiento de los atletas en R\u00edo de Janeiro por el entorno sombr\u00edo de Pionyang\u00bb.<\/p>\n<p>Por su parte, el propio campe\u00f3n ha destacado que \u00abestaba lleno de muchas emociones y alegr\u00eda\u00bb porque pens\u00f3 que \u00abera capaz de dar un sentido de victoria y gloria a nuestro l\u00edder\u00bb. Durante la ceremonia de la entrega de medallas, el deportista contuvo las l\u00e1grimas y mantuvo su mano en la sien derecha mientras sonaba el himno nacional y se izaba la bandera de Corea del Norte.<\/p>\n<p>La plata recay\u00f3 en el atleta ruso Den\u00eds Abli\u00e1zin mientras que el japon\u00e9s Kenzo Shirai se llev\u00f3 el bronce.<\/p>\n<div class=\"arcticle-media arcticle-media_js_slider\"><img decoding=\"async\" src=\"https:\/\/esp.rt.com\/actualidad\/public_images\/2016.08\/original\/57b42ccfc36188f8598b4591.jpg\" alt=\"\" \/><\/p>\n<div class=\"arcticle-media__caption\"><\/div>\n<\/div>\n<div class=\"clears mh\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El atleta norcoreano Ri Se-gwang ha ganado el oro para su pa\u00eds, pero su reacci\u00f3n tras la victoria dista de la habitual entre los deportistas vencedores.<\/p>\n","protected":false},"author":12,"featured_media":58118,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-58115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=58115"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58115\/revisions"}],"predecessor-version":[{"id":58119,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58115\/revisions\/58119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/58118"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=58115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=58115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=58115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}