{"id":58456,"date":"2016-09-02T12:07:56","date_gmt":"2016-09-02T16:07:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=58456"},"modified":"2016-09-02T12:07:56","modified_gmt":"2016-09-02T16:07:56","slug":"condenan-a-20-anos-dos-hombres-acusados-de-homicidio-y-agresion-fisica","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/condenan-a-20-anos-dos-hombres-acusados-de-homicidio-y-agresion-fisica\/","title":{"rendered":"Condenan a 20 a\u00f1os dos hombres acusados de homicidio y agresi\u00f3n f\u00edsica"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-58457 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/510A55E8-BFB7-43E3-A02C-26A7CE7BA890.jpg__778__440__CROPz3x778y440-300x170.jpg\" alt=\"510A55E8-BFB7-43E3-A02C-26A7CE7BA890.jpg__778__440__CROPz3x778y440\" width=\"300\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/510A55E8-BFB7-43E3-A02C-26A7CE7BA890.jpg__778__440__CROPz3x778y440-300x170.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/510A55E8-BFB7-43E3-A02C-26A7CE7BA890.jpg__778__440__CROPz3x778y440-768x434.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/510A55E8-BFB7-43E3-A02C-26A7CE7BA890.jpg__778__440__CROPz3x778y440-595x340.jpg 595w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/510A55E8-BFB7-43E3-A02C-26A7CE7BA890.jpg__778__440__CROPz3x778y440.jpg 778w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Santo Domingo.- El Tribunal Colegiado de San Crist\u00f3bal conden\u00f3 a 20 a\u00f1os de prisi\u00f3n a dos hombres que fueron hallados culpables de los delitos de homicidio y agresi\u00f3n f\u00edsica. La sentencia fue dictada en contra de Yeison Suero Romero (alias Eloy) y de Nelson de Jes\u00fas Ortega, declarados culpables de haber provocado la muerte con un arma blanca a Samuel Osvaldo Hern\u00e1ndez Rosario y provocar heridas Nelson De Los Santos Do\u00f1\u00e9.<!--more--><\/p>\n<p>El Ministerio P\u00fablico record\u00f3 hoy que el hecho se produjo en horas de la madrugada del 12 de abril del pasado a\u00f1o, durante un enfrentamiento entre dos grupos de j\u00f3venes.<\/p>\n<p>Suero Romero y De Jes\u00fas Ortega deber\u00e1n cumplir la sentencia en un centro penitenciario de la provincia San Crist\u00f3bal.EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.- El Tribunal Colegiado de San Crist\u00f3bal conden\u00f3 a 20 a\u00f1os de prisi\u00f3n a dos hombres que fueron hallados culpables de los delitos de homicidio y agresi\u00f3n f\u00edsica. La sentencia fue dictada en contra de Yeison Suero Romero (alias Eloy) y de Nelson de Jes\u00fas Ortega, declarados culpables de haber provocado la muerte con un arma blanca a Samuel Osvaldo Hern\u00e1ndez Rosario y provocar heridas Nelson De Los Santos Do\u00f1\u00e9.<\/p>\n","protected":false},"author":9,"featured_media":58457,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-58456","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=58456"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58456\/revisions"}],"predecessor-version":[{"id":58459,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58456\/revisions\/58459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/58457"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=58456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=58456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=58456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}