{"id":58486,"date":"2016-09-03T11:35:05","date_gmt":"2016-09-03T15:35:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=58486"},"modified":"2016-09-03T11:35:05","modified_gmt":"2016-09-03T15:35:05","slug":"residentes-en-diferentes-sectores-de-puerto-plata-se-quejan-por-falta-de-agua-potable","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/residentes-en-diferentes-sectores-de-puerto-plata-se-quejan-por-falta-de-agua-potable\/","title":{"rendered":"Residentes en diferentes sectores de Puerto Plata se quejan por falta de agua potable"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-58487 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/2EA49418-7C39-48A3-B1A1-FC6E0A00579D.jpg__778__440__CROPz3x778y440-300x170.jpg\" alt=\"2EA49418-7C39-48A3-B1A1-FC6E0A00579D.jpg__778__440__CROPz3x778y440\" width=\"300\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/2EA49418-7C39-48A3-B1A1-FC6E0A00579D.jpg__778__440__CROPz3x778y440-300x170.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/2EA49418-7C39-48A3-B1A1-FC6E0A00579D.jpg__778__440__CROPz3x778y440-768x434.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/2EA49418-7C39-48A3-B1A1-FC6E0A00579D.jpg__778__440__CROPz3x778y440-595x340.jpg 595w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/2EA49418-7C39-48A3-B1A1-FC6E0A00579D.jpg__778__440__CROPz3x778y440.jpg 778w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>PUERTO PLATA.-\u00a0Las quejas por la falta de agua potable se han convertido en una constante en las \u00faltimas semanas entre los residentes en distintos sectores de \u00e9sta ciudad, quienes al momento de emitir sus denuncias al respecto hablan barbaridades de los ejecutivos de la Corporaci\u00f3n de Acueductos y Alcantarillados de Puerto Plata (CORAAPPLATA).<!--more--><\/p>\n<p>Entre las m\u00faltiples denuncias pueblerinas por la falta del servicio de agua, provienes de sectores populares como son El Javillar, La Viara o el Barrio Codetel, pero tambi\u00e9n el lamento sobre dicha problem\u00e1tica se escucha desde las urbanizaciones Torre Alta, Aros Carraus, Los Maestros, entre otras donde los ciudadanos est\u00e1n muy irritados.<\/p>\n<p>A la marcada deficiencia en el suministro de agua potable, se le a\u00f1ade dos problem\u00e1ticas adicionales que tambi\u00e9n han sido criticadas por los puertoplate\u00f1os como son el aumento en la facturaci\u00f3n mensual y sin consultar a los consumidores, adem\u00e1s de los tratos abusivos por parte de empleados de la empresa Triple A en contra de usuarios.<\/p>\n<p>Las damas Lourdes Paula Pimentel y Ericka Mart\u00ednez, sostuvieron que fueron agredidas verbal y casi f\u00edsicamente por empleados de la compa\u00f1\u00eda Triple A cuando acudieron a la oficina central de la CORAAPPLATA a reclamar por un monto econ\u00f3mico excesivo que sali\u00f3 reflejado en la factura del mes, siendo sacadas a la fuerza por dos agentes de seguridad.<\/p>\n<p>Mientras, que en casi todos los sectores, urbanizaciones y residenciales de Puerto Plata la escasez del agua potable ha dado lugar a que se incremente la compra del vital l\u00edquido a los camiones cisternas que debido a la amplia demanda tienen un jugoso negocio con dicha acci\u00f3n comercial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.-\u00a0Las quejas por la falta de agua potable se han convertido en una constante en las \u00faltimas semanas entre los residentes en distintos sectores de \u00e9sta ciudad, quienes al momento de emitir sus denuncias al respecto hablan barbaridades de los ejecutivos de la Corporaci\u00f3n de Acueductos y Alcantarillados de Puerto Plata (CORAAPPLATA).<\/p>\n","protected":false},"author":9,"featured_media":58487,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-58486","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=58486"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58486\/revisions"}],"predecessor-version":[{"id":58488,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/58486\/revisions\/58488"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/58487"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=58486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=58486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=58486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}