{"id":59032,"date":"2016-09-19T08:09:47","date_gmt":"2016-09-19T12:09:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=59032"},"modified":"2016-09-19T08:09:47","modified_gmt":"2016-09-19T12:09:47","slug":"la-policia-vincula-hijo-de-percival-pena-en-asalto-a-camion-de-valores","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-policia-vincula-hijo-de-percival-pena-en-asalto-a-camion-de-valores\/","title":{"rendered":"La Polic\u00eda vincula hijo de Percival Pe\u00f1a en asalto a cami\u00f3n de valores"},"content":{"rendered":"<p>Santo Domingo.La Polic\u00eda se\u00f1ala al hijo del exgeneral Percival Pe\u00f1a, John Emilio Percival Matos, como uno de los coautores del asalto a un cami\u00f3n de valores la pasada semana que dej\u00f3 un vigilante muerto y otro gravemente herido, en el sector de Bella Vista de esta capital, y que cargaron con m\u00e1s de tres millones de pesos.<!--more--><\/p>\n<figure id=\"attachment_268662\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/i2.wp.com\/ensegundos.do\/wp-content\/uploads\/2016\/09\/John-Emilio-Perciva.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-268662\" src=\"http:\/\/i2.wp.com\/ensegundos.do\/wp-content\/uploads\/2016\/09\/John-Emilio-Perciva.jpg?resize=591%2C316\" sizes=\"auto, (max-width: 591px) 100vw, 591px\" srcset=\"http:\/\/i2.wp.com\/ensegundos.do\/wp-content\/uploads\/2016\/09\/John-Emilio-Perciva.jpg?w=685 685w, http:\/\/i2.wp.com\/ensegundos.do\/wp-content\/uploads\/2016\/09\/John-Emilio-Perciva.jpg?resize=300%2C160 300w, http:\/\/i2.wp.com\/ensegundos.do\/wp-content\/uploads\/2016\/09\/John-Emilio-Perciva.jpg?resize=640%2C342 640w, http:\/\/i2.wp.com\/ensegundos.do\/wp-content\/uploads\/2016\/09\/John-Emilio-Perciva.jpg?resize=681%2C364 681w\" alt=\"john-emilio-perciva\" width=\"591\" height=\"316\" \/><\/a><figcaption class=\"wp-caption-text\">Indica el peri\u00f3dico Diario Libre que la informaci\u00f3n se da a conocer en un comunicado enviado por la Direcci\u00f3n Central de Investigaciones y la Interpol a la Direcci\u00f3n Nacional de Migraci\u00f3n, la cual est\u00e1 firmada por el coronel Jos\u00e9 Feliz Cabrera.<\/p>\n<p>\u201cRespetuosamente nos dirigimos a ese Despacho (Direcci\u00f3n de Migraci\u00f3n), en ocasi\u00f3n de solicitarle, en la medida de las posibilidades, sean colocados sendos controles migratorios en los aeropuertos (\u2026) a los nombrados John Emilio Percival Matos C\u00e9du., No. 001-1505107-0, (\u2026) y Brayan Peter F\u00e9lix Paulino (\u2026) a requerimiento del Comandante Departamento Investigaciones de Homicidios, PN, por ser se\u00f1alados como los autores del asalto a un cami\u00f3n de valores en la plaza Bella Vista Mal, ocurrido en fecha 14-09-2016, quienes fueron identificados en el d\u00eda de hoy (ayer) y se est\u00e1n solicitando las respectivas \u00f3rdenes de arresto\u201d, dice la comunicaci\u00f3n.<\/figcaption><\/figure>\n<p><strong>Se recuerda que el exteniente del Ej\u00e9rcito Percival Matos y su esposa, Ginnssellys Halversoni V\u00e1squez, estuvieron tambi\u00e9n involucrados en el robo de un avi\u00f3n en el aeropuerto Joaqu\u00edn Balaguer (El Hig\u00fcero) en el 2013, de cuya acusaci\u00f3n fueron descargados por el Segundo Tribunal Colegiado de la C\u00e1mara Penal del Juzgado de Primera Instancia.<\/strong><\/p>\n<p>Seg\u00fan las investigaciones, los individuos que interceptaron el cami\u00f3n utilizaron un fusil M-16 para cometer el asalto y con el cual dispararon a los vigilantes, Bienvenido Garc\u00eda N\u00fa\u00f1ez, de 45 a\u00f1os, quien falleci\u00f3, y a Yervin Eduardo Cuevas Perdomo, de 33, quien se encuentra grave en el Centro M\u00e9dico Dominicano.<ins class=\"adsbygoogle\" data-ad-client=\"ca-pub-0246812289979917\" data-ad-slot=\"1045525976\" data-adsbygoogle-status=\"done\"><\/ins><ins id=\"aswift_1_expand\"><\/ins><ins id=\"aswift_1_anchor\"><\/ins><\/p>\n<p>El tambi\u00e9n imputado en el asalto, Brayan Peter F\u00e9lix Paulino, fue detenido en febrero de este a\u00f1o por supuestamente estafar a la se\u00f1ora Odette Secundina Castillo Ortega con 105 mil pesos mediante un concurso v\u00eda telef\u00f3nica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo.La Polic\u00eda se\u00f1ala al hijo del exgeneral Percival Pe\u00f1a, John Emilio Percival Matos, como uno de los coautores del asalto a un cami\u00f3n de valores la pasada semana que dej\u00f3 un vigilante muerto y otro gravemente herido, en el sector de Bella Vista de esta capital, y que cargaron con m\u00e1s de tres millones de pesos.<\/p>\n","protected":false},"author":12,"featured_media":59044,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-59032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=59032"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59032\/revisions"}],"predecessor-version":[{"id":59045,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59032\/revisions\/59045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/59044"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=59032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=59032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=59032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}