{"id":59036,"date":"2016-09-19T05:30:39","date_gmt":"2016-09-19T09:30:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=59036"},"modified":"2016-09-19T05:30:39","modified_gmt":"2016-09-19T09:30:39","slug":"yelitza-lora-transmitira-otra-cosa-via-internet","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/yelitza-lora-transmitira-otra-cosa-via-internet\/","title":{"rendered":"Yelitza Lora transmitir\u00e1 Otra Cosa v\u00eda internet"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/yelitza-lora.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-59037 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/yelitza-lora.jpg\" alt=\"yelitza-lora\" width=\"406\" height=\"270\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/yelitza-lora.jpg 620w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/09\/yelitza-lora-300x199.jpg 300w\" sizes=\"auto, (max-width: 406px) 100vw, 406px\" \/><\/a>Yelitza Lora se ha caracterizado por la presentaci\u00f3n de propuestas que apuestan a su independencia laboral. En esta ocasi\u00f3n, lo har\u00e1 bajo la plataforma digital con su espacio \u201cOtra Cosa TV\u201d en el formato de un programa de temporada.<!--more--><\/p>\n<p>La comunicadora anunci\u00f3 que a partir de octubre, el programa ser\u00e1 transmitido en Rep\u00fablica Dominicana a trav\u00e9s de www.otracosatv.com como un programa de temporada de 19 cap\u00edtulos y cada temporada ser\u00e1 grabada en diferentes pa\u00edses o ciudades; hasta ahora en agenda Santo Domingo, Santiago, Miami, Nueva York, Puerto Rico, Barcelona, Colombia, entre otras.<\/p>\n<p>Yelitza, adem\u00e1s, dijo que para desarrollar el proyecto cuenta con su propio estudio de grabaci\u00f3n y un canal oficial digital en su b\u00fasqueda de aprovechar las ventajas que ofrece hoy la tecnolog\u00eda para sus proyectos de comunicaci\u00f3n.<\/p>\n<p>\u201cHemos tenido asesor\u00eda para que Otra Cosa TV sea posible y as\u00ed conectar con una comunidad latina que se puede interesar por estos contenidos que elaboraremos\u201d, explic\u00f3 en un comunicado de prensa.<\/p>\n<p>De igual manera manifest\u00f3 que Princesa Films, luego de lo logros que junto a Ivirng Alberti alcanz\u00f3 el cortometraje \u201cLa madrastra\u201d, seguir\u00e1 trabajando en otros proyectos y que para el mes de noviembre estar\u00e1n rodando el segundo gui\u00f3n de la productora cinematogr\u00e1fica.<\/p>\n<p>Yelitza, adem\u00e1s, revel\u00f3 que representar\u00e1 la comunidad dominicana junto a Janeiro Matos, como conductores de la pr\u00f3xima gala de los premios Latin Awards Canad\u00e1 que ser\u00e1 celebrada en octubre.<\/p>\n<p>\u201cYo creo firmemente en que tenemos que mover nuestros proyectos y no quedarnos aqu\u00ed solamente. Los medios convencionales, a nivel de televisi\u00f3n y radio est\u00e1n limitados en cuanto a espacio. Por eso yo voy por otra l\u00ednea, quiero que la gente vea eso en cada uno de mis proyectos.<\/p>\n<p>Yo he visto lo mon\u00f3tono del entretenimiento local, lo repetitivo de los espacios de televisi\u00f3n que est\u00e1n en el aire\u201d, puntualiz\u00f3 Lora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yelitza Lora se ha caracterizado por la presentaci\u00f3n de propuestas que apuestan a su independencia laboral. En esta ocasi\u00f3n, lo har\u00e1 bajo la plataforma digital con su espacio \u201cOtra Cosa TV\u201d en el formato de un programa de temporada.<\/p>\n","protected":false},"author":12,"featured_media":59037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-59036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=59036"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59036\/revisions"}],"predecessor-version":[{"id":59038,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59036\/revisions\/59038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/59037"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=59036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=59036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=59036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}