{"id":59401,"date":"2016-09-28T09:41:14","date_gmt":"2016-09-28T13:41:14","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=59401"},"modified":"2016-09-28T09:41:14","modified_gmt":"2016-09-28T13:41:14","slug":"onamet-informa-onda-tropical-con-90-de-convertirse-en-ciclon-afectara-rd-el-viernes","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/onamet-informa-onda-tropical-con-90-de-convertirse-en-ciclon-afectara-rd-el-viernes\/","title":{"rendered":"ONAMET informa onda tropical con 90% de convertirse en cicl\u00f3n afectar\u00e1 RD el viernes"},"content":{"rendered":"<p class=\"post-title entry-title\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-43468 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4.jpg\" alt=\"ONAMET4\" width=\"376\" height=\"282\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4.jpg 600w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4-300x225.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/05\/ONAMET4-100x75.jpg 100w\" sizes=\"auto, (max-width: 376px) 100vw, 376px\" \/><\/a>SANTO DOMINGO.-La Oficina Nacional de Meteorolog\u00eda (ONAMET), inform\u00f3 hoy que la activa onda tropical pr\u00f3ximo a las islas de Barlovento, Antillas Menores, con posibilidades de un 90% de convertirse en cicl\u00f3n, afectar\u00e1 a Rep\u00fablica Dominicana el viernes y el fin de semana.<!--more--><\/p>\n<div id=\"post-body-7595105155750984775\" class=\"post-body entry-content\">\n<p>Dijo que mantiene la vigilancia de la evoluci\u00f3n y desplazamiento del sistema, asociado a una baja presi\u00f3n (disturbio tropical) que se localiza a unos 200 kil\u00f3metros al este\/sureste de las islas de Barlovento, y que se mueve r\u00e1pidamente hacia el oeste a unos 28 kil\u00f3metros por hora.<\/p>\n<p>Expres\u00f3 adem\u00e1s, que un ambiente relativamente tranquilo prevalecer\u00e1 durante las horas matutinas en toda la geograf\u00eda nacional, donde predominar\u00e1 un cielo con una mezcla de nubes y sol en la mayor\u00eda de las regiones del pa\u00eds, sin embargo, despu\u00e9s del medio d\u00edas se originar\u00e1n incrementos nubosos hacia el interior del pa\u00eds.<\/p>\n<p>Agreg\u00f3 que est\u00e1 situaci\u00f3n ocasionar\u00e1 aguaceros dispersos con aisladas tronadas, estando m\u00e1s concentrados hacia Los Haitises, cordillera Central y la zona fronteriza, todo esto como resultado de la combinaci\u00f3n del viento del este y los efectos locales.<\/p>\n<p>ONAMET pronostic\u00f3 que\u00a0para \u00a0este jueves habr\u00e1 un aumento significativo de la humedad ocasionando por la presencia en aguas del mar Caribe de un disturbio tropical, este aumentar\u00e1 de forma significativa la nubosidad sobre la llanura costera\u00a0y la regi\u00f3n este, ocasionando aguaceros moderados a fuertes con tormentas el\u00e9ctricas, r\u00e1fagas de vientos.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.-La Oficina Nacional de Meteorolog\u00eda (ONAMET), inform\u00f3 hoy que la activa onda tropical pr\u00f3ximo a las islas de Barlovento, Antillas Menores, con posibilidades de un 90% de convertirse en cicl\u00f3n, afectar\u00e1 a Rep\u00fablica Dominicana el viernes y el fin de semana.<\/p>\n","protected":false},"author":12,"featured_media":43468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-59401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=59401"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59401\/revisions"}],"predecessor-version":[{"id":59403,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59401\/revisions\/59403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/43468"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=59401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=59401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=59401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}