{"id":59538,"date":"2016-10-01T18:47:20","date_gmt":"2016-10-01T22:47:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=59538"},"modified":"2016-10-01T18:47:20","modified_gmt":"2016-10-01T22:47:20","slug":"tras-20-anos-ortiz-se-va-por-decision-propia-en-la-cuspide","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/tras-20-anos-ortiz-se-va-por-decision-propia-en-la-cuspide\/","title":{"rendered":"Tras 20 a\u00f1os, Ortiz se va por decisi\u00f3n propia, en la c\u00faspide"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/david-ortiz-un-inmortal.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-48047\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/david-ortiz-un-inmortal.jpg\" alt=\"david ortiz un inmortal\" width=\"521\" height=\"278\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/david-ortiz-un-inmortal.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/david-ortiz-un-inmortal-300x160.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2015\/09\/david-ortiz-un-inmortal-105x56.jpg 105w\" sizes=\"auto, (max-width: 521px) 100vw, 521px\" \/><\/a>BOSTON (AP) _ Los Marineros lo canjearon. Los Mellizos lo dieron de baja. E incluso los aficionados de Boston perdieron la fe en David Ortiz en un par de ocasiones luego que el dominicano batall\u00f3 para iniciar la pretemporada o tuvo campa\u00f1as abreviadas por lesiones.<!--more--><\/p>\n<p>Pero cuando esta temporada de los Medias Rojas haya llegado a su fin y la carrera de Ortiz termine junto con ella, ser\u00e1 por decisi\u00f3n propia. El pelotero elegido 10 veces al Juego de Estrellas y tres veces campe\u00f3n de Serie Mundial _con la posibilidad de una cuarta, si todo sale bien_ se encuentra en una de sus mejores campa\u00f1as y uno de los m\u00e1ximos cierres de una carrera en la historia del b\u00e9isbol.<\/p>\n<p>Por lo que la pregunta es: \u00bfSer\u00e1 Ortiz quien en esta ocasi\u00f3n est\u00e9 tirando la toalla demasiado pronto?<\/p>\n<p>\u201cQuer\u00edan que se retirara hace siete a\u00f1os. Y ahora que \u00e9l desea retirarse, nadie quiere que lo haga\u201d, declar\u00f3 Torii Hunter, su ex compa\u00f1ero con los Mellizos, cuando Ortiz pas\u00f3 por Minnesota este verano por \u00faltima vez. \u201cYo definitivamente pienso que retirarse en la c\u00faspide, esa es la manera de irse\u201d.<\/p>\n<p>Ortiz insiste en que esto ha terminado, y argumenta que sus pies le duelen mucho y de antemano le resulta demasiado dif\u00edcil a sus 40 a\u00f1os como para considerar el pasar laboriosamente por otra temporada.<\/p>\n<p>He aqu\u00ed un vistazo a algunos de los momentos en que la gente perdi\u00f3 la esperanza o tuvo sus dudas en el toletero de Boston:<\/p>\n<p><strong>EL CANJE<\/strong><\/p>\n<p>Seattle firm\u00f3 a Ortiz, que entonces era conocido como David Arias, un adolescente de 16 a\u00f1os en Rep\u00fablica Dominicana en 1992.<\/p>\n<p>Bateaba para .322 con 18 cuadrangulares y 93 carreras impulsadas en su primer a\u00f1o en la Categor\u00eda A un par de a\u00f1os despu\u00e9s cuando la organizaci\u00f3n evalu\u00f3 su roster, vio que de antemano contaba con un muy buen bateador designado en Edgar Mart\u00ednez, un as en el mont\u00edculo en Randy Johnson y un par de estrellas en ascenso en Ken Griffey Jr. y Alex Rodr\u00edguez.<\/p>\n<p>Los Marineros perdieron la serie de campeonato de la Liga Americana en 1995 y decidieron ir por todo la siguiente campa\u00f1a. A cinco juegos debajo en la divisi\u00f3n el 29 de agosto, Seattle adquiri\u00f3 al jugador de cuadro Dave Hollins proveniente de Minnesota a cambio de un pelotero por determinar.<\/p>\n<p>El 13 de septiembre de 1996, Ortiz fue enviado a los Mellizos para completar el canje.<\/p>\n<p><strong>DADO DE BAJA<\/strong><\/p>\n<p>Ortiz fue ascendiendo en las menores la siguiente temporada y debut\u00f3 en Grandes Ligas al ser mandado llamar en septiembre. En 2002, promediaba .272 al bate con 20 jonrones y 75 carreras remolcadas en 125 partidos.<\/p>\n<p>Al t\u00e9rmino de la campa\u00f1a, los Mellizos deb\u00edan tomar una decisi\u00f3n.<br \/>\nRevisando el historial de lesiones de Ortiz, sus limitaciones defensivas y el hecho de que se esperaba que lograra un aumento salarial en un arbitraje para ganar cerca de dos millones de d\u00f3lares en 2003, el gerente general Terry Ryan lo dio de baja a fin de crear un espacio en el roster para un pelotero de cuadro recientemente elegido en el draft, el tambi\u00e9n dominicano Jos\u00e9 Morb\u00e1n. Los Medias Rojas firmaron a Ortiz aproximadamente un mes despu\u00e9s por 1,25 millones de d\u00f3lares con el plan de dejarlo competir por turnos al bate en primera base y como bateador designado con Jeremy Giambi y Kevin Millar.<br \/>\nPara junio, Ortiz era un elemento habitual en la alineaci\u00f3n de Boston.<\/p>\n<p><strong>PROBLEMAS EN POSTEMPORADA<\/strong><\/p>\n<p>Todos en el b\u00e9isbol recuerda los actos heroicos de Ortiz en postemporada, pero no empez\u00f3 de esa manera.<\/p>\n<p>No peg\u00f3 un solo hit en sus primeros 16 turnos al bate para Boston en la Serie Divisional de la Americana en 2003 antes de conectar un doblete en el octavo inning del cuarto partido que ayud\u00f3 a los Medias Rojas a evitar la eliminaci\u00f3n. Boston termin\u00f3 perdiendo la serie por el campeonato de la Americana frente a los Yanquis de Nueva York en siete juegos.<\/p>\n<p><strong>DESPLOME<\/strong><\/p>\n<p>Ortiz bateaba por debajo de los .200 en la segunda semana de junio de 2009, y hasta mayo de la siguiente temporada.<\/p>\n<p>En 2012, jug\u00f3 apenas un partido en las \u00faltimas 10 semanas de la campa\u00f1a debido a una lesi\u00f3n en el tal\u00f3n de Aquiles derecho; sin \u00e9l, los Medias Rojas terminaron en \u00faltimo lugar divisional con la peor marca en cerca de 50 a\u00f1os. En 2014, el a\u00f1o despu\u00e9s de que gan\u00f3 su tercer campeonato con Boston y el premio al Jugador M\u00e1s Valioso de la Serie Mundial, los Medias Rojas se estancaron en el s\u00f3tano y Ortiz se perdi\u00f3 la mayor parte de la \u00faltima semana de la temporada con problemas de mu\u00f1eca.<\/p>\n<p>El 9 de junio de 2015, el dominicano promediaba .219 al bate con seis jonrones y 21 carreras producidas. Tras terminar con 37 cuadrangulares y 108 empujadas _ambas cifras sus mejores en casi una d\u00e9cada_ Ortiz reflexion\u00f3 sobre la necesidad de constantemente demostrar su calidad a los aficionados en una ciudad en la que hab\u00eda logrado pr\u00e1cticamente todo.<\/p>\n<p>\u201cSe les olvida casi todo lo que he hecho aqu\u00ed. Simplemente lo arrojan a la basura. No es que hablen sobre alguien que acaba de llegar\u201d, declar\u00f3 antes del \u00faltimo partido en casa el a\u00f1o pasado. \u201cTal parece que esperan que yo batalle para empezarme a criticar. En cualquier momento del a\u00f1o en que esto ocurre, yo simplemente me r\u00edo\u201d.<\/p>\n<p>Un mes despu\u00e9s, en su cumplea\u00f1os 40, Ortiz anunci\u00f3 que la temporada de 2016 ser\u00eda su \u00faltima.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOSTON (AP) _ Los Marineros lo canjearon. Los Mellizos lo dieron de baja. E incluso los aficionados de Boston perdieron la fe en David Ortiz en un par de ocasiones luego que el dominicano batall\u00f3 para iniciar la pretemporada o tuvo campa\u00f1as abreviadas por lesiones.<\/p>\n","protected":false},"author":12,"featured_media":48047,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-59538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=59538"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59538\/revisions"}],"predecessor-version":[{"id":59541,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/59538\/revisions\/59541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/48047"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=59538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=59538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=59538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}