{"id":60291,"date":"2016-10-19T14:32:32","date_gmt":"2016-10-19T18:32:32","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=60291"},"modified":"2016-10-19T14:32:32","modified_gmt":"2016-10-19T18:32:32","slug":"lluvias-inundan-117-viviendas-y-desplazan-a-85-familias-pobres","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lluvias-inundan-117-viviendas-y-desplazan-a-85-familias-pobres\/","title":{"rendered":"Lluvias inundan 117 viviendas y desplazan a 85 familias pobres"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/10\/image_content_7364613_20161019124015.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-60295\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/10\/image_content_7364613_20161019124015.jpg\" alt=\"image_content_7364613_20161019124015\" width=\"532\" height=\"284\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/10\/image_content_7364613_20161019124015.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/10\/image_content_7364613_20161019124015-300x160.jpg 300w\" sizes=\"auto, (max-width: 532px) 100vw, 532px\" \/><\/a>Unas 117 viviendas anegadas y 85 personas desplazadas de sus residencias en Puerto Plata, Santiago y Azua dejaron los aguaceros ayer, inform\u00f3 el Centro de Operaciones de Emergencias (COE).<!--more--><\/p>\n<p>El general Juan Manuel M\u00e9ndez Garc\u00eda explic\u00f3 que en Puerto Plata resultaron anegadas 50 viviendas; 50 en Tamboril y 17 en Palmar de Ocoa de Azua, de las cuales resultaron los desplazados a casas de amigos y familiares.<\/p>\n<p>Tambi\u00e9n el Centro de Operaciones de Emergencias (COE) tiene 19 provincias en alerta verde: La Vega, Monse\u00f1or Nouel, Duarte, Barahona, San Crist\u00f3bal, Santiago Rodr\u00edguez, Espaillat, Monte Plata, Santiago, Azua, Montecristi, Mar\u00eda Trinidad S\u00e1nchez y El\u00edas Pi\u00f1a y en amarilla Dajab\u00f3n, Puerto Plata y Montecristi.<\/p>\n<p>Los aguaceros con tormentas el\u00e9ctricas y r\u00e1fagas de viento seguir\u00e1n esta tarde en gran parte del pa\u00eds producidos por una vaguada localizada en la porci\u00f3n norte del pa\u00eds, inform\u00f3 la Oficina Nacional de Meteorolog\u00eda (Onamet).<\/p>\n<p>Santo Domingo permanecer\u00e1 medio nublado a nublado con aguaceros y tormentas y el\u00e9ctricas.<\/p>\n<p>El oleaje en la costa norte del pa\u00eds est\u00e1 de 7 a 8 pies de altura y por tanto las peque\u00f1as embarcaciones deben permanecer en puerto por oleaje anormal, seg\u00fan el pron\u00f3stico marino de la Onamet.<\/p>\n<p>En cuanto a la costa del mar Caribe todas las embarcaciones pueden realizar sus actividades con normalidad, pero sin aventurarse mar adentro.<\/p>\n<p>Meteorolog\u00eda comunic\u00f3 que contin\u00faa dando seguimiento a un sistema de baja presi\u00f3n localizado al noreste de Iislas Turcas y Caicos, en el oc\u00e9ano Atl\u00e1ntico, con un 60% de posibilidades de convertirse en cicl\u00f3n tropical en las pr\u00f3ximas 48 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unas 117 viviendas anegadas y 85 personas desplazadas de sus residencias en Puerto Plata, Santiago y Azua dejaron los aguaceros ayer, inform\u00f3 el Centro de Operaciones de Emergencias (COE).<\/p>\n","protected":false},"author":12,"featured_media":60295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-60291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/60291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=60291"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/60291\/revisions"}],"predecessor-version":[{"id":60296,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/60291\/revisions\/60296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/60295"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=60291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=60291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=60291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}