{"id":60477,"date":"2016-10-25T15:09:10","date_gmt":"2016-10-25T19:09:10","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=60477"},"modified":"2016-10-25T15:09:10","modified_gmt":"2016-10-25T19:09:10","slug":"arnold-schwarzenegger-protagonizara-pelicula-china","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/arnold-schwarzenegger-protagonizara-pelicula-china\/","title":{"rendered":"Arnold Schwarzenegger protagonizar\u00e1 pel\u00edcula china"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/10\/image_content_7390625_20161025135050.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60481\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/10\/image_content_7390625_20161025135050.jpg\" alt=\"image_content_7390625_20161025135050\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/10\/image_content_7390625_20161025135050.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/10\/image_content_7390625_20161025135050-300x160.jpg 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/><\/a>PEK\u00cdN. El actor estadounidense de origen austr\u00edaco Arnold Schwarzenegger ser\u00e1 el productor y protagonista de la futura pel\u00edcula china \u201cEl invitado de Sanxingdui\u201d, anunci\u00f3 hoy la agencia oficial Xinhua.<!--more--><\/p>\n<p>La pel\u00edcula, en 3D y con una inversi\u00f3n inicial de 200 millones de d\u00f3lares (183 millones de euros), comenzar\u00e1 a rodarse en marzo del pr\u00f3ximo a\u00f1o, se espera estrenar en 2019 y busca divulgar a grandes audiencias la historia de las ruinas de Sanxingdui, una cultura que hace milenios se desarroll\u00f3 en el centro de China.<\/p>\n<p>La civilizaci\u00f3n, que floreci\u00f3 en el \u00e1rea que ahora ocupa la provincia central de Sichuan, desapareci\u00f3 por razones a\u00fan no aclaradas, hace 3.000 a\u00f1os, y dej\u00f3 impresionantes restos arqueol\u00f3gicos, especialmente grandes figuras de bronce muy diferentes a las de otras culturas de la antig\u00fcedad china.<\/p>\n<p>Schwarzenegger ha viajado en varias ocasiones a China, tanto cuando era gobernador de California como promocionando pel\u00edculas o la pr\u00e1ctica del culturismo. Y el a\u00f1o pasado fue uno de los principales invitados al Festival Internacional de Cine de Pek\u00edn.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PEK\u00cdN. El actor estadounidense de origen austr\u00edaco Arnold Schwarzenegger ser\u00e1 el productor y protagonista de la futura pel\u00edcula china \u201cEl invitado de Sanxingdui\u201d, anunci\u00f3 hoy la agencia oficial Xinhua.<\/p>\n","protected":false},"author":12,"featured_media":60481,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-60477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/60477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=60477"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/60477\/revisions"}],"predecessor-version":[{"id":60482,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/60477\/revisions\/60482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/60481"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=60477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=60477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=60477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}