{"id":60772,"date":"2016-11-06T17:10:07","date_gmt":"2016-11-06T21:10:07","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=60772"},"modified":"2016-11-06T17:11:28","modified_gmt":"2016-11-06T21:11:28","slug":"curiosidades-del-monopolio-que-no-conocias","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/curiosidades-del-monopolio-que-no-conocias\/","title":{"rendered":"Curiosidades del Monopolio que no conoc\u00edas"},"content":{"rendered":"<p class=\"name post-title entry-title\">Como el nombre sugiere, el objetivo del juego es hacer un monopolio de oferta, poseyendo todas las propiedades inmuebles que aparecen en el juego. Los jugadores mueven sus respectivas fichas por turnos en sentido horario alrededor de un tablero, bas\u00e1ndose en la puntuaci\u00f3n de los dados, y caen en propiedades que pueden comprar de un banco imaginario<!--more-->, o dejar que el banco las subaste en caso de no ser compradas. Si las propiedades en las que caen ya tienen due\u00f1os, los due\u00f1os pueden cobrar alquileres o quien caiga podr\u00e1 compr\u00e1rselas.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"entry\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/juego-de-mesa-monopolio-juguete-ninos-ninas-monopoly-20280-mlv20187114565_102014-f.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-60775\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/juego-de-mesa-monopolio-juguete-ninos-ninas-monopoly-20280-mlv20187114565_102014-f.jpg\" alt=\"juego-de-mesa-monopolio-juguete-ninos-ninas-monopoly-20280-mlv20187114565_102014-f\" width=\"728\" height=\"485\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/juego-de-mesa-monopolio-juguete-ninos-ninas-monopoly-20280-mlv20187114565_102014-f.jpg 728w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/juego-de-mesa-monopolio-juguete-ninos-ninas-monopoly-20280-mlv20187114565_102014-f-300x200.jpg 300w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><\/p>\n<p>Tiene su origen en un juego de principios del siglo XX, The Landlord\u2019s Game creado por Elizabeth Maggie, del que se derivaron otros juegos de bienes ra\u00edces y el propio Monopoly. Desde los Estados Unidos, el juego se propag\u00f3 a otros pa\u00edses en diversas versiones, como el Matador dan\u00e9s.<\/p>\n<p>Jugadores en Inglaterra o Estados Unidos, por ejemplo, adaptaban esta clase de juegos a sus localidades, a\u00f1adiendo nombres de lugares cercanos a los tableros de juego.<\/p>\n<p><strong>Curiosidades sobre el Monopoly:<\/strong><\/p>\n<div><\/div>\n<p>\u2022 Se han vendido m\u00e1s de 275 millones de juegos en todo el mundo y est\u00e1 disponible en 111 pa\u00edses y en 43 idiomas.<br \/>\n\u2022 La partida de Monopoly m\u00e1s larga de la historia dur\u00f3 70 d\u00edas seguidos.<\/p>\n<p>\u2022 La versi\u00f3n m\u00e1s cara del juego fue producida por el c\u00e9lebre joyero de San Francisco Sidney Mobell. Valorado en 2 millones de d\u00f3lares, el juego presenta un tablero en oro de 23 quilates y un dado decorado con diamantes.<\/p>\n<p>\u2022 Se han creado muchas ediciones especiales del cl\u00e1sico juego con tus equipos de deportes favoritos, marcas, programas de televisi\u00f3n, dibujos y m\u00e1s.<\/p>\n<p>\u2022 El personaje que est\u00e1 en la c\u00e1rcel se llama Jake the Jailbird. El agente de polic\u00eda Edgar Mallory lo mand\u00f3 a la c\u00e1rcel.<\/p>\n<p>\u2022 Personas de todo el mundo juegan a MONOPOLY, pero el lugar donde viven puede determinar cu\u00e1l es la propiedad de alquiler m\u00e1s alto en el tablero. En Estados Unidos se llama \u201cBoardwalk\u201d, como una calle de Atlantic City. En Espa\u00f1a es el \u201cPaseo del Prado\u201d, de Madrid. Y en Francia, \u201cRue de la Paix\u201d es el nombre de la propiedad m\u00e1s codiciada.<\/p>\n<p>\u2022 En Alemania, se introdujeron mapas de huida, br\u00fajulas y limas de contrabando en los tableros de MONOPOLY, en los campos de prisioneros de guerra durante la II Guerra Mundial. Se meti\u00f3 dinero real para los fugitivos entre los montones de dinero MONOPOLY.<\/p>\n<p>\u2022 Cada pocos a\u00f1os, los campeones nacionales de todo el mundo se re\u00fanen para el Campeonato Mundial de Monopoly. Los Campeones Mundiales son de 10 pa\u00edses diferentes, incluyendo: Estados Unidos, Irlanda, Singapur, Italia, Nueva Zelanda, Reino Unido, Jap\u00f3n, Pa\u00edses Bajos, Hong Kong y Espa\u00f1a.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Como el nombre sugiere, el objetivo del juego es hacer un monopolio de oferta, poseyendo todas las propiedades inmuebles que aparecen en el juego. Los jugadores mueven sus respectivas fichas por turnos en sentido horario alrededor de un tablero, bas\u00e1ndose en la puntuaci\u00f3n de los dados, y caen en propiedades que pueden comprar de un banco imaginario<\/p>\n","protected":false},"author":12,"featured_media":60775,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-60772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/60772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=60772"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/60772\/revisions"}],"predecessor-version":[{"id":60777,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/60772\/revisions\/60777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/60775"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=60772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=60772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=60772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}