{"id":61014,"date":"2016-11-16T16:09:20","date_gmt":"2016-11-16T20:09:20","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61014"},"modified":"2016-11-16T16:09:20","modified_gmt":"2016-11-16T20:09:20","slug":"las-reinas-del-caribe-imparten-clinicas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/las-reinas-del-caribe-imparten-clinicas\/","title":{"rendered":"Las Reinas del Caribe imparten cl\u00ednicas"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/reinas-del-caribe.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-61017\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/reinas-del-caribe.jpg\" alt=\"reinas-del-caribe\" width=\"857\" height=\"253\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/reinas-del-caribe.jpg 857w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/reinas-del-caribe-300x89.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/reinas-del-caribe-768x227.jpg 768w\" sizes=\"auto, (max-width: 857px) 100vw, 857px\" \/><\/a>San Pedro de Macor\u00eds.- Las Reinas del Caribe trasladaron su acto fuera de las luces internacionales cuando se presentaron en este municipio a impartir sus conocimientos t\u00e9cnicos y narrar an\u00e9cdotas sobre su accionar por las diferentes canchas del mundo.<!--more--><\/p>\n<p>La Fundaci\u00f3n ImpActa Kids que preside Manny Acta, actual gerente general de las Aguilas Cibae\u00f1as, en la continuaci\u00f3n de la labor que lleva a cabo aqu\u00ed, este domingo cont\u00f3 con las estelares voleibolistas dominicanas que compartieron con un colectivo de escuelas y liceos del Distrito Educativo 05-06 de esta provincia oriental.<\/p>\n<p>\u201cPara nosotros es un motivo de orgullo tener este grupo de jugadoras compartiendo aqu\u00ed. Ellas han colocado el nombre de nuestro pa\u00eds en otro nivel y son figuras emblem\u00e1ticas, admiradas por todos\u201d, dijo Acta.<\/p>\n<p>Las cl\u00ednicas impartidas en el polideportivo local fueron lideradas por la estelar opuesta Gina Mambr\u00fa, las salidoras Bethania de la Cruz , Marifranchi Rodr\u00edguez y Marianne Fersola, las centrales Lisvel Eve Mej\u00eda y Annery Valdez, as\u00ed como la acomodadora Camil Dom\u00ednguez.<\/p>\n<p>La actividad fue coordinada por Anayma Acta, quien resalt\u00f3 a las Reinas del Caribe por extender sus conocimientos a j\u00f3venes jugadoras y ni\u00f1as que le admiran por su desempe\u00f1o en la cancha.<\/p>\n<p>Mambr\u00fa dijo que para ellas es un honor poder aportar y compartir con los j\u00f3venes de todos el pa\u00eds que en el futuro podr\u00eda formar parte del equipo nacional.<\/p>\n<p>\u201cNos sentimos muy halagadas cuando Anayma nos contact\u00f3 de parte de su hermano, Manny, una persona a la que admiramos porque reconocemos el esfuerzo que realiza por su comunidad\u201d, agreg\u00f3 la poderosa rematadora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Pedro de Macor\u00eds.- Las Reinas del Caribe trasladaron su acto fuera de las luces internacionales cuando se presentaron en este municipio a impartir sus conocimientos t\u00e9cnicos y narrar an\u00e9cdotas sobre su accionar por las diferentes canchas del mundo.<\/p>\n","protected":false},"author":12,"featured_media":61017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-61014","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61014"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61014\/revisions"}],"predecessor-version":[{"id":61018,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61014\/revisions\/61018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/61017"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}