{"id":61024,"date":"2016-11-16T19:27:55","date_gmt":"2016-11-16T23:27:55","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61024"},"modified":"2016-11-16T19:27:55","modified_gmt":"2016-11-16T23:27:55","slug":"suman-a-mas-de-90-mil-los-afectados-por-lluvias-en-puerto-plata","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/suman-a-mas-de-90-mil-los-afectados-por-lluvias-en-puerto-plata\/","title":{"rendered":"Suman a m\u00e1s de 90 mil los afectados por lluvias en Puerto Plata"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/15036572_1247932361962932_6969944071669282873_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-60935\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/15036572_1247932361962932_6969944071669282873_n.jpg\" alt=\"15036572_1247932361962932_6969944071669282873_n\" width=\"686\" height=\"457\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/15036572_1247932361962932_6969944071669282873_n.jpg 960w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/15036572_1247932361962932_6969944071669282873_n-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/15036572_1247932361962932_6969944071669282873_n-768x512.jpg 768w\" sizes=\"auto, (max-width: 686px) 100vw, 686px\" \/><\/a>PUERTO PLATA, Rep\u00fablica Dominicana.-<\/strong>\u00a0M\u00e1s de 90 mil afectados, 21 mil 315 desplazados, 93 viviendas destruidas y deslizamientos de tierra son solo parte de las huellas dejadas por los torrenciales aguaceros de las \u00faltimas semanas.<!--more--><\/p>\n<p>El director del COE en esa provincia, Whandar Garc\u00eda inform\u00f3 que los rios han bajado su cauce considerablemente, asimismo explic\u00f3 que la provincia ha regresado a la normalidad en un 50 por ciento.<\/p>\n<p>Seg\u00fan la ONAMET, para esta provincia se esperan precipitaciones moderadas en horas de la noche.<br \/>\n<iframe loading=\"lazy\" class=\"youtube-iframe-height\" src=\"https:\/\/www.youtube.com\/embed\/WepIFo3FX_A\" width=\"560\" height=\"315\" frameborder=\"0\" data-mce-fragment=\"1\"><\/iframe><\/p>\n<div class=\"noticia-content-banner-google\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA, Rep\u00fablica Dominicana.-\u00a0M\u00e1s de 90 mil afectados, 21 mil 315 desplazados, 93 viviendas destruidas y deslizamientos de tierra son solo parte de las huellas dejadas por los torrenciales aguaceros de las \u00faltimas semanas.<\/p>\n","protected":false},"author":12,"featured_media":60935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-61024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61024"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61024\/revisions"}],"predecessor-version":[{"id":61027,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61024\/revisions\/61027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/60935"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}