{"id":61084,"date":"2016-11-21T13:11:11","date_gmt":"2016-11-21T17:11:11","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61084"},"modified":"2016-11-21T13:11:11","modified_gmt":"2016-11-21T17:11:11","slug":"unicef-denuncia-bombardeos-contra-ninos-en-escuelas-y-hospitales-de-siria","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/unicef-denuncia-bombardeos-contra-ninos-en-escuelas-y-hospitales-de-siria\/","title":{"rendered":"UNICEF denuncia bombardeos contra ni\u00f1os en escuelas y hospitales de Siria"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-61085 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/1B0A0995-6C50-4821-A35F-9B1AC8EA73BA.jpg__778__440__CROPz3x778y440-300x170.jpg\" alt=\"1b0a0995-6c50-4821-a35f-9b1ac8ea73ba-jpg__778__440__cropz3x778y440\" width=\"300\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/1B0A0995-6C50-4821-A35F-9B1AC8EA73BA.jpg__778__440__CROPz3x778y440-300x170.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/1B0A0995-6C50-4821-A35F-9B1AC8EA73BA.jpg__778__440__CROPz3x778y440-768x434.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/1B0A0995-6C50-4821-A35F-9B1AC8EA73BA.jpg__778__440__CROPz3x778y440-595x340.jpg 595w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/1B0A0995-6C50-4821-A35F-9B1AC8EA73BA.jpg__778__440__CROPz3x778y440.jpg 778w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>El CAIRO.- 21 nov (EFE).- El Fondo de las Naciones Unidas para la Infancia (UNICEF) denunci\u00f3 hoy que los ni\u00f1os de Siria est\u00e1n expuestos a bombardeos en sus viviendas, escuelas y hospitales, lo que ha causado la muerte de al menos nueve de ellos esta \u00faltima semana.<!--more--><\/p>\n<p>\u00abHa sido una semana horrible para los ni\u00f1os sirios, que viven y mueren bajo los bombardeos ininterrumpidos de colegios, casas y hospitales\u00bb, destac\u00f3 Geert Cappelaere, director del UNICEF para la zona de Oriente Medio y el Norte de \u00c1frica.<\/p>\n<p>\u00abHemos visto im\u00e1genes de ni\u00f1os tratados por s\u00edntomas de asfixia en el este de Alepo. Poco despu\u00e9s, el hospital Al Bayan es bombardeado y madres aterrorizadas llevan a sus hijos al s\u00f3tano mientras ni\u00f1os enfermos son sacados de las incubadoras para ser llevados a un lugar seguro\u00bb, a\u00f1adi\u00f3 Cappelaere.<\/p>\n<p>Asimismo, se\u00f1al\u00f3 en un comunicado que ya no hay hospitales operativos en el este de Alepo, donde 100.000 ni\u00f1os est\u00e1n atrapados por el cerco de las fuerzas gubernamentales, lo cual restringe tambi\u00e9n su acceso a alimentos y medicinas.<\/p>\n<p>Estos ni\u00f1os \u00abnecesitan de los hospitales para permanecer con vida\u00bb, asegur\u00f3.<\/p>\n<p>Asimismo, el representante de la ONU destac\u00f3 que \u00ablos ni\u00f1os no deben morir en hospitales y en escuelas debido a las bombas\u00bb, haciendo referencia a los ataques contra dos escuelas del oeste de Alepo, una en las afueras de la capital, Damasco, y otro centro educativo en la provincia de Idleb (noroeste).<\/p>\n<p>Este a\u00f1o, la ONU ha documentado 84 ataques contra escuelas en Siria, en los que han muerto 69 ni\u00f1os.<\/p>\n<p>El director regional del UNICEF pidi\u00f3 a las partes en conflicto que no bombardeen escuelas, hospitales y otras infraestructuras civiles, pues ello \u00abcontraviene la ley internacional y puede representar cr\u00edmenes de guerra\u00bb. EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El CAIRO.- 21 nov (EFE).- El Fondo de las Naciones Unidas para la Infancia (UNICEF) denunci\u00f3 hoy que los ni\u00f1os de Siria est\u00e1n expuestos a bombardeos en sus viviendas, escuelas y hospitales, lo que ha causado la muerte de al menos nueve de ellos esta \u00faltima semana.<\/p>\n","protected":false},"author":9,"featured_media":61085,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-61084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61084"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61084\/revisions"}],"predecessor-version":[{"id":61086,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61084\/revisions\/61086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/61085"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}