{"id":6118,"date":"2014-07-16T12:21:12","date_gmt":"2014-07-16T16:21:12","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=6118"},"modified":"2014-12-02T17:06:50","modified_gmt":"2014-12-02T21:06:50","slug":"ahora-puedes-entrar-a-google-sin-decir-tu-nombre-real","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/ahora-puedes-entrar-a-google-sin-decir-tu-nombre-real\/","title":{"rendered":"Ahora puedes entrar a Google+ sin decir tu nombre real"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/214c61f83f21be2ee5d09a6a0b16ad773c30b6fb.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6120 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/214c61f83f21be2ee5d09a6a0b16ad773c30b6fb-300x200.jpg\" alt=\"214c61f83f21be2ee5d09a6a0b16ad773c30b6fb\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/214c61f83f21be2ee5d09a6a0b16ad773c30b6fb-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/214c61f83f21be2ee5d09a6a0b16ad773c30b6fb.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>En una nueva movida que busca ganar terreno contra su gigantesco competidor\u00a0<label style=\"color: #0000ff;\">Facebook<\/label>, Google+ dej\u00f3 de exigir a sus\u00a0<label style=\"color: #0000ff;\">usuarios<\/label>\u00a0que usen sus nombres verdaderos para ingresar en la red social en l\u00ednea.<!--more--><\/p>\n<p>\u00abCuando lanzamos Google+ hace m\u00e1s de tres a\u00f1os, pusimos muchas restricciones respecto al nombre que pod\u00edas poner en tu perfil\u00bb, indic\u00f3 el tit\u00e1n de\u00a0<label style=\"color: #0000ff;\">internet<\/label>, con sede en California, en un texto publicado en la propia red social.<\/p>\n<p>\u00abEsto ayud\u00f3 a crear una comunidad de gente real, pero tambi\u00e9n excluy\u00f3 a muchas personas que quer\u00edan ser parte de ella, sin usar su nombre de verdad\u00bb.<\/p>\n<p>\u00abNo hay m\u00e1s restricciones sobre el nombre que se puede usar\u00bb, a\u00f1adi\u00f3. AFP<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una nueva movida que busca ganar terreno contra su gigantesco competidor\u00a0Facebook, Google+ dej\u00f3 de exigir a sus\u00a0usuarios\u00a0que usen sus nombres verdaderos para ingresar en la red social en l\u00ednea.<\/p>\n","protected":false},"author":3,"featured_media":6120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-6118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=6118"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6118\/revisions"}],"predecessor-version":[{"id":6121,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6118\/revisions\/6121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/6120"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=6118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=6118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=6118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}