{"id":61191,"date":"2016-11-23T15:01:05","date_gmt":"2016-11-23T19:01:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61191"},"modified":"2016-11-23T15:01:05","modified_gmt":"2016-11-23T19:01:05","slug":"nina-original-de-gerber-cumple-90-anos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nina-original-de-gerber-cumple-90-anos\/","title":{"rendered":"Ni\u00f1a original de Gerber cumple 90 a\u00f1os"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-61192 size-full alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/image_content_7517829_20161123102539.jpg\" alt=\"image_content_7517829_20161123102539\" width=\"400\" height=\"584\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/image_content_7517829_20161123102539.jpg 400w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/image_content_7517829_20161123102539-205x300.jpg 205w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>La beba Gerber original ha cumplido 90 a\u00f1os. El fabricante de alimentos para beb\u00e9s dice que Ann Taylor Cook festej\u00f3 su cumplea\u00f1os el domingo.<!--more--><\/p>\n<p>Cook ten\u00eda cuatro meses en 1927 cuando un amigo de la familia dibuj\u00f3 su retrato con carbonilla. El dibujo fue presentado a Gerber el a\u00f1o siguiente, cuando la empresa invit\u00f3 a presentar retratos para su nueva publicidad de alimentos para beb\u00e9s. El retrato de Cook pas\u00f3 a ser marca registrada de la empresa en 1931.<\/p>\n<p>Cook tuvo cuatro hijos y ense\u00f1\u00f3 literatura en Tampa, Florida, durante 26 a\u00f1os hasta su retiro en 1989.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La beba Gerber original ha cumplido 90 a\u00f1os. El fabricante de alimentos para beb\u00e9s dice que Ann Taylor Cook festej\u00f3 su cumplea\u00f1os el domingo.<\/p>\n","protected":false},"author":9,"featured_media":61192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-61191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61191"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61191\/revisions"}],"predecessor-version":[{"id":61193,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61191\/revisions\/61193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/61192"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}