{"id":61202,"date":"2016-11-23T16:02:37","date_gmt":"2016-11-23T20:02:37","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61202"},"modified":"2016-11-23T16:02:37","modified_gmt":"2016-11-23T20:02:37","slug":"juez-no-firma-orden-de-libertad-de-omega","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/juez-no-firma-orden-de-libertad-de-omega\/","title":{"rendered":"Juez no firma orden de libertad de Omega"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-61205 size-full\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/image_content_7520346_20161123135928.jpg\" alt=\"image_content_7520346_20161123135928\" width=\"693\" height=\"370\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/image_content_7520346_20161123135928.jpg 693w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/image_content_7520346_20161123135928-300x160.jpg 300w\" sizes=\"auto, (max-width: 693px) 100vw, 693px\" \/>SANTO DOMINGO. El juez de Ejecuci\u00f3n de la Penal de la c\u00e1rcel de La Victoria, Richard Fidel Aquino Natera, se declar\u00f3 incompetente para firmar la orden de libertad de Omega, la cual estaba programada para hoy. <!--more--><\/p>\n<p>Aquino Natera tom\u00f3 la decisi\u00f3n debido a que la Fiscal\u00eda del Distrito Nacional recurri\u00f3 la sentencia no. 249-02-2016, del Primer Tribunal Colegiado, que dispon\u00eda la condena de 5 a\u00f1os de prisi\u00f3n con suspensi\u00f3n condicional de la pena que pesaba en contra del artista.<\/p>\n<p>El magistrado argumenta su incompetencia porque el caso se encuentra abierto.<\/p>\n<p>Omega fue sentenciado a cinco a\u00f1os de prisi\u00f3n, de los cuales cuatro a\u00f1os y cuatro meses est\u00e1n suspendidos.<\/p>\n<p>El pasado domingo, el cantante realiz\u00f3 una comilona para despedirse de sus compa\u00f1eros del penal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO. El juez de Ejecuci\u00f3n de la Penal de la c\u00e1rcel de La Victoria, Richard Fidel Aquino Natera, se declar\u00f3 incompetente para firmar la orden de libertad de Omega, la cual estaba programada para hoy.<\/p>\n","protected":false},"author":9,"featured_media":61205,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-61202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61202"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61202\/revisions"}],"predecessor-version":[{"id":61206,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61202\/revisions\/61206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/61205"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}