{"id":61413,"date":"2016-11-29T10:38:04","date_gmt":"2016-11-29T14:38:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61413"},"modified":"2016-11-29T10:38:04","modified_gmt":"2016-11-29T14:38:04","slug":"grupo-telemicro-suspende-tradicional-fiesta-de-navidad","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/grupo-telemicro-suspende-tradicional-fiesta-de-navidad\/","title":{"rendered":"Grupo Telemicro suspende tradicional fiesta de Navidad"},"content":{"rendered":"<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/medios-telemicro.jpg\"><br \/>\n<\/a> <a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/CyXCWYKWQAAkYsP.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-61416 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/CyXCWYKWQAAkYsP.jpg\" alt=\"cyxcwykwqaakysp\" width=\"320\" height=\"212\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/CyXCWYKWQAAkYsP.jpg 320w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/CyXCWYKWQAAkYsP-300x199.jpg 300w\" sizes=\"auto, (max-width: 320px) 100vw, 320px\" \/><\/a>El Grupo Telemicro anunci\u00f3 que debido a la estela de luto y dolor provocada por las lluvias en la zona Norte y en gran parte del pa\u00eds, se ha decidido suspender por este a\u00f1o la realizaci\u00f3n de la fiesta de empleados.<!--more--><br \/>\nLuego de un estudio de la situaci\u00f3n se informar\u00e1 a la poblaci\u00f3n de que manera se canalizar\u00e1 la ayuda directa a varias de las familias damnificadas con parte de los recursos que se gastar\u00edan en la celebraci\u00f3n navide\u00f1a, afirmaron los representantes de Telemicro.<\/div>\n<div><\/div>\n<div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-61415 alignright\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/medios-telemicro.jpg\" alt=\"medios-telemicro\" width=\"336\" height=\"252\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/medios-telemicro.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/11\/medios-telemicro-300x225.jpg 300w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/>\u00abNo es momento de fiestas. Es hora de solidaridad\u00bb, destacaron sus ejecutivos en una nota de prensa enviada a medios nacionales.<\/div>\n<div>\nLuego agregaron: \u00abPara este grupo empresarial es lamentable la cantidad de personas que han perdido la vida, as\u00ed como el n\u00famero de familias que hoy permanece sin hogar\u00bb.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El Grupo Telemicro anunci\u00f3 que debido a la estela de luto y dolor provocada por las lluvias en la zona Norte y en gran parte del pa\u00eds, se ha decidido suspender por este a\u00f1o la realizaci\u00f3n de la fiesta de empleados.<\/p>\n","protected":false},"author":12,"featured_media":61415,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-61413","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61413","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61413"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61413\/revisions"}],"predecessor-version":[{"id":61418,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61413\/revisions\/61418"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/61415"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61413"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61413"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61413"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}