{"id":61573,"date":"2016-12-04T12:40:34","date_gmt":"2016-12-04T16:40:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61573"},"modified":"2016-12-04T12:40:34","modified_gmt":"2016-12-04T16:40:34","slug":"detenido-pederasta-cuando-obligaba-a-dos-menores-a-practicarle-sexo-oral","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/detenido-pederasta-cuando-obligaba-a-dos-menores-a-practicarle-sexo-oral\/","title":{"rendered":"Detenido pederasta cuando obligaba a dos menores a practicarle sexo oral"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-61574 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/848F6D5E-3307-4856-920E-BB39B35014B1.jpg__778__440__CROPz3x778y440.jpg\" alt=\"848f6d5e-3307-4856-920e-bb39b35014b1-jpg__778__440__cropz3x778y440\" width=\"398\" height=\"225\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/848F6D5E-3307-4856-920E-BB39B35014B1.jpg__778__440__CROPz3x778y440.jpg 778w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/848F6D5E-3307-4856-920E-BB39B35014B1.jpg__778__440__CROPz3x778y440-300x170.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/848F6D5E-3307-4856-920E-BB39B35014B1.jpg__778__440__CROPz3x778y440-768x434.jpg 768w\" sizes=\"auto, (max-width: 398px) 100vw, 398px\" \/>SANTO DOMINGO.- La Polic\u00eda Nacional detuvo, en flagrante delito, a un hombre que abusaba sexualmente de dos ni\u00f1os en el sector Las Caobas de Santo Domingo Oeste, inform\u00f3 hoy la instituci\u00f3n en un comunicado.<!--more--><\/p>\n<p>Juan Antonio Heredia Jim\u00e9nez, de 53 a\u00f1os, fue sorprendido por miembros de la instituci\u00f3n del orden p\u00fablico, mientras obligaba a los infantes de 8 y 10 a\u00f1os, respectivamente, a que le practicaran sexo oral.<\/p>\n<p>El detenido se encuentra bajo control del Ministerio P\u00fablico para los fines legales correspondientes.<\/p>\n<p>La Polic\u00eda Nacional hace un llamado a la poblaci\u00f3n a denunciar por la v\u00eda que considere de rigor cualquier acto il\u00edcito que ocurra en su sector o comunidad para ser resuelto mediante una r\u00e1pida intervenci\u00f3n de las autoridades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- La Polic\u00eda Nacional detuvo, en flagrante delito, a un hombre que abusaba sexualmente de dos ni\u00f1os en el sector Las Caobas de Santo Domingo Oeste, inform\u00f3 hoy la instituci\u00f3n en un comunicado.<\/p>\n","protected":false},"author":9,"featured_media":61574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-61573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61573"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61573\/revisions"}],"predecessor-version":[{"id":61575,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61573\/revisions\/61575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/61574"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}