{"id":61637,"date":"2016-12-06T10:54:47","date_gmt":"2016-12-06T14:54:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61637"},"modified":"2016-12-06T10:57:45","modified_gmt":"2016-12-06T14:57:45","slug":"alimentos-que-debes-dejar-de-comer-para-adelgazar","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/alimentos-que-debes-dejar-de-comer-para-adelgazar\/","title":{"rendered":"Alimentos que debes dejar de comer para adelgazar"},"content":{"rendered":"<div class=\"field field-name-field-summary field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Para deshincharte r\u00e1pido solo debes dejar de comer ciertos alimentos. No perder\u00e1s mucha grasa, pero s\u00ed l\u00edquidos, lo que te har\u00e1 parecer mucho m\u00e1s delgado. Visiblemente, parecer\u00e1 que has bajado entre dos y tres kilos. Y la ropa aquella que te compraste te quedar\u00e1 como un guante.<!--more--><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-13245 tie-appear\" src=\"http:\/\/10curiosidades.com\/wp-content\/uploads\/2016\/12\/imagen-sin-titulo_80.jpg\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" srcset=\"http:\/\/10curiosidades.com\/wp-content\/uploads\/2016\/12\/imagen-sin-titulo_80.jpg 728w, http:\/\/10curiosidades.com\/wp-content\/uploads\/2016\/12\/imagen-sin-titulo_80-300x200.jpg 300w\" alt=\"imagen-sin-titulo_80\" width=\"728\" height=\"485\" \/><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Tienes un evento importante en un par de d\u00edas y est\u00e1s hinchado. El modelito que te compraste de pronto no te cabe ni con vaselina. No sabes qu\u00e9 hacer. Te sobran unos 3 kilos que no sabes muy bien de d\u00f3nde han salido. Piensas en ponerte a correr como loco por el parque que est\u00e1 al lado de tu casa, o en dejar de comer hasta el d\u00eda del evento. Pero, amigo, no es una opci\u00f3n sensata, ni mucho menos.<\/p>\n<p>Para deshincharte r\u00e1pido solo debes dejar de comer ciertos alimentos. No perder\u00e1s mucha grasa, pero s\u00ed l\u00edquidos, lo que te har\u00e1 parecer mucho m\u00e1s delgado. Visiblemente, parecer\u00e1 que has bajado entre dos y tres kilos. Y la ropa aquella que te compraste te quedar\u00e1 como un guante.<\/p>\n<p>\u201cLa hinchaz\u00f3n temporal se puede aliviar en pocos d\u00edas con la hidrataci\u00f3n adecuada y eligiendo bien los alimentos\u201d, asegura la nutricionista Jennifer Christman a \u2018Prevention\u2019. Olv\u00eddate de t\u00e9s de desintoxicaci\u00f3n, pastillas, zumos de lim\u00f3n o trucos extra\u00f1os innecesarios. Si dejas de comer por unos d\u00edas estos siete alimentos, bajar\u00e1s peso en tiempo express sin poner en riesgo tu salud.<\/p>\n<p><strong>1) Verduras crudas<\/strong><\/p>\n<p>Aunque algunos alimentos frescos son esenciales dentro de una dieta saludable, hay algunos que te hinchan como un globo. Es el caso de las verduras crudas. Si te sientes hinchado y quieres verte m\u00e1s slim, deber\u00edas cocinar los vegetales antes de comerlos. El aporte nutricional ser\u00e1 el mismo, pero la versi\u00f3n cocinada ocupar\u00e1 menos espacio en tu tracto gastrointestinal, el conjunto de \u00f3rganos responsable de la digesti\u00f3n de los alimentos. Y, por tanto, no te inflar\u00e1s.<\/p>\n<p>As\u00ed pues, debes dejar ya de comer y cenar ensalada. Es muy sana, pero no es la opci\u00f3n que m\u00e1s te conviene ahora mismo. Aunque parezca mentira, la lechuga es un alimento bastante indigesto. Tiene un alto contenido en fibra insoluble y puede hacer que tengamos gases e hinchaz\u00f3n abdominal por la noche. Mucha gente toma ensaladas por la noche, y no hay raz\u00f3n para no hacerlo, pero es preferible apostar por ensaladas de tomate o camperas. Tambi\u00e9n son recomendables las ensaladas mixtas, con algo de prote\u00edna, que ayudar\u00e1n a saciarnos y no tener la tentaci\u00f3n de picar por la noche.<\/p>\n<p><strong>2) Comida picante<\/strong><\/p>\n<p>Aunque el picante es un gran saciente y puede ser un poderoso quemagrasas, a corto plazo no hace bien a tu figura. \u201cLos aliments picantes pueden liberar el \u00e1cido del est\u00f3mago, lo que causar\u00e1 irritaci\u00f3n, gases e hinchaz\u00f3n\u201d, asegura Alpert. La lista de preparados prohibidos para tu r\u00e9gimen express son la pimienta negra, la nuez moscada, el chile en polvo, la cebolla, el ajo, la mostaza, la salsa barbacoa, el r\u00e1bano picante, el ketchup, la salsa de tomate y el vinagre. En su lugar, es mejor que optes por condimentar tu comida con lim\u00f3n fresco o zumo de lima.<\/p>\n<div><\/div>\n<p>La comida picante, no obstante, es un gran aliado a la hora de adelgazar a largo plazo. Seg\u00fan una reciente investigaci\u00f3n realizada en la Escuela de Farmacia de la Universidad de Wyoming, Estados Unidos, los alimentos que contienen chile picante pueden ayudarnos a quemar grasas sin tener que restringir las calor\u00edas de nuestra dieta. Otro estudio realizado en 2013 en la Universidad de Maastricht (Pa\u00edses Bajos) demostr\u00f3 que el chile, la cayena o los pimientos rojos picantes contienen capsaicina, el componente activo que disminuye los l\u00edpidos corporales mediante un mecanismo que motiva la muerte de las c\u00e9lulas grasas inmaduras, por lo que podr\u00eda ayudar a adelgazar a largo plazo.<\/p>\n<p><strong>3) Sal<\/strong><\/p>\n<p>La sal retiene l\u00edquidos, lo que te hace estar m\u00e1s hinchado que de costumbre. Para adelgazar en tiempo r\u00e9cord, debes limitar tu ingesta de sodio a una cucharadita o menos al d\u00eda. Eso deber\u00eda ayudarte a bajar tu peso en agua r\u00e1p\u00ecdamente.<\/p>\n<p>Debes recordar que el sodio es el responsable de la retenci\u00f3n de agua y de la hinchaz\u00f3n el cuerpo, ya que hidrata a las c\u00e9lulas. Una dieta saludable debe contener solo 2.300 mg (una cucharadita) de sodio por d\u00eda. Asimismo, es recomendable que evites alimentos muy salados, como salazones, embutidos, salsas, aderezos, palomitas y algunos quesos (especialmente el roquefort).<\/p>\n<p>No tienes que reducir en exceso el consumo de sal, ya que es un elemento qu\u00edmico necesario para el mecanismo del cuerpo humano, utilizado para producir energ\u00eda y regular la hidrataci\u00f3n, y es un ingrediente que no puede faltar en la preparaci\u00f3n de los alimentos de cualquier cocina.<\/p>\n<p><strong>4) Carbohidratos refinados<\/strong><\/p>\n<p>A menos que tengas un trabajo ligado a la actividad f\u00edsica, deber\u00edas reducir al m\u00e1ximo el consumo de alimentos ricos en carbohidratos refinados. Lo ideal, si quieres deshincharte, es que consumas una o dos porciones diarias. Podr\u00eda ser una rebanada de pan y media taza de arroz, por ejemplo. Por supuesto, nada de bagels, cereales, patatas fritas o pasta.<\/p>\n<p>\u201cTus m\u00fasculos guardan un tipo de carbohidrato llamado gluc\u00f3geno, que es el encargado de acopiar energ\u00eda\u201d, asegura Alpert. Y cada gramo de este gluc\u00f3geno se almacena con aproximadamente 3 gramos de agua, haciendo que te hinches. Si limitas la ingesta de carbohidratos, tu cuerpo tendr\u00e1 acceso al combustible retenido en su m\u00fasculo, podr\u00e1 quemarlo y as\u00ed drenar el exceso de l\u00edquidos almacenados. Y, por tanto, estar\u00e1s visiblemente mucho m\u00e1s delgado.<\/p>\n<p>Esta teor\u00eda es la que defiende el cient\u00edfico y periodista Gary Taubes, autor de \u2018Good Calories, Bad Calories\u2019. En este libro, asegura que la clave para perder peso reside en \u201cdisminuir nuestros niveles de insulina\u201d, y que la mejor forma de hacerlo es eliminar de nuestra dieta todas las comidas que aumenten nuestra insulina, y que, por tanto, hace que almacenemos grasa. Son el az\u00facar y los carbohidratos provenientes de la harina y el almid\u00f3n.<\/p>\n<p><strong>5) Alimentos que producen gas<\/strong><\/p>\n<p>Alimentos como br\u00f3coli, jud\u00edas negras, coles de Bruselas, repollo, coliflor, lechuga, cebollas y leche contienen enzimas que naturalmente producen gas. Cuando las bacterias del intestino digieren estos alimentos, crean gas como subproducto, el cual se queda atrapado en el tracto gastrointestinal y puede acumularse en los intestinos y causar hinchaz\u00f3n. Por tanto, es importante cambiar estos alimentos por otros que no nos inflen, como los esp\u00e1rragos o la col rizada.<\/p>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para deshincharte r\u00e1pido solo debes dejar de comer ciertos alimentos. No perder\u00e1s mucha grasa, pero s\u00ed l\u00edquidos, lo que te har\u00e1 parecer mucho m\u00e1s delgado. Visiblemente, parecer\u00e1 que has bajado entre dos y tres kilos. Y la ropa aquella que te compraste te quedar\u00e1 como un guante.<\/p>\n","protected":false},"author":12,"featured_media":61641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-61637","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61637"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61637\/revisions"}],"predecessor-version":[{"id":61643,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61637\/revisions\/61643"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/61641"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}