{"id":61638,"date":"2016-12-06T11:04:21","date_gmt":"2016-12-06T15:04:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61638"},"modified":"2016-12-06T11:04:21","modified_gmt":"2016-12-06T15:04:21","slug":"la-increible-historia-del-hombre-que-paso-de-dormir-en-banos-publicos-a-ser-un-inversionista-multimillonario","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-increible-historia-del-hombre-que-paso-de-dormir-en-banos-publicos-a-ser-un-inversionista-multimillonario\/","title":{"rendered":"La incre\u00edble historia del hombre que pas\u00f3 de dormir en ba\u00f1os p\u00fablicos a ser un inversionista multimillonario"},"content":{"rendered":"<p class=\"story-body__introduction\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/de-pobre-a-millonario.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-61645\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/de-pobre-a-millonario.jpg\" alt=\"de-pobre-a-millonario\" width=\"432\" height=\"243\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/de-pobre-a-millonario.jpg 660w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/de-pobre-a-millonario-300x169.jpg 300w\" sizes=\"auto, (max-width: 432px) 100vw, 432px\" \/><\/a>En los d\u00edas cuando Chris Gardner y su peque\u00f1o hijo dorm\u00edan en un piso de un ba\u00f1o p\u00fablico, jam\u00e1s se pudo imaginar que la historia de su vida se convertir\u00eda en una taquillera pel\u00edcula de Hollywood.<!--more--><\/p>\n<p>Fue a comienzos de los a\u00f1os 80, cuando Gardner, en ese entonces de 27 a\u00f1os, y su ni\u00f1o <strong>vivieron en la calle durante un a\u00f1o<\/strong> en San Francisco, California.<\/p>\n<p>Empleado con sueldo m\u00ednimo en un programa de capacitaci\u00f3n en una empresa de corredores de bolsa, <strong>no ten\u00eda suficiente dinero para pagar el dep\u00f3sito de arriendo<\/strong> de un apartamento.<\/p>\n<p>As\u00ed que Gardner, que estaba separado de su pareja, y su hijo Chris Jr dorm\u00edan donde pudieran.<\/p>\n<p>Adem\u00e1s del ba\u00f1o en una estaci\u00f3n de tren, <strong>encontraban donde dormir en parques, refugios en iglesias o debajo de los escritorios de la oficina<\/strong>, despu\u00e9s de que todos se hubieran ido a casa.<\/p>\n<p>Se alimentaban en comedores de beneficencia y el poco dinero que ten\u00eda lo usaba para pagar una guarder\u00eda que cuidaba a su hijo mientras \u00e9l iba al trabajo.<\/p>\n<p>A pesar de las adversidades, Gardner prosper\u00f3 en su trabajo.<strong> Ten\u00eda un instinto natural para vender activos<\/strong> y, al final del per\u00edodo de capacitaci\u00f3n su firma, Dean Witter Reynolds (DWR), le dio un empleo de tiempo completo.<\/p>\n<p>Ya con medios para su arrendar una casa para \u00e9l y su hijo, <strong>su carrera ascendi\u00f3 r\u00e1pidamente hacia alturas inimaginables<\/strong> y, en 1987, abri\u00f3 su propia compa\u00f1\u00eda de inversiones, Gardner Rich.<\/p>\n<h2 class=\"story-body__crosshead\">Hollywood golpea a la puerta<\/h2>\n<p>Hoy en d\u00eda, Gardner tiene 62 a\u00f1os,<strong> una fortuna estimada en US$60 millones<\/strong>, viaja por el mundo dando charlas motivacionales y patrocina una serie de organizaciones de beneficencia para los sin techo y contra la violencia hacia las mujeres.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive-image__img js-image-replace\" src=\"http:\/\/ichef-1.bbci.co.uk\/news\/624\/cpsprodpb\/EF27\/production\/_92732216_happyness.jpg\" alt=\"La portada del primer libro de Chris Gardner\" width=\"976\" height=\"549\" data-highest-encountered-width=\"624\" \/><\/span><\/figure>\n<p>El hecho que Gardner tuvo una muy dif\u00edcil ni\u00f1ez y que <strong>estuvo en la c\u00e1rcel poco antes de su pasant\u00eda en DWR<\/strong> puede explicar por qu\u00e9 Hollywood se interes\u00f3 en la autobiograf\u00eda que escrib\u00eda y que se convirti\u00f3 en un \u00e9xito de ventas <i>The Pursuit of Happyness<\/i> (\u00abLa b\u00fasqueda de la felicidad\u00bb).<\/p>\n<p><strong>La pel\u00edcula del mismo nombre se lanz\u00f3 en 2006, con Will Smith<\/strong>, que recibi\u00f3 una nominaci\u00f3n al Oscar de Mejor Actor por su interpretaci\u00f3n de Gardner.<\/p>\n<p>En retrospectiva, Gardner dijo a la BBC que \u00abno cambiar\u00eda nada\u00bb de su vida.<\/p>\n<p>\u00abTuve que pasar dolores de ni\u00f1o para que mis hijos no tuvieran que sufrirlos\u00bb, expres\u00f3. \u00abA los cinco a\u00f1os tom\u00e9 la decisi\u00f3n que mis hijos conocer\u00edan a su padre\u00bb.<\/p>\n<p>\u00abEl resto de mi destino me lleg\u00f3 porque tom\u00e9 las decisiones correctas\u00bb.<\/p>\n<h2 class=\"story-body__crosshead\">Madre inspiradora<\/h2>\n<p>Gardner naci\u00f3 en Milwaukee, en estado de Wisconsin, pero nunca conoci\u00f3 a su padre.<\/p>\n<p>Fue<strong> criado en medio de la pobreza por su madre Bettye Jean y un padrastro alcoh\u00f3lico que lo maltrat\u00f3 f\u00edsicamente.<\/strong><\/p>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive-image__img js-image-replace\" src=\"http:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/2C9F\/production\/_92732411_gettyimages-72948824.jpg\" alt=\"Will Smith y Chris Gardner\" width=\"976\" height=\"549\" data-highest-encountered-width=\"624\" \/><span class=\"off-screen\">Image copyright<\/span><span class=\"story-image-copyright\">GETTY IMAGES<\/span><\/span><figcaption class=\"media-caption\"><span class=\"off-screen\">Image caption<\/span><span class=\"media-caption__text\">Chris Gardner con Will Smith, quien lo interpret\u00f3 en la pantalla gigante.<\/span><\/figcaption><\/figure>\n<p>Tambi\u00e9n pas\u00f3 un per\u00edodo de tiempo en un hogar adoptivo despu\u00e9s de que su madre, en un ataque de desesperaci\u00f3n, intent\u00f3 matar a su compa\u00f1ero.<\/p>\n<p>A pesar de las dificultades en su ni\u00f1ez, Gardner asegur\u00f3 que <strong>su madre fue una inspiraci\u00f3n<\/strong>.<\/p>\n<p>\u00abTengo una de esas madres enchapadas a la antigua que me dec\u00eda todos los d\u00edas, &#8216;Hijo, puedes ser o hacer cualquier cosa que quieras'\u00bb, coment\u00f3.<\/p>\n<p>\u00abY le cre\u00ed y qued\u00e9 convencido 100%\u00bb.<\/p>\n<p>A\u00f1adi\u00f3 que un d\u00eda, de ni\u00f1o, estaba viendo un partido de baloncesto universitario en TV y coment\u00f3 que <strong>uno de esos jugadores llegar\u00eda a ganar un mill\u00f3n de d\u00f3lares<\/strong>.<\/p>\n<p>\u00abMi madre declar\u00f3: &#8216;Hijo, un d\u00eda t\u00fa ser\u00e1s el que haga un mill\u00f3n de d\u00f3lares&#8217;. Hasta que ella dijo esas palabras, la idea nunca hab\u00eda cruzado mi mente\u00bb.<\/p>\n<h2 class=\"story-body__crosshead\">Encuentro casual<\/h2>\n<p>El mill\u00f3n de d\u00f3lares no lleg\u00f3 inmediatamente y, despu\u00e9s de graduarse de la escuela secundaria, se enrol\u00f3 cuatro a\u00f1os en la Marina de EE.UU.<\/p>\n<p>Despu\u00e9s de recibir una baja honrosa en 1974, Gardner se traslad\u00f3 a San Francisco, donde empez\u00f3 a vender equipos m\u00e9dicos.<\/p>\n<p>Su vida cambi\u00f3 por completo cuando un d\u00eda <strong>vio a un hombre estacionando su Ferrari rojo<\/strong> y Gardner le pregunt\u00f3 a qu\u00e9 se dedicaba.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive-image__img js-image-replace\" src=\"http:\/\/ichef.bbci.co.uk\/news\/624\/cpsprodpb\/C8DF\/production\/_92732415_gettyimages-180103631.jpg\" alt=\"San Francisco\" width=\"976\" height=\"549\" data-highest-encountered-width=\"624\" \/><\/span><\/figure>\n<p>El hombre era un corredor de bolsa llamado Bob Bridges y, despu\u00e9s de conversar un poco con \u00e9l, Gardner expres\u00f3 un inter\u00e9s en incursionar en ese \u00e1mbito.<\/p>\n<p>Se reunieron otra vez y Bridges le ayud\u00f3 a Gardner lograr una entrevista para una pasant\u00eda.<\/p>\n<p>Sin embargo, en los d\u00edas antes de la entrevista en DWR, Gardner <strong>fue arrestado y encarcelado por no pagar sus multas de estacionamiento<\/strong>.<\/p>\n<p>Eventualmente pudo llegar a la entrevista pero s\u00f3lo vestido en la ropa que ten\u00eda puesta cuando lo arrestaron, que inclu\u00eda un par de zapatos tenis y un chaleco.<\/p>\n<p>A pesar de su facha desali\u00f1ada, <strong>su empuje y entusiasmo fueron suficientes para ganarle el puesto<\/strong>.<\/p>\n<h2 class=\"story-body__crosshead\">Reevaluaci\u00f3n de la vida<\/h2>\n<p>Seis a\u00f1os despu\u00e9s del estreno de la pel\u00edcula, la vida de Gardner cambi\u00f3 otra vez en 2012, cuando <strong>su esposa muri\u00f3 de c\u00e1ncer a los 55 a\u00f1os<\/strong>.<\/p>\n<p>Eso provoc\u00f3 un reevaluaci\u00f3n de lo que quer\u00eda hacer con su vida y, despu\u00e9s de tres muy exitosas d\u00e9cadas en finanzas,<strong> decidi\u00f3 efectuar un completo cambio<\/strong>.<\/p>\n<p>\u00abEn unas de las \u00faltimas conversaciones que tuvimos ella me dijo: &#8216;Ahora que podemos ver lo verdaderamente corta que puede ser la vida, \u00bfqu\u00e9 piensas hacer el resto de tu vida?'\u00bb.<\/p>\n<figure class=\"media-landscape has-caption full-width\"><span class=\"image-and-copyright-container\"><img loading=\"lazy\" decoding=\"async\" class=\"responsive-image__img js-image-replace\" src=\"http:\/\/ichef-1.bbci.co.uk\/news\/624\/cpsprodpb\/13D47\/production\/_92732218_chris_gardner351_original.jpg\" alt=\"Chris Gardner\" width=\"976\" height=\"549\" data-highest-encountered-width=\"624\" \/><\/span><\/figure>\n<p>\u00abCuando tienes una conversaci\u00f3n as\u00ed, eso cambia todo. Yo he dicho que cuando no est\u00e1s haciendo algo que te apasiona, est\u00e1s comprometiendo tu ser todos los d\u00edas\u00bb.<\/p>\n<p>Al darse cuenta de que no quer\u00eda seguir trabajando en la banca de inversi\u00f3n, se reinvent\u00f3 como un <strong>orador motivacional y autor<\/strong>.<\/p>\n<h2 class=\"story-body__crosshead\">\u00abIncre\u00edble testamento\u00bb<\/h2>\n<p>Ahora pasa<strong> 200 d\u00edas del a\u00f1o viajando por el mundo dando charlas a auditorios llenos en m\u00e1s de 50 pa\u00edses<\/strong>.<\/p>\n<p>Scott Burns, director de la firma de inversi\u00f3n estadounidense <i>Morningstar<\/i>, dice que Gardner es \u00absencillamente un incre\u00edble testamento de fortaleza\u00bb.<\/p>\n<p>Y a\u00f1adi\u00f3: \u00abUno puede caer y quedar tendido pero solo tan bajo como uno mismo lo permita\u00bb.<\/p>\n<p>Gardner cree que \u00e9l es prueba contundente contra<strong> la teor\u00eda de que todos somos producto de nuestro entorno<\/strong>.<\/p>\n<p>\u00abDe acuerdo con esa escuela de pensamiento, yo deb\u00ed haberme convertido en otro pobre diablo alcoh\u00f3lico que golpea a su esposa y maltrata a su hijos\u00bb.<\/p>\n<p>En cambio, dice que<strong> tom\u00f3 sus propias decisiones positivas gracias al amor de su madre y el apoyo de otras personas<\/strong>.<\/p>\n<p>\u00abEscog\u00ed la luz, de parte de mi madre y de otros con los que no comparto una sola gota de sangre, y la acog\u00ed con brazos abiertos\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En los d\u00edas cuando Chris Gardner y su peque\u00f1o hijo dorm\u00edan en un piso de un ba\u00f1o p\u00fablico, jam\u00e1s se pudo imaginar que la historia de su vida se convertir\u00eda en una taquillera pel\u00edcula de Hollywood.<\/p>\n","protected":false},"author":12,"featured_media":61645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-61638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61638"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61638\/revisions"}],"predecessor-version":[{"id":61647,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61638\/revisions\/61647"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/61645"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}