{"id":61651,"date":"2016-12-06T20:03:46","date_gmt":"2016-12-07T00:03:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=61651"},"modified":"2016-12-06T20:03:46","modified_gmt":"2016-12-07T00:03:46","slug":"guzman-marcelino-supervisa-aplicacion-programas-salud-en-provincias-del-norte","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/guzman-marcelino-supervisa-aplicacion-programas-salud-en-provincias-del-norte\/","title":{"rendered":"Guzm\u00e1n Marcelino supervisa aplicaci\u00f3n programas salud en provincias del Norte"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-61652 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/A85DD63D-7776-4698-9974-EA3B3928BF9F.jpg__778__440__CROPz3x778y440.jpg\" alt=\"a85dd63d-7776-4698-9974-ea3b3928bf9f-jpg__778__440__cropz3x778y440\" width=\"280\" height=\"158\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/A85DD63D-7776-4698-9974-EA3B3928BF9F.jpg__778__440__CROPz3x778y440.jpg 778w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/A85DD63D-7776-4698-9974-EA3B3928BF9F.jpg__778__440__CROPz3x778y440-300x170.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2016\/12\/A85DD63D-7776-4698-9974-EA3B3928BF9F.jpg__778__440__CROPz3x778y440-768x434.jpg 768w\" sizes=\"auto, (max-width: 280px) 100vw, 280px\" \/>SANTO DOMINGO.- La ministra de Salud, Altagracia Guzm\u00e1n Marcelino, visit\u00f3 este martes las zonas m\u00e1s afectadas por las inundaciones registradas en las provincias San Francisco de Macor\u00eds y Mar\u00eda Trinidad S\u00e1nchez, para supervisar la aplicaci\u00f3n de los programas de salud.<!--more--><\/p>\n<p>En la ciudad de Nagua, durante una reuni\u00f3n de acompa\u00f1amiento con el Nivel Desconcentrado de Rector\u00eda Local, antigua Direcci\u00f3n Provincial de Salud (DPS), recibi\u00f3 de su director, Luis Alemany, los informes de indicadores y la aplicaci\u00f3n de los programas de Salud Colectiva que vienen aplicando.<\/p>\n<p>Entre otros aspectos tratados con el director provincial y con los t\u00e9cnicos, Guzm\u00e1n Marcelino hizo \u00e9nfasis en la intensificaci\u00f3n de la vigilancia epidemiol\u00f3gica para detectar a tiempo los episodios diarreicos y febriles.<\/p>\n<p>Asimismo, prestar atenci\u00f3n a los pacientes cr\u00f3nicos, y verificar que sigan regularmente sus tratamientos, al igual que las embarazadas y los ancianos.<\/p>\n<p>La ministra tambi\u00e9n inst\u00f3 a mantener la orientaci\u00f3n a la poblaci\u00f3n para que consuma agua bien tratada y clorada, as\u00ed como lavarse constantemente las manos para prevenir c\u00f3lera, y otras enfermedades diarreica agudas, enfermedades respiratorias agudas y leptospirosis.<\/p>\n<p>Tambi\u00e9n hizo \u00e9nfasis enla permanente eliminaci\u00f3n de criaderos de mosquitos a los fines de controlar la poblaci\u00f3n del que transmite los virus del zika, el dengue y la chikungunya.<\/p>\n<p>Posteriormente a la supervisi\u00f3n del Plan de Prevenci\u00f3n de brotes de enfermedades y preparaci\u00f3n de respuesta ante amenazas, la ministra se desplaz\u00f3 hacia la Comunidad Las Garzas, en Rinc\u00f3n de Molenillo y al Guayabo de la provincia Duarte, zonas especialmente golpeadas por las inundaciones sufridas en la Regi\u00f3n Nordeste.<\/p>\n<p>All\u00ed, Guzm\u00e1n Marcelino convers\u00f3 con l\u00edderes comunitarios y con la poblaci\u00f3n para escuchar sus inquietudes relativas a la situaci\u00f3n de salud y sus expectativas al respecto, y aprovech\u00f3 para pedir su colaboraci\u00f3n con la autoridad sanitaria local para enfrentar las amenazas que puedan presentarse. EFE<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SANTO DOMINGO.- La ministra de Salud, Altagracia Guzm\u00e1n Marcelino, visit\u00f3 este martes las zonas m\u00e1s afectadas por las inundaciones registradas en las provincias San Francisco de Macor\u00eds y Mar\u00eda Trinidad S\u00e1nchez, para supervisar la aplicaci\u00f3n de los programas de salud.<\/p>\n","protected":false},"author":9,"featured_media":61652,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-61651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=61651"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61651\/revisions"}],"predecessor-version":[{"id":61653,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/61651\/revisions\/61653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/61652"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=61651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=61651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=61651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}