{"id":6208,"date":"2014-07-18T10:24:03","date_gmt":"2014-07-18T14:24:03","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=6208"},"modified":"2014-07-18T10:24:03","modified_gmt":"2014-07-18T14:24:03","slug":"insomnio-por-que-no-puedo-dormir-y-que-hacer-para-lograrlo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/insomnio-por-que-no-puedo-dormir-y-que-hacer-para-lograrlo\/","title":{"rendered":"Insomnio: por qu\u00e9 no puedo dormir y qu\u00e9 hacer para lograrlo"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/799f25501345825209872c8236977984.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6209 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/799f25501345825209872c8236977984-300x200.jpg\" alt=\"799f25501345825209872c8236977984\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/799f25501345825209872c8236977984-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/799f25501345825209872c8236977984.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>El dormir es algo tan\u00a0<label style=\"color: #0000ff;\">natural<\/label>\u00a0que no solemos pensar c\u00f3mo lo logramos y cuando surge el problema se buscan soluciones inmediatas in situ sin tener herramientas. Frustraci\u00f3n que se convierte en angustia, un cansancio del que no sabemos salir, una percepci\u00f3n del tiempo ag\u00f3nica, la magnificaci\u00f3n de todos nuestros problemas del\u00a0<label style=\"color: #0000ff;\">d\u00eda<\/label>\u00a0y la anticipaci\u00f3n de que al sonar el despertador\u00a0<label style=\"color: #0000ff;\">todo<\/label>\u00a0esto ser\u00e1 a\u00fan peor. (Tal vez est\u00e9 leyendo este art\u00edculo en una de esas noches en vela en que se ha puesto a navegar por la red desesperado\u2026).<!--more--><\/p>\n<p>El insomnio, sea como demanda principal o asociado a otro problema psicol\u00f3gico, es frecuente en terapia y requiere de una evaluaci\u00f3n extensa y de un entrenamiento en t\u00e9cnicas que lo eliminen. Sin embargo, dado el desconocimiento general, se pretende en este art\u00edculo arrojar algo de luz a esas oscuras noches permitiendo que el lector discrimine sobre las causas y tipolog\u00eda de su insomnio y tenga un primer manual acerca de c\u00f3mo tratarlo cuando se est\u00e1 produciendo.<\/p>\n<p>Causas del insomnio y pautas para dormir<\/p>\n<p>Lo primero es tratar de identificar las causas: Las pautas ser\u00e1n distintas para cada caso<\/p>\n<p><strong>De repente, una noche en vela<\/strong><br \/>\nEstar sin dormir una noche de manera aislada no se considera siquiera insomnio. El ruido, el calor, el jetlag o el haber estado demasiado activo durante el d\u00eda pueden hacer que sea imposible conciliar el sue\u00f1o cuando lo deseamos.<\/p>\n<p>En este caso es conveniente asumir la p\u00e9rdida de horas de sue\u00f1o con\u00a0<label style=\"color: #0000ff;\">total<\/label>\u00a0naturalidad, tratar de estar relajados o incluso levantarse y aprovechar estas horas extra de vigilia para realizar otras actividades, sean gratificantes o productivas. Es cierto que durante el d\u00eda estaremos m\u00e1s cansados pero al ser una causa puntual la que imped\u00eda el sue\u00f1o, pronto volveremos a equilibrar nuestro ritmo de sue\u00f1o.<\/p>\n<p><strong>Duermo de d\u00eda y me desvelo de noche<\/strong><br \/>\nLa causa m\u00e1s frecuente de no poder dormir por la noche suele ser por\u00a0<label style=\"color: #0000ff;\">cambios<\/label>\u00a0en los horarios del sue\u00f1o: trasnochar, levantarse tarde, echarse siestas&#8230; son actividades que impiden conciliar el sue\u00f1o por la noche y al estar cansados durante el d\u00eda, se duerme fuera de hora o se usan estimulantes que volver\u00e1n a evitar que se duerma por la noche cuando nos lo proponemos. Muchas personas que dicen padecer insomnio no se est\u00e1n dando cuenta de que esas decisiones son las que les desvelan.<\/p>\n<p>Tambi\u00e9n es com\u00fan en adolescentes ir modificando los horarios de sue\u00f1o, aprovechando que de noche pueden tener menos control parental y justificar el dormir de d\u00eda a que tienen \u201cinsomnio\u201d.<\/p>\n<p>Una buena manera de identificar que se est\u00e1n siguiendo h\u00e1bitos incorrectos es registrar la hora en que se va a la cama, la hora aproximada en que uno se durmi\u00f3 y la hora en que uno se levanta, incluyendo siestas. Tambi\u00e9n anotar si se ha bebido cafe\u00edna o te\u00edna durante el d\u00eda y en qu\u00e9 cantidades. Los resultados de los registros pueden sorprendernos y hacernos entender que no existe un problema m\u00e1s all\u00e1 de cambiar esa rutina. Hay que se\u00f1alar que dormir de d\u00eda o hacerlo en periodos distintos produce un sue\u00f1o de menor calidad y probablemente de menos horas que si se sigue el reloj biol\u00f3gico durmiendo en ausencia de luz solar.<\/p>\n<p><strong>Preocupaciones que no dejan dormir<\/strong><br \/>\nParece que nuestra cabeza est\u00e1 esperando a que nos tumbemos en la cama para dar vueltas a ese tema que tanto malestar nos causa durante toda la noche. Esto es as\u00ed porque cuando existe una baja estimulaci\u00f3n e inactividad se facilita el rumiar pensamientos y hemos cogido la costumbre de repasar el d\u00eda o planificar el siguiente antes de irnos a dormir. Gran error, sobre todo si hay temas que nos preocupan: una alta actividad cognitiva es incompatible con conciliar el sue\u00f1o y adem\u00e1s suele ser in\u00fatil tratar de solucionar problemas de madrugada.<\/p>\n<p>Por ello hay que dejar las preocupaciones fuera de la cama. Aprender a cerrar temas o planificar el d\u00eda en horarios y sitios distintos. Es importante ser constantes y no caer en la tentaci\u00f3n de dar cancha a esos problemas cuando queremos dormir para dejar de usar la cama como nuestra mesa de reuniones. Puede ayudar a \u201csacar\u201d los pensamientos de la cabeza el anotarlos durante el d\u00eda en una agenda (o cualquier otro soporte f\u00edsico frente al registro mental) junto a la soluci\u00f3n que le vamos a dar e ir tachando cuando se van cerrando.<\/p>\n<p><strong>Estoy nervioso y no s\u00e9 por qu\u00e9<\/strong><br \/>\nA veces no es un tema concreto lo que nos desvela. Nos sentimos nerviosos y activados y por la noche no logramos dormir. Probablemente durante el d\u00eda estemos igual. No estamos tan cansados las primeras noches, pero s\u00ed mostramos s\u00edntomas ansi\u00f3genos que se incrementar\u00e1n si el problema persiste. La ansiedad, en efecto, es una gran enemiga del sue\u00f1o y abordarla ser\u00e1 la soluci\u00f3n para que desaparezca el problema. Mientras, por la noche, es importante evitar pensamientos que nos est\u00e1n activando, aunque no los identifiquemos, siguiendo las pautas del punto anterior. Tambi\u00e9n puede ayudar, de manera puntual, distraernos con otra actividad, como la lectura o la televisi\u00f3n, pero hay que tener cuidado de no acabar acostumbr\u00e1ndonos a condicionar el sue\u00f1o con esas actividades o instauraremos rutinas de nuevo inadecuadas. La famosa t\u00e9cnica de \u201ccontar ovejitas\u201d tiene como funci\u00f3n impedir pensar a la vez en aquello que nos activa.<\/p>\n<p>Adem\u00e1s, es \u00fatil aplicar t\u00e9cnicas de relajaci\u00f3n, perfectamente ejecutables en la cama y que disminuyen las se\u00f1ales fisiol\u00f3gicas que nos mantienen activados.<\/p>\n<p><strong>No duermo porque no duermo<\/strong><br \/>\nA la anteriores causas de no conciliar el sue\u00f1o se suma la propia angustia de no poder dormir: contamos las horas que nos quedan de sue\u00f1o, anticipamos lo desastroso que ser\u00e1 el no poder estar descansados al d\u00eda siguiente y damos vueltas pregunt\u00e1ndonos por qu\u00e9 nos est\u00e1 pasando esto. La preocupaci\u00f3n de no dormir nos mantiene activos a modo de una profec\u00eda autocumplida y puede durar todo el d\u00eda generando una angustia totalmente incompatible con relajarnos. La soluci\u00f3n es tan simple como sorprendente: Hay que dejar de preocuparse de no poder dormir cuando se est\u00e1 intent\u00e1ndolo. El dormir es una necesidad b\u00e1sica y, conscientes de las desventajas que tiene no hacerlo, se vive como una imposici\u00f3n vital cuando en realidad tenemos mucho m\u00e1s margen. No pasa nada por estar en vela alguna noche o tener rachas en que se duermen menos horas; nuestro rendimiento no siempre se ve inmediatamente afectado ni condiciona de manera tan dr\u00e1stica el d\u00eda posterior. Hay muchos otros factores que afectan a nuestras capacidades y a nuestro cansancio aparte del dormir. Si se tiene un problema de insomnio, hay que buscar una soluci\u00f3n razonada durante el d\u00eda, poco a poco, mejorando h\u00e1bitos o acudiendo a profesionales y no martirizarnos por no conseguir un fundido en negro autom\u00e1tico.<\/p>\n<p>Probablemente esta afirmaci\u00f3n de restar importancia al dormir le sorprenda, pero seamos racionales: \u00bfayuda a conseguir que nos durmamos el preocuparnos por no hacerlo? \u00bfO por el contrario hemos experimentado que cuando menos relevante era, antes nos hemos podido relajar?<\/p>\n<p><strong>Pautas generales para el insomnio<\/strong><\/p>\n<p>Siga las directrices comunes de higiene del sue\u00f1o: seguir una rutina antes de irse a dormir, no tomar estimulantes y sobre todo levantarse siempre a la misma hora, se haya dormido m\u00e1s o menos, y no cambiar nuestra rutina por ello o acabaremos haciendo que nuestra vida gire en torno al problema.<\/p>\n<p>Lev\u00e1ntese de la cama si no logra dormir: el sue\u00f1o se condiciona a la cama y, por tanto, no debemos usar \u00e9sta para otras actividades durante el d\u00eda. As\u00ed mismo, es muy importante que si no logramos conciliar el sue\u00f1o nos levantemos y nos vayamos a otra parte hasta que vuelva a entrarnos el cansancio. Dar vueltas en la cama har\u00e1 que lo que se condicione al dormitorio sea la activaci\u00f3n.<\/p>\n<p>La medicaci\u00f3n no es una soluci\u00f3n al problema. puede ayudar e incluso ser necesaria, pautada por un m\u00e9dico en determinadas situaciones, pero debemos encontrar otras soluciones m\u00e1s definitivas a trav\u00e9s de la modificaci\u00f3n de conducta o haremos cr\u00f3nico el problema.<\/p>\n<p>Y recuerde, dormir es tan importante como placentero pero vivir el insomnio con angustia e impaciencia no va a hacer que duerma. Aproveche su noche en vela y busque una soluci\u00f3n durante el d\u00eda. Probablemente en cuanto le pierda el miedo a lo de estar despierto\u2026 se quedar\u00e1 dormido.<\/p>\n<p>Fuente:\u00a0<a style=\"color: #006e94;\" href=\"http:\/\/www.elconfidencial.com\/alma-corazon-vida\/2014-07-17\/la-solucion-al-insomnio-por-que-no-puedo-dormir-y-que-hacer-para-lograrlo_162501\/?utm_source=dlvr.it&amp;utm_medium=facebook\" target=\"_blank\">El Confidencial<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El dormir es algo tan\u00a0natural\u00a0que no solemos pensar c\u00f3mo lo logramos y cuando surge el problema se buscan soluciones inmediatas in situ sin tener herramientas. Frustraci\u00f3n que se convierte en angustia, un cansancio del que no sabemos salir, una percepci\u00f3n del tiempo ag\u00f3nica, la magnificaci\u00f3n de todos nuestros problemas del\u00a0d\u00eda\u00a0y la anticipaci\u00f3n de que al sonar el despertador\u00a0todo\u00a0esto ser\u00e1 a\u00fan peor. (Tal vez est\u00e9 leyendo este art\u00edculo en una de esas noches en vela en que se ha puesto a navegar por la red desesperado\u2026).<\/p>\n","protected":false},"author":3,"featured_media":6209,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-6208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=6208"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6208\/revisions"}],"predecessor-version":[{"id":6210,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6208\/revisions\/6210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/6209"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=6208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=6208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=6208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}