{"id":6226,"date":"2014-07-19T08:09:54","date_gmt":"2014-07-19T12:09:54","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=6226"},"modified":"2014-07-19T09:26:30","modified_gmt":"2014-07-19T13:26:30","slug":"trece-aviones-mas-de-1-800-pasajeros-asesinados","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/trece-aviones-mas-de-1-800-pasajeros-asesinados\/","title":{"rendered":"Trece aviones, m\u00e1s de 1.800 pasajeros asesinados"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/ataques-aviones-644x362.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-6229 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/ataques-aviones-644x362.jpg\" alt=\"ataques-aviones--644x362\" width=\"557\" height=\"313\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/ataques-aviones-644x362.jpg 644w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/ataques-aviones-644x362-300x168.jpg 300w\" sizes=\"auto, (max-width: 557px) 100vw, 557px\" \/><\/a>El Boeing de Malaysia Airlines es el \u00faltimo vuelo comercial que ha sido derribado en los \u00faltimos 40 a\u00f1os.<!--more--><\/p>\n<p>El 28 de noviembre de 2002, dos miembros de\u00a0Al Qaida\u00a0lanzaron dos misiles port\u00e1tiles contra un avi\u00f3n comercial israel\u00ed que volaba tranquilamente con 240 pasajeros a bordo, desde el aeropuerto de Mombasa (Kenia). En aquella ocasi\u00f3n los terroristas fallaron el blanco, una suerte que no tuvieron este jueves los 298 ocupantes del Boeing 777 de la compa\u00f1\u00eda\u00a0Malaysia Airlines, que fue derribado por un misil lanzado desde tierra, en la regi\u00f3n de Donetsk, cuando volaba a 10.000 metros de altitud [sigue en directo la novedades sobre la\u00a0cat\u00e1strofer a\u00e9rea de Donestk].<\/p>\n<div class=\"photo-alt5\" style=\"color: #1e1e00;\">\n<div class=\"photo-prod clearfix\">\n<div class=\"bloquei\">\n<div class=\"nombre\" style=\"color: #45443f;\">Con \u00e9ste, son 13 los aviones comerciales que han sido derribados en pleno vuelo desde que, en 1976, un grupo anticastrista hiciera explotar, sobre el Caribe, dos artefactos en un avi\u00f3nDouglas DC-8 de Cubana de Aviaci\u00f3n. Murieron 73 ocupantes, la mayor\u00eda deportistas cubanos. Fueron las primeras v\u00edctimas de los 1.803 pasajeros que han sido asesinados desde entonces, entre los que hay pasajeros de todas las nacionalidades posibles, desde coreanos a franceses, pasando por estadounidenses, ucranianos, canadienses, colombianos, ruandeses o paname\u00f1os, incluidos varios presidentes del Gobierno.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>El atentado contra el Douglas DC-8 fue el peor ataque de este tipo que se hab\u00eda producido hasta entonces en el hemisferio occidental. El juicio se celebr\u00f3 en Venezuela y la sentencia se demor\u00f3 nada menos que nueve a\u00f1os, hasta que en 1987 fueron condenados a 20 a\u00f1os de prisi\u00f3n dos venezolanos. Otro de los detenidos, el exiliado cubano\u00a0Luis Posada Carriles\u00a0logr\u00f3 huir tras ocho a\u00f1os detenido a la espera de una sentencia. Despu\u00e9s consigui\u00f3 entrar en Estados Unidos, donde estuvo detenido por haber ingresado ilegalmente en el pa\u00eds, pero fue liberado en 2007.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Boeing de Malaysia Airlines es el \u00faltimo vuelo comercial que ha sido derribado en los \u00faltimos 40 a\u00f1os.<\/p>\n","protected":false},"author":3,"featured_media":6229,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-6226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=6226"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6226\/revisions"}],"predecessor-version":[{"id":6230,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6226\/revisions\/6230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/6229"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=6226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=6226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=6226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}