{"id":6304,"date":"2014-07-19T13:57:39","date_gmt":"2014-07-19T17:57:39","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=6304"},"modified":"2014-07-19T13:57:39","modified_gmt":"2014-07-19T17:57:39","slug":"califican-caso-de-la-mulata-iii-de-sosua-como-una-tremenda-verguenza-para-las-autoridades-dominicanas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/califican-caso-de-la-mulata-iii-de-sosua-como-una-tremenda-verguenza-para-las-autoridades-dominicanas\/","title":{"rendered":"Califican caso de La Mulata III de Sos\u00faa como una tremenda verg\u00fcenza para las autoridades dominicanas"},"content":{"rendered":"<p><span style=\"color: #000000;\"><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/0_la_mulata_3_210_120.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6305 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/0_la_mulata_3_210_120.jpg\" alt=\"0_la_mulata_3_210_120\" width=\"210\" height=\"120\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/0_la_mulata_3_210_120.jpg 210w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/0_la_mulata_3_210_120-595x340.jpg 595w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a>PUERTO PLATA.- A juico de la mayor\u00eda de ciudadanos de este pa\u00eds, el desenlace que ha tenido en los tribunales el caso del residencial La Mulata III ocurrido el 12 de octubre del 2012, ha sido calificado como una verg\u00fcenza para las autoridades dominicanas.<\/span><!--more--><\/p>\n<p style=\"color: #000000;\">\n<p style=\"color: #000000;\">\nEsta apreciaci\u00f3n ciudadana surge cuando ya han transcurrido casi dos a\u00f1os de los allanamientos irregulares llevados a cabo por un grupo de agentes de la Polic\u00eda Nacional quienes protagonizaron un supuesto enfrentamiento a tiros con extranjeros residentes en ese residencial en cuya refriega muri\u00f3 acribillado un ciudadano alem\u00e1n, mientras que otros resultaron heridos entre los que se destaca a un empleado de nacionalidad haitiana.<\/p>\n<p>Se afirma que dicho hecho que a casi dos a\u00f1os de su ocurrencia, las autoridades no han podido precisar la cadena de custodia que fue utilizada en el famoso allanamiento donde seg\u00fan las denuncias del abogado alem\u00e1n Peter Brunck los agentes policiales perpetraron un saqueo a esas residencias hasta el punto de que cuantiosos fueron sacados de esas villas y a\u00fan se encuentran desaparecidos.<\/p>\n<p>Los ciudadanos consultados opinaron que \u201clo m\u00e1s indignante es que a pesar de las acciones ilegales de polic\u00edas y fiscales que actuaron en el allanamiento que caus\u00f3 un esc\u00e1ndalo a nivel internacional, no existe una sola condena por las diabluras cometidas ya que se ha tratado como si el hecho nunca hubiera ocurrido\u201d.<\/p>\n<p>En lo referente a este caso, la verg\u00fcenza judicial se extiende a tarjetas de cr\u00e9dito confiscadas y utilizadas despu\u00e9s del allanamiento al igual que varios veh\u00edculos, por lo que algunos extranjeros de los residentes en el residencial la Mulata III en el municipio tur\u00edstico de Sos\u00faa ya han tenido que abandonar el pa\u00eds agobiados por la falta de recursos econ\u00f3micos, mientras que otros est\u00e1n contemplando la posibilidad de seguirles los pasos, de no ver ning\u00fan resultado positivo en el caso.<\/p>\n<p>Asimismo se asegura que ninguna autoridad da la cara por el fracaso en los tribunales de las acusaciones de homicidio, pillaje y violaciones a los derechos humanos que presuntamente fueron cometidos por oficiales y agentes de la Polic\u00eda Nacional en contra de los extranjeros, adem\u00e1s seg\u00fan el inventario de los ciudadanos alemanes por la sustracci\u00f3n de millones de pesos en prendas, art\u00edculos y dinero en efectivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PUERTO PLATA.- A juico de la mayor\u00eda de ciudadanos de este pa\u00eds, el desenlace que ha tenido en los tribunales el caso del residencial La Mulata III ocurrido el 12 de octubre del 2012, ha sido calificado como una verg\u00fcenza para las autoridades dominicanas.<\/p>\n","protected":false},"author":3,"featured_media":6305,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-6304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=6304"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6304\/revisions"}],"predecessor-version":[{"id":6306,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6304\/revisions\/6306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/6305"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=6304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=6304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=6304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}