{"id":63105,"date":"2017-01-11T10:30:16","date_gmt":"2017-01-11T14:30:16","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=63105"},"modified":"2017-01-11T10:30:16","modified_gmt":"2017-01-11T14:30:16","slug":"dos-de-cada-tres-estadounidenses-quieren-que-trump-cierre-su-cuenta-de-twitter","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/dos-de-cada-tres-estadounidenses-quieren-que-trump-cierre-su-cuenta-de-twitter\/","title":{"rendered":"Dos de cada tres estadounidenses quieren que Trump cierre su cuenta de Twitter"},"content":{"rendered":"<p><strong><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/TRUMP4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-63106  alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/TRUMP4.jpg\" width=\"339\" height=\"226\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/TRUMP4.jpg 1200w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/TRUMP4-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/TRUMP4-768x512.jpg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/TRUMP4-1024x683.jpg 1024w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/a>WASHINGTON.-<\/strong>\u00a0El 64 % de estadounidenses quiere que su presidente electo, Donald Trump, cierre su pol\u00e9mica cuenta de Twitter, mientras que un 51 % desaprueba su gesti\u00f3n desde que gan\u00f3 las elecciones hace dos meses, seg\u00fan una encuesta publicada hoy.<!--more--><\/p>\n<p>El porcentaje de estadounidenses que desea que Trump cierre la cuenta de Twitter sube hasta el 71 % cuando los encuestados tienen entre 18 y 34 a\u00f1os, de acuerdo con el estudio realizado por la Universidad de Quinnipiac (Connecticut).<\/p>\n<p>Tan solo el 32 % de los encuestados -26 % entre los m\u00e1s j\u00f3venes- tiene una imagen positiva de la afici\u00f3n de su presidente electo a esa red social.<\/p>\n<p>Los tuits de Trump han influido, quiz\u00e1s, en que el 51 % de los encuestados desapruebe su gesti\u00f3n como presidente electo, mientras que tan solo un 37 % la aprueba.<\/p>\n<p>Cifras que contrastan con las del todav\u00eda presidente del pa\u00eds, Barack Obama, quien dejar\u00e1 el Despacho Oval el pr\u00f3ximo d\u00eda 20 con una aprobaci\u00f3n del 55 % y una imagen negativa del 39 %, sus mejores datos desde 2009, el primer a\u00f1o de su era.<\/p>\n<p>El estudio tambi\u00e9n revela que el 45 % de los estadounidenses cree que Trump ser\u00e1 peor presidente que Obama, mientras que el 34 % prev\u00e9 que ser\u00e1 mejor y el 15 % opina que ser\u00e1n lo mismo.<\/p>\n<p>Sin embargo, el 52 % se muestra optimista sobre el futuro de la econom\u00eda en el pa\u00eds y el 47 % considera que Trump ayudar\u00e1 a su crecimiento, mientras que tan solo el 31 % cree que lo perjudicar\u00e1.<\/p>\n<p>La encuesta fue realizada entre el 2 y el 5 de enero a 899 votantes registrados de todo el pa\u00eds y tiene un margen de error del 3,3 %.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>WASHINGTON.-\u00a0El 64 % de estadounidenses quiere que su presidente electo, Donald Trump, cierre su pol\u00e9mica cuenta de Twitter, mientras que un 51 % desaprueba su gesti\u00f3n desde que gan\u00f3 las elecciones hace dos meses, seg\u00fan una encuesta publicada hoy.<\/p>\n","protected":false},"author":12,"featured_media":63106,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-63105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=63105"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63105\/revisions"}],"predecessor-version":[{"id":63107,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63105\/revisions\/63107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/63106"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=63105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=63105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=63105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}