{"id":6311,"date":"2014-07-20T07:27:21","date_gmt":"2014-07-20T11:27:21","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=6311"},"modified":"2014-07-20T07:27:21","modified_gmt":"2014-07-20T11:27:21","slug":"surfistas-de-la-terrena-y-cabarete-arrasan-en-la-clasificacion-del-barahona-international-surf-championship","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/surfistas-de-la-terrena-y-cabarete-arrasan-en-la-clasificacion-del-barahona-international-surf-championship\/","title":{"rendered":"Surfistas de La Terrena y Cabarete arrasan en la clasificaci\u00f3n del Barahona International Surf Championship"},"content":{"rendered":"<p style=\"color: #000000;\"><strong><em><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/surfing-en-barahona-desde-cabarete.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6312 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/surfing-en-barahona-desde-cabarete.jpg\" alt=\"surfing en barahona desde cabarete\" width=\"348\" height=\"232\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/surfing-en-barahona-desde-cabarete.jpg 348w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/surfing-en-barahona-desde-cabarete-300x200.jpg 300w\" sizes=\"auto, (max-width: 348px) 100vw, 348px\" \/><\/a>PLAYA BAHORUCO.<\/em><\/strong>&#8211; Los competidores de Las Terrena y Cabarete se alzaron con las principales calificaciones en la jornada del s\u00e1bado 19 de julio, en las diferentes categor\u00edas que compiten en el Barahona International Surf Championship que se realiza en la playa de Bahoruco de Barahona.<!--more--><\/p>\n<p>En la categor\u00eda Open Femenino calificaron Carolina Gutierres de Cabarete, Vanessa Ram\u00edrez de Santo Domingo y Alice Gibien, Caroline de Cat y Joan Mariel de Las Terrenas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"http:\/\/www.diariolibre.com\/showimage.php?typeid=19&amp;imageid=586681\" alt=\"\" width=\"361\" height=\"217\" \/>Mientras que en el rengl\u00f3n Hombres Open clasificaron a la final Leon Gough, Zeon Balbuena, Brandon Sandford, Pedro Fern\u00e1ndez y Angel Compres de Cabarete y Sa\u00fal Medina de Bahoruco.<\/p>\n<p>En las categor\u00edas m\u00e1s j\u00f3venes, la Junior, con competidores de 14 a 18 a\u00f1os pasan a la final Leandro Castillo, Luis Miguel Almeyda, Max Self de Cabarete, Edwin Feliz y Angel Acosta de Bahoruco, Alex Encarnaci\u00f3n de Las Terrenas.<\/p>\n<p>Los m\u00e1s peque\u00f1os de la competencia, la categor\u00eda Mini Junior, con atletas hasta los 14 a\u00f1os, avanzan a la final Alex Feliz, Juan Feliz y Angel Feliz, Edwin Ruiz y David Feliz de Bahoruco, David Cuevas de Barahona, Benjamin Knudsen de las Terrenas.<\/p>\n<p>En la categor\u00eda Master avanzaron a la final Luis Dur\u00e1n, Mario Vi\u00f1as, Jos\u00e9 Luis Aquino y Marcos S. Hilaire de Santo Domingo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/www.diariolibre.com\/showimage.php?typeid=19&amp;imageid=586691\" alt=\"\" width=\"334\" height=\"201\" \/>Ma\u00f1ana domingo se realizar\u00e1 la ronda final para seleccionar los ganadores en Mini-Junior, Damas Open, Master, Open, Master y Kahuna iniciada este viernes<\/p>\n<p>Vanessa Ram\u00edrez, del Circuito Nacional de Surf y miembro del comit\u00e9 organizador, dijo que todos los participantes demostraron un gran dominio en las olas de playa Bahoruco, la cual posee excelentes oleaje todo el a\u00f1o debido a su ubicaci\u00f3n geogr\u00e1fica de Bahoruco y los vientos que soplan en direcci\u00f3n Este.<\/p>\n<p>Esta competencia cuenta con la participaci\u00f3n de m\u00e1s de 60 surfistas dominicanos, procedentes de B\u00e1varo, Macao, Punta Cana, Las Terrenas, Nagua, R\u00edo San Juan, Cabarete, Puerto Plata, Boca Chica, Santo Domingo, Nizao, Ban\u00ed y los anfitriones de Barahona y Bahoruco quienes aprovecharan aprovechar\u00e1n el excelente oleaje que ofrece la playa de Bahoruco.\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignright\" src=\"http:\/\/www.diariolibre.com\/showimage.php?typeid=19&amp;imageid=586701\" alt=\"\" width=\"358\" height=\"215\" \/><\/p>\n<p>Esta competencia forma parte de un plan de trabajo del Cl\u00faster Tur\u00edstico y Productivo de Barahona con el cual se trabaja para posicionar esta provincia como un destino de naturaleza y para la pr\u00e1ctica de deportes no tradicionales como el surfing, regata de vela, senderismo, triatl\u00f3n.<\/p>\n<p>Esta actividad deportiva, que se realiza en la Bahoruco cuenta con el apoyo de: Ministerio de Turismo, Ministerio de Deportes WT Events , Juegos Rica, Revista en Sociedad, Revista Abordo, Gatorade , Carib Wind Cabarete, Caripack, Consorcio Azucarero Central, Mobil, Bol\u00edgrafos Dominicanos, Agua Everest, EGE Haina, Isabella Bay Village, Central Romana Corporation, Peri\u00f3dico Hoy, Nexos y Turenlace.<\/p>\n<p><strong><br \/>\nSobre Barahona<\/strong><\/p>\n<p>En Barahona, los visitantes encuentran facilidades de alojamiento, comida y otros servicios, que les har\u00e1n disfrutar su estad\u00eda de manera placentera.<\/p>\n<p>Barahona tiene atractivos ecotur\u00edsticos \u00fanicos y excursiones tem\u00e1ticas de gran valor como son: la Ruta del az\u00facar que se puede realizar en colaboraci\u00f3n con la Fundaci\u00f3n del Consorcio Azucarero Central, la Ruta del Caf\u00e9, el Centro de visitantes el Cachote en la Loma de Bahoruco Central, la Mina de Larimar, Polo y los parques nacionales y \u00e1reas protegidas que pueden ser visitados durante todo el a\u00f1o reservando con los hoteles o tour operadores locales.<\/p>\n<p style=\"color: #000000;\">\n","protected":false},"excerpt":{"rendered":"<p>PLAYA BAHORUCO.&#8211; Los competidores de Las Terrena y Cabarete se alzaron con las principales calificaciones en la jornada del s\u00e1bado 19 de julio, en las diferentes categor\u00edas que compiten en el Barahona International Surf Championship que se realiza en la playa de Bahoruco de Barahona.<\/p>\n","protected":false},"author":3,"featured_media":6312,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,3],"tags":[],"class_list":["post-6311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=6311"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6311\/revisions"}],"predecessor-version":[{"id":6313,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6311\/revisions\/6313"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/6312"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=6311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=6311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=6311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}