{"id":63181,"date":"2017-01-13T08:10:02","date_gmt":"2017-01-13T12:10:02","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=63181"},"modified":"2017-01-13T08:10:54","modified_gmt":"2017-01-13T12:10:54","slug":"olviden-los-vinilos-el-cassette-tambien-se-esta-poniendo-de-moda","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/olviden-los-vinilos-el-cassette-tambien-se-esta-poniendo-de-moda\/","title":{"rendered":"Olviden los vinilos, el cassette tambi\u00e9n se est\u00e1 poniendo de moda"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/casette.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-63187\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/casette.jpg\" alt=\"\" width=\"499\" height=\"289\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/casette.jpg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/casette-300x174.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/01\/casette-768x444.jpg 768w\" sizes=\"auto, (max-width: 499px) 100vw, 499px\" \/><\/a>Durante los \u00faltimos a\u00f1os hemos visto el regreso de los discos de vinilo como un formato en el que los m\u00fasicos modernos ofrecen sus \u00e1lbumes. Ahora es el turno de los cassettes. Cada vez m\u00e1s personas en el mundo est\u00e1n volviendo a disfrutar de este formato retro; es la nueva moda musical.<!--more--><\/p>\n<aside class=\"referenced-wide referenced-fullwidth js_inset tmpl_referencedGroupFullWidth clearfix core-decorated-inset\">\n<div class=\"container\"><\/div>\n<\/aside>\n<p>La discusi\u00f3n acerca de si los vinilos suenan mejor o no que el formato digital ha mantenido ocupados a los mel\u00f3manos durante mucho tiempo. Sin embargo, todo el mundo sabe que los cassettes suenan mal, o al menos peor que un CD o un disco de vinilo.<\/p>\n<p>Sin embargo, la nueva moda del cassette podr\u00eda haber surgido gracias a la nostalgia y al hecho de que es m\u00e1s barato para los artistas independientes compartir su m\u00fasica en este formato antes que en cualquier otro.<\/p>\n<p>Un reporte de la industria musical por parte de la firma <a href=\"http:\/\/www.buzzanglemusic.com\/buzzangle-music-2016-report\/\" target=\"_blank\" rel=\"noopener\">BuzzAngle <\/a>asegura que en 2016 se vendieron un 140% m\u00e1s cassettes que el a\u00f1o pasado en los Estados Unidos. Los artistas que publican sus \u00e1lbumes en plataformas <em>online<\/em> como Bandcamp tambi\u00e9n los ofrecen en CDs y cassettes por un precio muy bajo, lo que ha disparado sus ventas. Finalmente, el fabricante de cassettes National Audio Company asegura que su producci\u00f3n ha incrementado un 20%.<\/p>\n<p>Hoy en d\u00eda existen sellos discogr\u00e1ficos independientes que ofrecen a los m\u00fasicos la posibilidad de vender sus creaciones en cassettes para bajar los costos y aumentar sus ganancias. Lo que comenz\u00f3 como una curiosidad retro o hipster se est\u00e1 convirtiendo en un producto que realmente interesa al mercado audi\u00f3filo, ya sea por nostalgia o por el simple hecho de ofrecer una experiencia musical diferente.<\/p>\n<div class=\"ad-container js_ad-video row ad-wide ad-top js_ad-video-desktop\"><\/div>\n<div class=\"ad-promotions-container js_ad-promotion row ad-wide ad-top js_ad-promotion-mobile\" data-mobile=\"true\"><\/div>\n<div class=\"taboola-mobile-second hide-contents ad-mobile\">\n<div class=\"ad-mobile-inner\">\n<p class=\"ad-label proxima\"><small class=\" proxima\">Sponsored<\/small><\/p>\n<div id=\"taboola-mobile-article-carousel\" class=\"taboola-mobile-article-carousel\"><\/div>\n<\/div>\n<\/div>\n<p>Los cassettes tienen una peor calidad de audio que cualquier otro formato actual. Sin embargo, para el fan\u00e1tico se convierte en una pieza de colecci\u00f3n y algo muy diferente a buscar una canci\u00f3n en Spotify. Lo \u201csucio\u201d del sonido de un cassette incluso puede ser una ventaja. [v\u00eda <a href=\"https:\/\/www.fastcompany.com\/3067073\/musics-weird-cassette-tape-revival-is-paying-off\" target=\"_blank\" rel=\"noopener\">Fast Company<\/a>]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante los \u00faltimos a\u00f1os hemos visto el regreso de los discos de vinilo como un formato en el que los m\u00fasicos modernos ofrecen sus \u00e1lbumes. Ahora es el turno de los cassettes. Cada vez m\u00e1s personas en el mundo est\u00e1n volviendo a disfrutar de este formato retro; es la nueva moda musical.<\/p>\n","protected":false},"author":12,"featured_media":63187,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-63181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=63181"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63181\/revisions"}],"predecessor-version":[{"id":63189,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63181\/revisions\/63189"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/63187"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=63181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=63181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=63181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}