{"id":63762,"date":"2017-02-01T21:00:50","date_gmt":"2017-02-02T01:00:50","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=63762"},"modified":"2017-02-01T21:00:50","modified_gmt":"2017-02-02T01:00:50","slug":"muere-el-actor-frank-pellegrino-a-los-72-anos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/muere-el-actor-frank-pellegrino-a-los-72-anos\/","title":{"rendered":"Muere el actor Frank Pellegrino a los 72 a\u00f1os"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Frank-Pellegrino-800.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-63763 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Frank-Pellegrino-800.jpg\" alt=\"\" width=\"350\" height=\"219\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Frank-Pellegrino-800.jpg 800w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Frank-Pellegrino-800-300x188.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Frank-Pellegrino-800-768x480.jpg 768w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a>El actor <strong>Frank Pellegrino<\/strong>, reconocido por su actuaci\u00f3n en los dramas de mafia <em><strong>Goodfellas<\/strong><\/em> y <em><strong>The Sopranos<\/strong><\/em>, muri\u00f3 a los 72 a\u00f1os de edad, despu\u00e9s de luchar largamente contra el c\u00e1ncer de pulm\u00f3n.<!--more--><\/p>\n<p>Pllegrino interpret\u00f3 al oficina del FBI de Nueva Jersey, Frank Cubitoso, el jefe del n\u00e9mesis de Tony Soprano, el agente Harris (Matt Servitto). Otras papeles recordados de Pellegrino incluyen las series de televisi\u00f3n <em><strong>Law &amp; Order<\/strong><\/em> y <em><strong>New York Undercover,<\/strong><\/em> adem\u00e1s de las pel\u00edculas Cop Land y It Could Happen To You.<\/p>\n<p>Bo Dietl, amigo del difunto actor, dijo en entrevista para el New York Post que Pellegrino muri\u00f3 justo antes de las 2 pm de ayer en el Hospital Memorial Sloan Kettering de Manhattan rodeado de familiares.<\/p>\n<p>Charlie Gasparino, amigo y corresponsal de Fox Business News escribi\u00f3 sobre el artista en Facebook<\/p>\n<blockquote><p>\u00abFrank era de la vieja escuela, rudo por fuera pero con un coraz\u00f3n de oro y luch\u00f3 contra el c\u00e1ncer como se esperar\u00eda de un chico de las calles de East Harlem, hasta que no pudo pelear m\u00e1s.\u00bb<\/p><\/blockquote>\n<p>Pellegrino tambi\u00e9n era co-propietario del exclusivo restaurante italiano Rao&#8217;s en East Harlem, que el director Martin Scorsese -cliente frecuente- utiliz\u00f3 como localizaci\u00f3n en la pel\u00edcula <em>Wolf of Wall Street<\/em>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El actor Frank Pellegrino, reconocido por su actuaci\u00f3n en los dramas de mafia Goodfellas y The Sopranos, muri\u00f3 a los 72 a\u00f1os de edad, despu\u00e9s de luchar largamente contra el c\u00e1ncer de pulm\u00f3n.<\/p>\n","protected":false},"author":12,"featured_media":63763,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-63762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=63762"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63762\/revisions"}],"predecessor-version":[{"id":63764,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63762\/revisions\/63764"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/63763"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=63762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=63762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=63762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}