{"id":63769,"date":"2017-02-02T01:20:31","date_gmt":"2017-02-02T05:20:31","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=63769"},"modified":"2017-02-02T01:20:31","modified_gmt":"2017-02-02T05:20:31","slug":"la-quinceanera-mas-famosa-del-mundo-quiere-ser-artista-y-la-red-se-burla-de-ella","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/la-quinceanera-mas-famosa-del-mundo-quiere-ser-artista-y-la-red-se-burla-de-ella\/","title":{"rendered":"\u00abLa quincea\u00f1era m\u00e1s famosa del mundo\u00bb quiere ser artista y la Red se burla de ella"},"content":{"rendered":"<div class=\"arcticle-summary\">\n<p>La mexicana Rub\u00ed Ibarra se hizo famosa cuando la invitaci\u00f3n a su fiesta de 15 a\u00f1os se hizo viral y miles de personas acudieron al evento. Ahora ha anunciado p\u00fablicamente que quiere empezar una carrera art\u00edstica.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div class=\"arcticle-media\">\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/58921641c46188131e8b45d2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63772\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/58921641c46188131e8b45d2.jpg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/58921641c46188131e8b45d2.jpg 750w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/58921641c46188131e8b45d2-300x169.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<div class=\"arcticle-media__caption\"><\/div>\n<\/div>\n<div class=\"arcticle-fb-like\"><\/div>\n<div class=\"arcticle-content-wrapper\">\n<div class=\"arcticle-content js-mediator-article\">\n<p>A juzgar por un anuncio que ha publicado en su cuenta oficial\u00a0en Instagram, la quincea\u00f1era mexicana Rub\u00ed Ibarra no tiene intenci\u00f3n de dejar pasar el tren de la fama y quiere aprovecharlo para emprender la carrera art\u00edstica. Seg\u00fan\u00a0la publicaci\u00f3n,\u00a0divulgada el 31 de enero, Rub\u00ed est\u00e1 disponible para ser contratada para acudir a \u00abcarnavales, presentaciones, firmas, etc.\u00bb<\/p>\n<p>\u00abLa quincea\u00f1era m\u00e1s famosa del mundo\u00bb, como Rub\u00ed se autodenomina en el anuncio, tambi\u00e9n ha asegurado que contin\u00faa su desarrollo profesional. <strong>\u00abAclarando que estoy estudiando actuaci\u00f3n y canto, no he dejado mis estudios\u00bb<\/strong>, afirm\u00f3 la muchacha en su comentario a\u00a0la foto en la que acompa\u00f1a el\u00a0anuncio.<\/p>\n<p>De acuerdo con el diario &#8216;Debate&#8217;, actualmente la adolescente\u00a0tiene un\u00a0&#8216;manager&#8217;,\u00a0Rub\u00e9n Rojas, que colabora con la agencia Solo Si Son Famosos\u00a0y que ha trabajado con Maribel Guardia, Lis Vega e Ivonne Montero, entre otros.<\/p>\n<p>Las aspiraciones art\u00edsticas de Rub\u00ed han obtenido amplio eco en Instagram, donde muchos internautas han emitido sus cr\u00edticas hacia la joven. \u00abNo mames\u2026 para qu\u00e9 te voy a contratar. <strong>A d\u00f3nde vamos a parar con esta juventud tan par\u00e1sita<\/strong>\u00ab, escribi\u00f3 @piatrendry, mientras que @thechocolatelounge\u00a0ir\u00f3nicamente public\u00f3 \u00abUuy Si Que Tanto deseo ser como ella! Woooow me admiro de su gran talento!!\u00bb.<\/p>\n<p>Otros usuarios se han regodeado de un error que contiene el anuncio. Por ejemplo, el_chino_del_amor coment\u00f3 que \u00abmuy linda&#8230; pero deber\u00edas volver a editar tu portada&#8230; se escribe Quincea\u00f1era&#8230; <strong>no te hagas famosa por falta ortogr\u00e1fica&#8230;<\/strong>\u00ab. Y es que en realidad Rub\u00ed escribi\u00f3 &#8216;quicea\u00f1era&#8217;.<\/p>\n<div class=\"rtcode\"><iframe loading=\"lazy\" id=\"instagram-embed-0\" class=\"instagram-media instagram-media-rendered\" src=\"https:\/\/www.instagram.com\/p\/BP6OXqrDrrJ\/embed\/captioned\/?cr=1&amp;v=7\" width=\"600\" height=\"1000\" frameborder=\"0\" scrolling=\"no\" data-instgrm-payload-id=\"instagram-media-payload-0\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<p>El fen\u00f3meno de &#8216;Los XV de Rub\u00ed&#8217;\u00a0comenz\u00f3 a principios de diciembre pasado, cuando el padre de la adolescente public\u00f3 en\u00a0Facebook\u00a0un video invitando \u00aba todo el mundo\u00bb al cumplea\u00f1os de su hija. El video pronto se hizo\u00a0viral\u00a0en las redes sociales.<\/p>\n<p>La fiesta, celebrada el 26 de diciembre en la comunidad de La Joya del estado de San Lu\u00eds de Potos\u00ed, acab\u00f3 convirti\u00e9ndose en un acto multitudinario que cont\u00f3 con la participaci\u00f3n de varios artistas y con una carrera de caballos que tuvo\u00a0tr\u00e1gicas consecuencias.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La mexicana Rub\u00ed Ibarra se hizo famosa cuando la invitaci\u00f3n a su fiesta de 15 a\u00f1os se hizo viral y miles de personas acudieron al evento. Ahora ha anunciado p\u00fablicamente que quiere empezar una carrera art\u00edstica.<\/p>\n","protected":false},"author":12,"featured_media":63772,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-63769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=63769"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63769\/revisions"}],"predecessor-version":[{"id":63773,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63769\/revisions\/63773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/63772"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=63769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=63769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=63769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}