{"id":63807,"date":"2017-02-04T16:32:17","date_gmt":"2017-02-04T20:32:17","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=63807"},"modified":"2017-02-04T16:32:17","modified_gmt":"2017-02-04T20:32:17","slug":"nueva-pelicula-dominicana-con-fuerte-mensaje-a-politicos-y-ricos-del-pais-trailer","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/nueva-pelicula-dominicana-con-fuerte-mensaje-a-politicos-y-ricos-del-pais-trailer\/","title":{"rendered":"Nueva pel\u00edcula dominicana con fuerte mensaje a pol\u00edticos y ricos del pa\u00eds #TRAILER"},"content":{"rendered":"<p>La nueva pel\u00edcula de cineasta dominicano Angel Mu\u00f1iz, no ser\u00e1 estrenada en cines sino en televisi\u00f3n el pr\u00f3ximo domingo 26 de febrero por Color Visi\u00f3n, justo el d\u00eda antes de la rendici\u00f3n de cuentas del presidente Danilo Medina.<!--more--><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Escena-de-la-pelicula-dominicana-Y-a-Dios-que-me-perdone.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63808\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Escena-de-la-pelicula-dominicana-Y-a-Dios-que-me-perdone.jpg\" alt=\"\" width=\"640\" height=\"315\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Escena-de-la-pelicula-dominicana-Y-a-Dios-que-me-perdone.jpg 640w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Escena-de-la-pelicula-dominicana-Y-a-Dios-que-me-perdone-300x148.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p>Durante una entrevista en el segmeno \u00abEl Mundo del Arte\u00bb de Noticias SIN -donde se estren\u00f3 el trailer- Mu\u00f1iz coment\u00f3 que \u00abel mes de la Patria es un escenario perfecto e id\u00f3neo para promover esta historia\u00bb de denuncia social\u00bb basada en hechos reales y que ser\u00e1 la primera pel\u00edcula dominicana que se estrena en un canal de televisi\u00f3n gratis y sin comerciales.<\/p>\n<blockquote class=\"tr_bq\"><p>Mu\u00f1iz dijo que proyecta gratis la pel\u00edcula para que \u00ablos pobres no tienen acceso a las salas de cine -la gente m\u00e1s sufrida- vean la historia, se vean ellos en este cuento a ver si salimos de esta coraza en la que estamos metidos y le pase factura a los pol\u00edticos ladrones y delincuentes que nos tienen en zozobra\u00bb.<\/p><\/blockquote>\n<p style=\"text-align: center;\">\nDijo que el mensaje va a los ricos del pa\u00eds, los pol\u00edticos y al Presidente para que sepan que \u00abcomo Toribio este pa\u00eds se va a jartar\u00bb.<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/1tpIVqqVg1g?showinfo=0\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><br \/>\nEl filme narra la historia de Toribio Sosa, un raso de la polic\u00eda que hace todo lo que est\u00e9 a su alcance para conseguir los recursos necesarios con tal que su mujer sobreviva a una leucemia post parto. El drama esta protagonizado por Johnnie Mercedes, Clara y Akuarela, quienes son esposa e hija del actor dominicano respectivamente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La nueva pel\u00edcula de cineasta dominicano Angel Mu\u00f1iz, no ser\u00e1 estrenada en cines sino en televisi\u00f3n el pr\u00f3ximo domingo 26 de febrero por Color Visi\u00f3n, justo el d\u00eda antes de la rendici\u00f3n de cuentas del presidente Danilo Medina.<\/p>\n","protected":false},"author":12,"featured_media":63808,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[387],"tags":[],"class_list":["post-63807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cine-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=63807"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63807\/revisions"}],"predecessor-version":[{"id":63809,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63807\/revisions\/63809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/63808"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=63807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=63807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=63807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}