{"id":63813,"date":"2017-02-04T16:53:27","date_gmt":"2017-02-04T20:53:27","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=63813"},"modified":"2017-02-04T16:53:27","modified_gmt":"2017-02-04T20:53:27","slug":"sabes-lo-que-pasa-en-nuestro-cuerpo-al-dormir-bien-te-encantara","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/sabes-lo-que-pasa-en-nuestro-cuerpo-al-dormir-bien-te-encantara\/","title":{"rendered":"\u00bfSabes lo que pasa en nuestro cuerpo al dormir bien? \u00a1Te encantar\u00e1!"},"content":{"rendered":"<p>\u00bfSab\u00edas que dormir bien es fundamental para que nuestra dermis se regenere? As\u00ed, un mal descanso puede derivar en la aparici\u00f3n de arrugas prematuras y en un tono de piel m\u00e1s apagado.<!--more--><br \/>\nNuestro descanso nocturno es m\u00e1s importante de lo que puede parecer.<\/p>\n<p>Para <strong>almacenar correctamente nuevos conocimientos o datos<\/strong> en nuestra mente, es aconsejable dormir bien dos horas despu\u00e9s de las cinco siguientes a haber recibido la informaci\u00f3n.<\/p>\n<div class=\"ad-desktop\"><\/div>\n<h2>La importancia del descanso mientras dormimos<\/h2>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Dormir-mejor-sin-pastillas-500x334.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-63816\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Dormir-mejor-sin-pastillas-500x334.jpg\" alt=\"\" width=\"500\" height=\"334\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Dormir-mejor-sin-pastillas-500x334.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/Dormir-mejor-sin-pastillas-500x334-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Todos lo hemos experimentado m\u00e1s de una vez. La noche que descansamos de forma insuficiente, estamos agotados el d\u00eda siguiente.<\/p>\n<p>Tenemos los ojos enrojecidos, poca energ\u00eda y, en general, un mal cuerpo que mermar\u00e1 nuestra actividad diaria.<\/p>\n<p>Podemos pensar que, durante la noche, la actividad corporal disminuye mucho. Nada m\u00e1s lejos de la realidad.<\/p>\n<p>Es m\u00e1s bien al contrario, <strong>durante la noche, el organismo libera hormonas que nos ayudan a mantener el bienestar<\/strong> a lo largo del d\u00eda.<\/p>\n<p>Estas hormonas se van a convertir en aliadas de nuestra salud y tambi\u00e9n de nuestro aspecto exterior.<\/p>\n<h2>Dormir bien es imprescindible<\/h2>\n<p>Est\u00e1 claro que<strong> el sue\u00f1o\u00a0adem\u00e1s de muy beneficioso, es imprescindible para nosotros. <\/strong>Pasamos aproximadamente un tercio de nuestra vida durmiendo.<\/p>\n<h2>Las fases del sue\u00f1o<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"kalooga_24978 aligncenter size-large wp-image-93986\" src=\"https:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/02\/interpretar-tus-suenos-500x334.jpg\" alt=\"interpretar tus suenos\" width=\"500\" height=\"334\" \/><\/p>\n<p><strong>Todas las horas del sue\u00f1o no son iguales ni inciden en nuestro cuerpo de la misma forma.<\/strong><\/p>\n<p>Cuando dormimos vamos pasando por diferentes etapas, que se repiten a lo largo de toda la noche.<\/p>\n<div class=\"ad-desktop\"><\/div>\n<ul>\n<li>Las primeras, <strong>las fases 1 y 2, nos regalan un sue\u00f1o ligero en el que la musculatura se relaja.<\/strong><\/li>\n<\/ul>\n<p>La presi\u00f3n arterial, la frecuencia cardiaca y la respiratoria descienden, y se registra una menor actividad cerebral.<\/p>\n<ul>\n<li>Durante las fases 3 y 4, el sue\u00f1o es profundo, las ondas cerebrales son muy lentas. A estas ondas se las denomina ondas celta.<\/li>\n<li>\u00bfCu\u00e1l es la conocida fase REM? Estas siglas derivan del ingl\u00e9s \u201c<em>Rapid Eye Movement<\/em>\u201d, es decir, un r\u00e1pido movimiento de los ojos.<\/li>\n<\/ul>\n<p>En esta fase se registra un alto nivel de actividad cerebral, en contraste con la gran relajaci\u00f3n muscular. <strong>En ella se producen la mayor\u00eda de los sue\u00f1os que solemos recordar<\/strong>.<\/p>\n<h2>Dormir bien, una f\u00e1brica de m\u00fasculo<\/h2>\n<p>Cuando <strong>descansamos tumbados, nuestro organismo descansa m\u00e1s y mejor<\/strong>.<\/p>\n<p>Nuestra posici\u00f3n horizontal facilita que las articulaciones soporten menos peso que durante el d\u00eda. Adem\u00e1s, ello hace posible que los m\u00fasculos se liberen de la tensi\u00f3n, se relajen y se regeneren.<\/p>\n<p>Durante las fases 3 y 4 nuestro organismo va a segregar la hormona del crecimiento, que resulta muy importante para la regeneraci\u00f3n muscular.<\/p>\n<p>Esta hormona es imprescindible para los ni\u00f1os, y por ello su descanso nocturno (o, en el caso de los beb\u00e9s, a lo largo del d\u00eda) debe ser dilatado y muy profundo.<\/p>\n<p>Adem\u00e1s del descanso nocturno, <strong>una buena siesta puede ser tambi\u00e9n muy reparadora<\/strong>. No obstante, en ning\u00fan caso debe ser demasiado larga ni sustituir al sue\u00f1o nocturno.<\/p>\n<h2>Dormir bien cura enfermedades<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"kalooga_24978 aligncenter size-large wp-image-87587\" src=\"https:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/12\/Mant%C3%A9n-una-rutina-de-sue%C3%B1o-500x333.jpg\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" srcset=\"https:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/12\/Mant\u00e9n-una-rutina-de-sue\u00f1o-500x333.jpg 500w, https:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/12\/Mant\u00e9n-una-rutina-de-sue\u00f1o-768x512.jpg 768w\" alt=\"Mant\u00e9n una rutina de sue\u00f1o\" width=\"500\" height=\"333\" \/><\/p>\n<p>Nuestro sistema inmunitario se fortalecer\u00e1 mediante un sue\u00f1o reparador. <strong>Tambi\u00e9n el sistema circulatorio se beneficia durante el sue\u00f1o<\/strong>.<\/p>\n<p>Al descender la presi\u00f3n arterial, el coraz\u00f3n necesita realizar menos esfuerzo para bombear sangre a todo el sistema circulatorio.<\/p>\n<ul>\n<li>Al dormir bien, el equilibrio en nuestro organismo se mantiene.<\/li>\n<li><strong>Si no lo hacemos correctamente, el sistema inmunitario se ve afectado<\/strong> y nos volvemos m\u00e1s vulnerables a determinadas enfermedades, como las infecciones por virus.<\/li>\n<\/ul>\n<p>Cuando estamos enfermos, nuestro cuerpo repone la energ\u00eda con m\u00e1s dificultad y por ello es importante dormir m\u00e1s.<\/p>\n<h2>La vista<\/h2>\n<p>Algunos productos cosm\u00e9ticos para uso nocturno basan su efecto en eso, en que <strong>durante el sue\u00f1o las c\u00e9lulas se regeneran m\u00e1s deprisa <\/strong>y la piel asimila mejor los activos nutritivos.<\/p>\n<div class=\"ad-desktop\"><\/div>\n<p>La falta de sue\u00f1o provoca algunas alteraciones en la pel\u00edcula lagrimal que debe proteger la c\u00f3rnea.<\/p>\n<p>Las personas con tendencia a la retenci\u00f3n de l\u00edquidos o bolsas grasas pueden tener un empeoramiento en periodos de descanso inadecuado.<\/p>\n<p>Las consecuencias\u00a0son visibles en nuestro rostro. Por ello,<strong> uno de los grandes consejos de belleza es el de dormir bien<\/strong>.<\/p>\n<h2>Sacudidas h\u00edpnicas<\/h2>\n<p><strong>M\u00e1s de la mitad de las personas sufrimos espasmos cuando dormimos<\/strong>, lo que se llama mioclonos nocturnos o sacudidas h\u00edpnicas.<\/p>\n<p>Todos hemos tenido alguna vez la sensaci\u00f3n de que la pierna se nos mueve sola, o de que caemos de la cama.<\/p>\n<h2><strong>El bruxismo<\/strong><\/h2>\n<p>El\u00a0rechinado de dientes mientras dormimos tambi\u00e9n es habitual.<\/p>\n<p>Aunque sus causas no se conocen de forma detallada, el estr\u00e9s puede ser un condicionante, as\u00ed como la postura elegida para dormir bien, la alimentaci\u00f3n, etc.<\/p>\n<h2>Par\u00e1lisis de sue\u00f1o<\/h2>\n<p>A veces nuestro organismo puede <strong>paralizar <\/strong><strong>nuestros m\u00fasculos mientras dormimos <\/strong>y as\u00ed evitar que se muevan en funci\u00f3n de lo que estamos so\u00f1ando.<\/p>\n<p>Cuando hay fallos y estamos semidespiertos, no somos capaces de mover m\u00fasculos. Se llama par\u00e1lisis de sue\u00f1o.<\/p>\n<h2><strong>Excitaci\u00f3n sexual<\/strong><\/h2>\n<p>Es habitual que los hombres tengan\u00a0erecciones nocturnas\u00a0durante el sue\u00f1o. La sangre se oxigena m\u00e1s en el descanso provocando este tipo de reacci\u00f3n, de tres a cinco veces durante la noche.<\/p>\n<p>Tambi\u00e9n sucede en las mujeres, que notan\u00a0impulsos en sus genitales\u00a0e incluso pueden llegar a tener orgasmos, generalmente producidos por un sue\u00f1o subido de tono.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSab\u00edas que dormir bien es fundamental para que nuestra dermis se regenere? As\u00ed, un mal descanso puede derivar en la aparici\u00f3n de arrugas prematuras y en un tono de piel m\u00e1s apagado.<\/p>\n","protected":false},"author":12,"featured_media":63816,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-63813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=63813"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63813\/revisions"}],"predecessor-version":[{"id":63817,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/63813\/revisions\/63817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/63816"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=63813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=63813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=63813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}