{"id":64185,"date":"2017-02-21T15:27:49","date_gmt":"2017-02-21T19:27:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=64185"},"modified":"2017-02-21T20:29:48","modified_gmt":"2017-02-22T00:29:48","slug":"lakers-nombran-a-magic-johnson-como-presidente-de-operaciones","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/lakers-nombran-a-magic-johnson-como-presidente-de-operaciones\/","title":{"rendered":"Lakers nombran a Magic Johnson como presidente de operaciones"},"content":{"rendered":"<div id=\"ArticleAuthorDiv\" class=\"article-body-author\"><b><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/201702212103581.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-64186 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/02\/201702212103581.jpeg\" alt=\"\" width=\"294\" height=\"215\" \/><\/a>AP,\u00a0<\/b><b>Los \u00c1ngeles.-\u00a0<\/b>Los Lakers de Los Angeles despidieron el martes al gerente general Mitch Kupchak y otorgaron las riendas del equipo a Magic Johnson.<\/div>\n<p><!--more--><\/p>\n<div id=\"ArticleBody\">\n<p>La due\u00f1a de los Lakers, Jeanie Buss, tambi\u00e9n sac\u00f3 a su hermano, Jim, de su cargo como vicepresidente ejecutivo del equipo a cargo de las operaciones deportivas.<\/p>\n<p>Inmediatamente, Jeanie Buss otorg\u00f3 mayores responsabilidades a Johnson, una leyenda del equipo en su \u00e9poca como jugador que regres\u00f3 a los Lakers esta temporada con un cargo ejecutivo. Johnson es el nuevo presidente de operaciones deportivas, y reportar\u00e1 directamente a Jeanie Buss.<\/p>\n<p>Jeanie Buss realiz\u00f3 los cambios dos d\u00edas antes que expire el plazo para canjes en la NBA. Los Lakers tienen marca de 19-39 esta temporada, la primera bajo la tutela del entrenador Luke Walton, quien recibi\u00f3 un espaldarazo de Jeanie Buss.<\/p>\n<p>En un comunicado, Jeanie Buss dijo que \u00abtom\u00e9 varias decisiones que creo que colocar\u00e1n a los Lakers en el nivel que exig\u00eda (su fenecido padre y exdue\u00f1o del equipo) el doctor Jerry Buss y que nuestros fan\u00e1ticos esperan\u00bb.<\/p>\n<p>\u00abLa b\u00fasqueda de un nuevo gerente general para trabajar con Earvin (Johnson) y Luke Walton est\u00e1 bien encaminada, y esperamos presentar pronto al nuevo gerente general\u00bb, agreg\u00f3. \u00abEarvin, Luke y nuestro nuevo gerente general formar\u00e1n la base para la nueva generaci\u00f3n de grandeza de los Lakers de Los Angeles2.<\/p>\n<p>Kupchak fue el gerente general del equipo desde 2000, cuando Jerry West se fue de los Lakers. Llevaba 30 a\u00f1os en la gerencia del equipo, incluyendo los \u00faltimos 17 como gerente general. Jim Buss estuvo 19 a\u00f1os en la plana mayor del equipo, incluyendo 12 a cargo de las operaciones deportivas junto con Kupchak.<\/p>\n<p>Los Lakers atraviesan el peor per\u00edodo de cuatro a\u00f1os en la historia del equipo, al perderse los playoffs tres a\u00f1os consecutivos. Su marca de 17-65 la temporada pasada fue la peor en la historia del equipo.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>AP,\u00a0Los \u00c1ngeles.-\u00a0Los Lakers de Los Angeles despidieron el martes al gerente general Mitch Kupchak y otorgaron las riendas del equipo a Magic Johnson.<\/p>\n","protected":false},"author":12,"featured_media":64186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-64185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=64185"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64185\/revisions"}],"predecessor-version":[{"id":64187,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64185\/revisions\/64187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/64186"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=64185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=64185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=64185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}