{"id":64554,"date":"2017-03-04T11:24:15","date_gmt":"2017-03-04T15:24:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=64554"},"modified":"2017-03-04T11:24:15","modified_gmt":"2017-03-04T15:24:15","slug":"piden-a-expresidente-estadounidense-barack-obama-sumarse-a-campana-presidencial-en-francia","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/piden-a-expresidente-estadounidense-barack-obama-sumarse-a-campana-presidencial-en-francia\/","title":{"rendered":"Piden a expresidente estadounidense Barack Obama sumarse a campa\u00f1a presidencial en Francia"},"content":{"rendered":"<div><b><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/a11885659bc9f42e28b40ba3ae03a759_300x226.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-64557 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/a11885659bc9f42e28b40ba3ae03a759_300x226.jpg\" alt=\"\" width=\"300\" height=\"226\" \/><\/a>PARIS.-<\/b> \u201cOui on peut!\u201d es el lema que ha aparecido en carteles en las calles de Par\u00eds, la traducci\u00f3n de \u201c\u00a1S\u00ed se puede!\u201d. \u00bfSuena conocido?. Los organizadores de la campa\u00f1a exhortan al expresidente estadounidense Barack Obama a que se sume a la contienda presidencial en Francia. El petitorio en internet tiene ya m\u00e1s de 45,000 firmas y los organizadores esperan alcanzar un mill\u00f3n para el 15 de marzo.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<div>La campa\u00f1a para los comicios presidenciales de abril-mayo est\u00e1 dominada hasta ahora por una investigaci\u00f3n por corrupci\u00f3n al candidato conservador Fran\u00e7ois Fillon, y los organizadores dicen que quieren inyectar humor al proceso.<\/div>\n<div>Aunque es enormemente popular en Francia, Obama no tiene posibilidades de \u00e9xito. No es franc\u00e9s y por ello no puede tomar parte en la contienda.<\/div>\n<div>\nSarah Wachter, una estadounidense que reside en Francia desde 1999, dice que el petitorio es una se\u00f1al positiva para el pa\u00eds. \u201cLa gente quiere un cambio, pero un cambio justo. Un cambio incluyente, un cambio humano pero tambi\u00e9n abierto al mundo, y eso requiere un equilibrio muy delicado\u201d, dijo. \u201cCreo que Obama lo ha logrado en Estados Unidos\u201d.<\/div>\n<div>\nEsta semana, Obama fue nombrado ganador del Premio John F. Kennedy al Coraje 2017. \u201cMe siento honrado de ser reconocido por una familia con un legado de servicio\u201d, dijo el exmandatarior.<\/div>\n<div>\n\u201cEl presidente Kennedy convoc\u00f3 a una nueva generaci\u00f3n de estadounidenses a dar sus talentos al servicio del pa\u00eds\u201d, dijo su hija, Caroline Kennedy, en una declaraci\u00f3n el jueves.<\/div>\n<p>\u201cCon dignidad y coraje excepcionales, el presidente Obama ha llevado esa antorcha a nuestros tiempos, dando a j\u00f3venes de todos los contextos un ejemplo que pueden emular en sus vidas\u201d. El premio es presentado anualmente a servidores p\u00fablicos que han tomado decisiones valientes de consciencia sin importar las consecuencias profesionales y personales. Lleva el nombre del galardonado libro de John F. Kennedy de 1957 \u201cPerfiles de Coraje\u201d, donde narra las historias de ocho senadores estadounidenses que arriesgaron sus carreras defendiendo posiciones impopulares.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PARIS.- \u201cOui on peut!\u201d es el lema que ha aparecido en carteles en las calles de Par\u00eds, la traducci\u00f3n de \u201c\u00a1S\u00ed se puede!\u201d. \u00bfSuena conocido?. Los organizadores de la campa\u00f1a exhortan al expresidente estadounidense Barack Obama a que se sume a la contienda presidencial en Francia. El petitorio en internet tiene ya m\u00e1s de 45,000 firmas y los organizadores esperan alcanzar un mill\u00f3n para el 15 de marzo.<\/p>\n","protected":false},"author":12,"featured_media":64557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-64554","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=64554"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64554\/revisions"}],"predecessor-version":[{"id":64558,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64554\/revisions\/64558"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/64557"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=64554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=64554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=64554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}