{"id":64559,"date":"2017-03-04T11:27:40","date_gmt":"2017-03-04T15:27:40","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=64559"},"modified":"2017-03-04T11:27:40","modified_gmt":"2017-03-04T15:27:40","slug":"4-recomendaciones-para-mitigar-el-cansancio-de-tus-ojos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/4-recomendaciones-para-mitigar-el-cansancio-de-tus-ojos\/","title":{"rendered":"4 recomendaciones para mitigar el cansancio de tus ojos"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/4-recomendaciones-para-mitigar-el-cansancio-de-tus-ojos-500x334.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-64560\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/4-recomendaciones-para-mitigar-el-cansancio-de-tus-ojos-500x334.jpg\" alt=\"\" width=\"500\" height=\"334\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/4-recomendaciones-para-mitigar-el-cansancio-de-tus-ojos-500x334.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/4-recomendaciones-para-mitigar-el-cansancio-de-tus-ojos-500x334-300x200.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a>Debemos cuidar de la salud de nuestros ojos y aprender a parpadear de forma consciente cada poco tiempo para lubricarlos, as\u00ed como hacer descansos programados para cerrarlos y descansar unos segundos.<!--more--><\/p>\n<p>Los ojos son \u00f3rganos ubicados en la parte frontal del cr\u00e1neo.<\/p>\n<p><strong>Estos se encargan de asimilar todo tipo de im\u00e1genes<\/strong>, que son\u00a0transportadas al cerebro a trav\u00e9s de impulsos nerviosos con el fin de asimilar y procesar informaci\u00f3n clara y concisa.<\/p>\n<p>Esta funci\u00f3n resulta relevante para el d\u00eda a d\u00eda del ser humano, teniendo en cuenta todo el medio encontrado alrededor.<\/p>\n<div class=\"ad-desktop\"><\/div>\n<p>El uso de estos \u00f3rganos de la visi\u00f3n se extiende m\u00e1s all\u00e1 de las\u00a012 o 13 horas al d\u00eda, y es que<strong> est\u00e1n implicados en casi todo tipo de actividad, entretenimiento o trabajo<\/strong>.<\/p>\n<p>As\u00ed las cosas,<strong> no es de extra\u00f1ar que puedan presentar fatiga o cansancio<\/strong>.<\/p>\n<h2>Actividades que desgastan los ojos<\/h2>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/8-maneras-de-proteger-los-ojos-ante-los-da\u00f1os-de-los-dispositivos-electr\u00f3nicos.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-64561\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/8-maneras-de-proteger-los-ojos-ante-los-da\u00f1os-de-los-dispositivos-electr\u00f3nicos.jpg\" alt=\"\" width=\"486\" height=\"357\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/8-maneras-de-proteger-los-ojos-ante-los-da\u00f1os-de-los-dispositivos-electr\u00f3nicos.jpg 486w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/8-maneras-de-proteger-los-ojos-ante-los-da\u00f1os-de-los-dispositivos-electr\u00f3nicos-300x220.jpg 300w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><\/a><\/p>\n<p>A pesar de utilizar los ojos en periodos de tiempo extremadamente cortos, existen actividades donde el esfuerzo de estos deber ser un poco m\u00e1s exigente.<\/p>\n<p>Por l\u00f3gica raz\u00f3n, el d\u00eda a d\u00eda trae consigo cumplir una rutina com\u00fan. Durante esta, los ojos son los gu\u00edas principales del camino.<\/p>\n<p>No obstante, tambi\u00e9n surgen <strong>actividades donde el sentido de la vista se emplea sobre manera<\/strong>.<\/p>\n<p>Con base en ello, \u00a0hoy vamos a mostrar\u00a0las actividades m\u00e1s desgastantes para los ojos. Comencemos.<\/p>\n<h3>Usar la computadora<\/h3>\n<p>En los tiempos de hoy, los trabajos, en su mayor\u00eda, se centran en las\u00a0computadoras, ya sea en casa o en la oficina. Esto, sin duda, genera un uso excesivo de los ojos.<\/p>\n<p>Dicha exposici\u00f3n fomenta un extremo cansancio y desgaste.<\/p>\n<div id=\"hybs-slot-28570da5\" class=\"hybs-slot\"><\/div>\n<div id=\"hybs-slot-28570da5\" class=\"hybs-slot\"><\/div>\n<h3>Fumar<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"kalooga_24978 aligncenter size-large wp-image-87617\" src=\"https:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/12\/Fumar-500x332.jpg\" alt=\"Fumar\" width=\"500\" height=\"332\" \/>El exceso de nicotina en el organismo fomenta la degeneraci\u00f3n macular, debido a la aceleraci\u00f3n del proceso degenerativo de la retina producido por tal sustancia.<\/p>\n<p>Adem\u00e1s, <strong>la sobreexposici\u00f3n al humo del cigarrillo da\u00f1a de forma severa el sentido de la visi\u00f3n.<\/strong><\/p>\n<h3>Exposici\u00f3n al sol<\/h3>\n<p>El sol emana rayos intensos denominados o conocidos como ultravioleta (UV); estos suelen causar diversas enfermedades en el organismo, especialmente en la piel.<\/p>\n<p>No obstante, los ojos tambi\u00e9n se ven afectados por la exposici\u00f3n prolongada al astro rey y <strong>pueden presentar\u00a0padecimientos degenerativos o maculopat\u00eda solar.<\/strong><\/p>\n<h3>Consumir az\u00facar sint\u00e9tica<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"kalooga_24978 aligncenter size-large wp-image-85222\" src=\"https:\/\/mejorconsalud.com\/wp-content\/uploads\/2015\/12\/Refrescos-500x332.jpg\" alt=\"Refrescos\" width=\"500\" height=\"332\" \/><\/p>\n<p>Este ingrediente se encuentra en un sinf\u00edn de productos industrializados, sobre todo\u00a0en los refrescos de dieta.<\/p>\n<p>Cuando estos se ingieren incesantemente, <strong>la retina se ve afectada\u00a0de forma considerable<\/strong>.<\/p>\n<p>Todas estas actividades\u00a0influyen directa e indirectamente con el cansancio visual; por ello, se recomienda evitarlas de lleno o, por lo menos, ser moderado.<\/p>\n<h2>Recomendaciones sencillas para mitigar el cansancio ocular<\/h2>\n<p>Aunque muchas de las actividades mencionadas de forma previa hacen alusi\u00f3n al desgaste ocular, hay otras que\u00a0tambi\u00e9n cansan los \u00f3rganos sobremanera.<\/p>\n<p>Por tal raz\u00f3n les mostraremos una serie de recomendaciones sencillas para mitigar el cansancio de los ojos.<\/p>\n<h3>1. Mirar a lo lejos<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"kalooga_24978 aligncenter size-large wp-image-126287\" src=\"https:\/\/mejorconsalud.com\/wp-content\/uploads\/2016\/11\/5-errores-en-el-cuidado-de-los-ojos-que-puedes-estar-cometiendo-500x334.jpg\" alt=\"5 errores en el cuidado de los ojos que puedes estar cometiendo\" width=\"500\" height=\"334\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Es posible que el cansancio ocular se presente en la oficina o en un espacio cerrado.\u00a0Si este es el caso,<strong> se recomienda buscar un punto fijo, por lo menos, a un metro.<\/strong><\/p>\n<ul>\n<li>Una vez establecido, se recomienda observarlo de forma fija durante unos 20 segundos.<\/li>\n<li>Pasado el tiempo indicado es necesario parpadear r\u00e1pidamente.<\/li>\n<\/ul>\n<h3>2. Relajarse<\/h3>\n<p>La relajaci\u00f3n es una gran recomendaci\u00f3n frente a cualquier padecimiento del organismo, y m\u00e1s a\u00fan, si tenemos\u00a0en cuenta el asombroso poder de la mente.<\/p>\n<div class=\"ad-desktop\"><\/div>\n<p>Existen diferente formas de conseguir relajarse.<\/p>\n<ul>\n<li>Con respecto a los ojos, se recomienda<strong> cerrarlos (sin hacer presi\u00f3n alguna), respirar hondo y lentamente<\/strong>.<\/li>\n<li>Tambi\u00e9n es posible cubrirse los parpados con las palmas de las manos en forma c\u00f3ncava.<\/li>\n<\/ul>\n<h3>3. Parpadear<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"kalooga_24978 aligncenter size-large wp-image-133285\" src=\"https:\/\/mejorconsalud.com\/wp-content\/uploads\/2017\/01\/Mujer-joven-con-los-ojos-cerrados-500x334.jpg\" alt=\"Mujer-joven-con-los-ojos-cerrados\" width=\"500\" height=\"334\" \/><\/p>\n<p>Puede que suene redudante, teniendo en cuenta el parpadeo natural de los ojos. No obstante, la recomendaci\u00f3n en s\u00ed gira en torno a hacerlo de diversas formas.<\/p>\n<ul>\n<li>En caso de estar leyendo de la pantalla de un ordenador, debemos hacerlo a una distancia de 60 cm.<\/li>\n<li>Una vez establecida, comenzar a parpadear de manera pausada <strong>(tambi\u00e9n puede hacerse en caso de ser un libro o un dispositivo m\u00f3vil).<\/strong><\/li>\n<\/ul>\n<p>Emplear la famosa regla del parpadeo 20-6-20 se pueden lograr grandes resultados con respecto al descanso ocular.<\/p>\n<p>Esta se realizar de la siguiente manera:<\/p>\n<ul>\n<li>Luego de 20 minutos de actividad se debe fijar un objeto a 6 metros de distancia;<strong> se\u00f1alarlo con la mirada y parpadear alrededor de 20 segundos<\/strong>.<\/li>\n<li>Si dicha actividad va m\u00e1s all\u00e1 de la hora, se puede realizar la regla en cuesti\u00f3n\u00a0cada 20 minutos.<\/li>\n<\/ul>\n<h3>4. Descansos programados<\/h3>\n<p>Es comprensible la importancia del trabajo dentro de la oficina o en el ordenador. No obstante, hacerlo de manera continua afecta considerablemente la salud de los ojos.<\/p>\n<p>En ese orden de ideas, la recomendaci\u00f3n sugiere<strong> descansar, al menos, cada 2 horas, por lo menos durante 15 minutos<\/strong>.<\/p>\n<p>Durante este per\u00edodo de descanso se debe\u00a0parpadear y cerrar los ojos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debemos cuidar de la salud de nuestros ojos y aprender a parpadear de forma consciente cada poco tiempo para lubricarlos, as\u00ed como hacer descansos programados para cerrarlos y descansar unos segundos.<\/p>\n","protected":false},"author":12,"featured_media":64561,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-64559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=64559"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64559\/revisions"}],"predecessor-version":[{"id":64562,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64559\/revisions\/64562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/64561"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=64559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=64559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=64559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}