{"id":64747,"date":"2017-03-12T10:13:05","date_gmt":"2017-03-12T14:13:05","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=64747"},"modified":"2017-03-12T10:13:05","modified_gmt":"2017-03-12T14:13:05","slug":"fideos-de-calabacin-con-camarones-y-ajo","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/fideos-de-calabacin-con-camarones-y-ajo\/","title":{"rendered":"Fideos de Calabac\u00edn con Camarones y Ajo"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-64748 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/pasta-para-diabeticos-receta-CG11626.jpg\" alt=\"\" width=\"219\" height=\"283\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/pasta-para-diabeticos-receta-CG11626.jpg 550w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/pasta-para-diabeticos-receta-CG11626-232x300.jpg 232w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/>No es la primera receta con fideos de calabacines que comparto. El que est\u00e1 ahora publicando otra te indica cuanto me gustan, aunque suene raro. La raz\u00f3n por la que me gustan ambas recetas es porque las dos tienen sabores fuertes, que levantan el sabor delicado de los calabacines. La primera ten\u00eda <a href=\"https:\/\/www.cocinadominicana.com\/1753\/mamba-mantequilla-de-mani-a-la-dominicana.html\">Mamb\u00e1<\/a>, esta tiene mucho ajo.<!--more--><\/p>\n<p>Hace unos d\u00edas una colega bloguera culinaria latina cont\u00f3 la historia de alguien que se sorprendi\u00f3 de que us\u00f3 toda una cabeza de ajo en una receta. Su lector pens\u00f3 que definitivamente ten\u00eda que ser un error.<\/p>\n<p>Lo que nos hizo sonre\u00edr a ambas es la idea de que puede haber tal cosa como \u201cdemasiado ajo\u201d. M\u00e1s f\u00e1cil puedo creer en unicornios y hadas madrinas.<\/p>\n<p>Quiz\u00e1 es una cosa de latinos, pero <em>amamos<\/em> el ajo.<\/p>\n<p>Bueno, si eres uno de esos que odia el ajo (o eres un vampiro), sugiero que te mantengas alejado de este plato. De lo contrario, bienvenido(a), compa\u00f1ero fan\u00e1tico(a) del ajo.<\/p>\n<p>Esta es una receta que encantar\u00e1 a diab\u00e9ticos y a quienes est\u00e1n a dieta baja en carbohidratos. Es como un plato de pasta, pero sin la culpa. Los fideos de calabacines son mi sustituto favorito de la pasta, y por supuesto, si no est\u00e1s a dieta puedes usar pasta real. Te recomiendo spaghettini para este.<\/p>\n<p>Pru\u00e9balo y me avisas.<\/p>\n<p>\u00a1Buen provecho!<\/p>\n<p><span class=\"signature\">T\u00eda Clara<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No es la primera receta con fideos de calabacines que comparto. El que est\u00e1 ahora publicando otra te indica cuanto me gustan, aunque suene raro. La raz\u00f3n por la que me gustan ambas recetas es porque las dos tienen sabores fuertes, que levantan el sabor delicado de los calabacines. La primera ten\u00eda Mamb\u00e1, esta tiene mucho ajo.<\/p>\n","protected":false},"author":9,"featured_media":64748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-64747","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=64747"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64747\/revisions"}],"predecessor-version":[{"id":64749,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64747\/revisions\/64749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/64748"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=64747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=64747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=64747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}