{"id":64763,"date":"2017-03-13T16:13:15","date_gmt":"2017-03-13T20:13:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=64763"},"modified":"2017-03-13T16:13:15","modified_gmt":"2017-03-13T20:13:15","slug":"alimentos-que-rejuvenecen-tu-cerebro","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/alimentos-que-rejuvenecen-tu-cerebro\/","title":{"rendered":"Alimentos que rejuvenecen tu cerebro"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-64764 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/Arandanos-291x160.jpg\" alt=\"\" width=\"291\" height=\"160\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/Arandanos-291x160.jpg 291w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/03\/Arandanos-291x160-400x220.jpg 400w\" sizes=\"auto, (max-width: 291px) 100vw, 291px\" \/>Buenos d\u00edas lectores! Espero que est\u00e9n poniendo en practica los consejos que les voy dando. Quiero seguir teniendo seguidores sanos y fuertes!<br \/>\nHe pensado en ir preguntando sobre los temas que m\u00e1s os interesan, y escribir sobre aquellos que m\u00e1s comentados. As\u00ed que pueden ir enviando sus preguntas o preferencias!! Siempre referente a la salud y nutrici\u00f3n claro.<!--more--> De electricidad o fontaner\u00eda no ser\u00eda de gran ayuda\u2026<\/p>\n<p>Hoy les hablar\u00e9 de una serie de alimentos que ayudan a proteger y mantener joven a nuestro cerebro. Todos ellos son ricos en antioxidantes e incluy\u00e9ndolos en tu dieta de forma regular, mejoraras tus capacidades cognitivas.<\/p>\n<h3>Pescado azul<\/h3>\n<p>Pescados como el at\u00fan, caballa, sardinas, salm\u00f3n, anchoa, salmonete, anguila, arenque, caz\u00f3n, etc.. son ricos en \u00e1cidos grasos omega-3. El omega-3 es un antioxidante que nuestro cuerpo no lo puede sintetizar, por lo que debemos consumir alimentos que lo contengan para disfrutar de sus beneficios.<br \/>\nEntre sus propiedades, destaca la prevenci\u00f3n del envejecimiento prematuro celular y espec\u00edficamente el de las neuronas. Al parecer con dos raciones a la semana, reducimos en gran medida la p\u00e9rdida de memoria.<\/p>\n<h3>Pl\u00e1tano<\/h3>\n<p>Es un producto f\u00e1cil de conseguir y generalmente asequible. Su alto contenido en potasio y amino\u00e1cidos como el tript\u00f3fano le otorgan propiedades muy saludables. Entre ellas, aumenta la concentraci\u00f3n, memoria y el estado de alerta, ejerce un efecto sedante del sistema nervioso, estabiliza el estado de animo y combate enfermedades como la depresi\u00f3n y la ansiedad gracias al tript\u00f3fano.<\/p>\n<h3>Aguacate<\/h3>\n<p>Muy beneficioso para las neuronas gracias a su gran aporte de potasio, vitamina E, vitaminas del grupe B, omega-3, \u00e1cido f\u00f3lico y aceites vegetales, siendo la mayor\u00eda \u00e1cidos grasos monoinsaturados, como el oleico.<\/p>\n<h3>Nueces<\/h3>\n<p>Son ricos en polifenoles, antioxidantes naturales que adem\u00e1s de aumentar las capacidades cognitivas y proteger nuestras neuronas, son beneficiosos para nuestro sistema cardiovascular. El \u00fanico problema es que debemos tener cuidado en no comerlos en exceso, porque son muy cal\u00f3ricos. Con 3 nueces diarias es m\u00e1s que suficiente.<\/p>\n<h3>Br\u00f3coli<\/h3>\n<p>Al parecer una <a title=\"Vitamina K y procesos cognitivos\" href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/23850343\" target=\"_blank\">investigaci\u00f3n<\/a> revela que su gran aporte de vitamina K podr\u00eda prevenir patolog\u00edas neurodegenerativas como la enfermedad de Alzheimer.<\/p>\n<h3>Ar\u00e1ndanos<\/h3>\n<p>Algunos <a title=\"EStudio Harvard medical School.\" href=\"http:\/\/onlinelibrary.wiley.com\/doi\/10.1002\/ana.23594\/abstract\" target=\"_blank\">estudios<\/a> afirman que comer diariamente frutos rojos y sobre todo ar\u00e1ndanos,gracias a los flavonoides, previene la perdida de memoria y mejora la concentraci\u00f3n.<\/p>\n<p>Espero que les sea de utilidad y les parezca interesante.<br \/>\nSaludos a todos!<br \/>\nHasta el pr\u00f3ximo post!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buenos d\u00edas lectores! Espero que est\u00e9n poniendo en practica los consejos que les voy dando. Quiero seguir teniendo seguidores sanos y fuertes! He pensado en ir preguntando sobre los temas que m\u00e1s os interesan, y escribir sobre aquellos que m\u00e1s comentados. As\u00ed que pueden ir enviando sus preguntas o preferencias!! Siempre referente a la salud y nutrici\u00f3n claro.<\/p>\n","protected":false},"author":9,"featured_media":64764,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-64763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud-bienestar"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=64763"}],"version-history":[{"count":2,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64763\/revisions"}],"predecessor-version":[{"id":64766,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64763\/revisions\/64766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/64764"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=64763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=64763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=64763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}