{"id":64810,"date":"2017-03-16T12:46:34","date_gmt":"2017-03-16T16:46:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=64810"},"modified":"2017-03-16T12:49:39","modified_gmt":"2017-03-16T16:49:39","slug":"prince-royce-pide-union","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/prince-royce-pide-union\/","title":{"rendered":"Prince Royce pide uni\u00f3n"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Prince-Royce-45754345.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-24992\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Prince-Royce-45754345.jpg\" alt=\"Prince-Royce-45754345\" width=\"465\" height=\"427\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Prince-Royce-45754345.jpg 465w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2013\/04\/sosua_images_Prince-Royce-45754345-300x275.jpg 300w\" sizes=\"auto, (max-width: 465px) 100vw, 465px\" \/><\/a>M\u00e9xico. EFE. El cantante neoyorquino de origen dominicano Prince Royce lanz\u00f3 hoy un mensaje en favor de la uni\u00f3n de la comunidad latina en Estados Unidos, especialmente tras la \u201cnegatividad y violencia\u201d inyectada por el presidente Donald Trump desde la campa\u00f1a electoral.<!--more--><\/p>\n<p>\u201cEn Estados Unidos estamos viviendo momentos dif\u00edciles y creo que estamos en un momento donde hay que unirnos como personas, como comunidad\u201d, dijo en una rueda de prensa en la Ciudad de M\u00e9xico para presentar su \u00faltimo disco, \u201cFive\u201d.<\/p>\n<p>El cantante, criado en el Bronx, inst\u00f3 a no caer en \u201cla negatividad ni la violencia que el presidente utiliz\u00f3 a lo largo de su campa\u00f1a\u201d, y consider\u00f3 que es momento de \u201cunirse y rezar por lo mejor\u201d.<\/p>\n<p>\u201cHay que aceptar la realidad, nuestra realidad, y trabajar juntos para defendernos como comunidad\u201d, indic\u00f3 el artista.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e9xico. EFE. El cantante neoyorquino de origen dominicano Prince Royce lanz\u00f3 hoy un mensaje en favor de la uni\u00f3n de la comunidad latina en Estados Unidos, especialmente tras la \u201cnegatividad y violencia\u201d inyectada por el presidente Donald Trump desde la campa\u00f1a electoral.<\/p>\n","protected":false},"author":12,"featured_media":24992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-64810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=64810"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64810\/revisions"}],"predecessor-version":[{"id":64814,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/64810\/revisions\/64814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/24992"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=64810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=64810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=64810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}