{"id":65086,"date":"2017-04-01T13:05:36","date_gmt":"2017-04-01T17:05:36","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=65086"},"modified":"2017-04-01T13:05:36","modified_gmt":"2017-04-01T17:05:36","slug":"correcaminos-y-eduardo-del-batey-triunfan-en-el-basket-superior-de-pp","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/correcaminos-y-eduardo-del-batey-triunfan-en-el-basket-superior-de-pp\/","title":{"rendered":"Correcaminos y Eduardo del Batey triunfan en el Basket Superior de PP"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/17626666_579615638875528_5499777824950402482_n-678x381.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-65087\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/17626666_579615638875528_5499777824950402482_n-678x381.jpg\" alt=\"\" width=\"529\" height=\"297\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/17626666_579615638875528_5499777824950402482_n-678x381.jpg 678w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/17626666_579615638875528_5499777824950402482_n-678x381-300x169.jpg 300w\" sizes=\"auto, (max-width: 529px) 100vw, 529px\" \/><\/a>San Felipe Puerto Plata.- Los quintetos de Correcaminos de la Parte Baja y Eduardo de Batey obtuvieron victorias en la continuaci\u00f3n del XXIII Torneo de Baloncesto Superior con refuerzo de esta ciudad, el cual tiene una especial al licenciado Juan Ram\u00f3n G\u00f3mez D\u00edaz; Presidente del Grupo Telemicro y en opci\u00f3n a la Copa Ayuntamiento de Puerto Plata.<!--more--><\/p>\n<p>Previo al primer compromiso se realiz\u00f3 un minuto de silencio en la memoria del empresario Willy Rivera, quien falleci\u00f3 en los Estados Unidos, Willy era hermano de Carlos Rivera y primo de William N\u00fa\u00f1ez Grano de Oro y John Grano de Oro.<\/p>\n<p><strong>Polanco gu\u00eda a los Correcaminos<\/strong><br \/>\nEl estelar canastero Bernardo Polanco anot\u00f3 27 puntos para guiar a los Correcaminos de la Parte Baja 93-89 sobre las Cotorras de Gustavo, en el primer choque de la doble jornada.<\/p>\n<p>La primera mitad finalizo 55-38 a favor de los ganadores que son dirigidos por el t\u00e9cnico puertoplate\u00f1o Ram\u00f3n Cabrera, quienes dominaron los dos primeros dos cuartos 28-12 y 27-26.<\/p>\n<p>Adem\u00e1s de los 27 puntos de Polanco aport\u00f3 con 5 rebotes y 4 asistencias, el refuerzo H\u00e9ctor Cordero consigui\u00f3 un doble-doble 23 puntos y 13 rebotes, Yohan Torres totalizo 16 encestes y Pedro N\u00fa\u00f1ez lig\u00f3 11 tantos con 6 capturas.<\/p>\n<p>Por la causa perdida se destacaron; Rafael Cris\u00f3stomo con 27 puntos y 4 rebotes Javier Bonilla 16 y 6 rebotes, Juan Pichardo 13 tantos y reparti\u00f3 7 asistencias, Oliver Gonz\u00e1lez 13 puntos y 5 asistencias y Christopher Acevedo viniendo desde la banca encest\u00f3 12.<\/p>\n<p>Los Correcaminos dominaron la captura de los rebotes 44-23.<br \/>\nLas Cotorras conquistaron el tercer y cuarto periodo 33-22 y 18-16 respectivamente, pero esto no basto para ser derrotados 93-89.<\/p>\n<p>\u201cNos vimos bien en la cancha, debemos reajustar m\u00e1s la defensa, gracias a Dios salimos por la puerta grande, yo confi\u00f3 bastante en mis muchachos, las Cotorras remontaron pero est\u00e1bamos preparado mentalmente, siempre vamos a ver m\u00e1s de 8 jugadores jugando, tenemos un equipo muy aguerrido, les exhorto a todos los fan\u00e1ticos que se den cita y apoyen el torneo\u201d expres\u00f3 Ram\u00f3n Cabrera; dirigente de los Correcaminos.<\/p>\n<p><strong>Eduardo del Batey vence a los Sharks.<\/strong><br \/>\nAl cierre de la doble jornada, los Eduardo del Batey contaron con 5 jugadores en cifras dobles en puntos para vencer 104-102 a los Sos\u00faa Sharks en dos tiempo extra.<\/p>\n<p>El partido marco el regreso del veterano jugador Marlon Mart\u00ednez (El Rey), el cual fue aplaudido por todos los fan\u00e1ticos presentes en su entrada al Techado Fabio Rafael Gonz\u00e1lez.<\/p>\n<p>El saque de honor del encuentro fue realizado por el licenciado Jos\u00e9 Ignacio Paliza, Senador de la Rep\u00fablica, a quien se le dedicado la doble jornada del viernes. Paliza quien se siente comprometido con el deporte en toda la provincia de Puerto Plata.<br \/>\nJean Carlos Severino \u00a0lider\u00f3 a cinco compa\u00f1eros en cifras dobles en puntos con 23 puntos y 7 rebotes, Juan Carlos Ortega anot\u00f3 20 y otorg\u00f3 8 asistencias, el Rey Marlon Mart\u00ednez hizo un doble-doble 17 puntos, 13 rebotes y 2 tiros bloqueados y los nativos de la Vega; Reyson Beato 16 puntos con 4 tiros de 3, 8 rebotes y 4 asistencias y Edison Esquea se fue con 15 tantos y 15 atrapadas.<\/p>\n<p>Mientras que en el rev\u00e9s, Tyrone Jhonson 24 puntos, 5 rebotes y 4 asistencias, Leyvi Ciriaco 18 y 14 rebotes, Jos\u00e9 Polanco y Pedro Alcequie 14 puntos cada uno.<\/p>\n<p>Los Sharks dominaron la primera mitad 45-36, el tercero tambi\u00e9n 31-25, pero el cuarto periodo los Eduardo del Batey lo ganaron 25-9 para irse a tiempo extra. El primer tiempo extra termino empatado a 10 y el segundo 9-7 a favor de los Sharks.<br \/>\nDespu\u00e9s del encuentro Marlon Mart\u00ednez manifest\u00f3 lo siguiente \u201cContento de regresar al baloncesto, debemos mejorar en la posici\u00f3n uno, pero sabemos que lo haremos en cada partido, Mikigua me transmite mucha motivaci\u00f3n en cancha, tenemos 20 a\u00f1os jugando juntos, los Sharks son un equipo bien aguerrido, en un momento nos sacaron 18 puntos, pudimos remontar y sacar el partido, exh\u00f3rtale a los fan\u00e1ticos que apoyen su equipo y el torneo\u201d.<\/p>\n<p><strong>Partidos del domingo.<\/strong><br \/>\nEl torneo retorna este domingo 2 de abril con doble jornada desde las 6 de la tarde en el Techado Fabio Rafael Gonz\u00e1lez, a primera hora chocar\u00e1n los Eduardo del Batey (1-0) Vs Mellizos del Sur (0-1) y a segunda hora cerrar\u00e1n los Sos\u00faa Sharks (1-1) Vs Cotorras del Gustavo (0-1).<\/p>\n<p>La justa es organizada por la Asociaci\u00f3n de Baloncesto de Puerto Plata, comercializador por la empresa Medios Creativos y contar\u00e1 con el Aval de la Federaci\u00f3n Dominicana de Baloncesto.<\/p>\n<p>El XXIII torneo cuenta con el auspicio del Ministerio de Deportes, Farmacia Popular, Brugal &amp; Co., Ayuntamiento de Puerto Plata, Ferreter\u00eda Frank Felipe, Cervecer\u00eda Nacional Dominicana, S\u00faper Gato, Oficina Senatorial, Viva tu voz, Producto Mar\u00eda, Compraventa Antonio, Ferreter\u00eda Internacional Freddy Pop Cinemas, BanResarvas. Ferreter\u00eda Ing. Edgar Mart\u00ednez entre otras.<br \/>\nPie de foto 1: El Senador Jos\u00e9 Ignacio Paliza realiza el saque de honor.<\/p>\n<p>Pie de foto 2: Marlon Mart\u00ednez realiza una gesti\u00f3n ofensiva ante Sa\u00fal Mart\u00ednez.<\/p>\n<p>Escrito por: Pedro L\u00f3pez Ortega<\/p>\n<p>Prensa Abapplata<\/p>\n","protected":false},"excerpt":{"rendered":"<p>San Felipe Puerto Plata.- Los quintetos de Correcaminos de la Parte Baja y Eduardo de Batey obtuvieron victorias en la continuaci\u00f3n del XXIII Torneo de Baloncesto Superior con refuerzo de esta ciudad, el cual tiene una especial al licenciado Juan Ram\u00f3n G\u00f3mez D\u00edaz; Presidente del Grupo Telemicro y en opci\u00f3n a la Copa Ayuntamiento de Puerto Plata.<\/p>\n","protected":false},"author":12,"featured_media":65087,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-65086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=65086"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65086\/revisions"}],"predecessor-version":[{"id":65088,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65086\/revisions\/65088"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/65087"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=65086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=65086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=65086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}