{"id":65746,"date":"2017-04-19T22:16:15","date_gmt":"2017-04-20T02:16:15","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=65746"},"modified":"2017-04-19T22:16:15","modified_gmt":"2017-04-20T02:16:15","slug":"como-podemos-asegurarnos-de-que-google-maps-no-nos-rastrea","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/como-podemos-asegurarnos-de-que-google-maps-no-nos-rastrea\/","title":{"rendered":"\u00bfC\u00f3mo podemos asegurarnos de que Google Maps no nos rastrea?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/google-maps.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-65747\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/google-maps.jpg\" alt=\"\" width=\"750\" height=\"422\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/google-maps.jpg 750w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/google-maps-300x169.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a>Google ha incorporado una\u00a0funci\u00f3n llamada Timeline en su aplicaci\u00f3n Google Maps para los dispositivos iOS, lo que permitir\u00e1 a sus usuarios ver todos los lugares y localizaciones donde han estado.<!--more--><\/p>\n<p>Esta funci\u00f3n, que antes ya estaba disponible en los dispositivos Android, permite ver el historial de todos sus sitios visitados y sus movimientos, <strong>archivado con fechas e incluso con el tipo de transporte a trav\u00e9s del cual ha llegado all\u00ed<\/strong> y con la ruta concreta recorrida. O sea, las preguntas \u00ab\u00bfc\u00f3mo se llamaba aquel restaurante donde estuve\u00a0con mis amigos la semana pasada?\u00bb o \u00ab\u00bfcuando estuve\u00a0all\u00ed?\u00bb ya no son un problema.<\/p>\n<h3>\u00bfC\u00f3mo utilizar Timeline?<\/h3>\n<p>Para ver el historial de sus movimientos y lugares visitados primero hay que asegurarse de que usted tiene la \u00faltima actualizaci\u00f3n de la aplicaci\u00f3n Google Maps. Adem\u00e1s, para que el gigante tecnol\u00f3gico\u00a0pueda utilizar la informaci\u00f3n de ubicaci\u00f3n, de b\u00fasqueda y de navegaci\u00f3n y crear la cronolog\u00eda, hay que activar la Ubicaci\u00f3n y el Historial de Ubicaciones en su\u00a0tel\u00e9fono o tableta.<\/p>\n<p>De esta forma, en la secci\u00f3n Your Timeline aparecer\u00e1n todos los lugares en los que haya estado con los dispositivos en los que inici\u00f3\u00a0sesi\u00f3n con su cuenta de Google.<\/p>\n<div class=\"arcticle-media arcticle-media_js_slider\"><img decoding=\"async\" src=\"https:\/\/esp.rt.com\/actualidad\/public_images\/2017.04\/original\/58f7e3ddc46188455d8b462f.jpg\" \/><\/p>\n<div class=\"arcticle-media__caption\"><span class=\"arcticle-media__caption-item\">pixabay.com<\/span><\/div>\n<\/div>\n<p>Asimismo, es posible\u00a0<strong>suscribirse\u00a0a recordatorios<\/strong> mensuales a trav\u00e9s del correo electr\u00f3nico y\u00a0<strong>corregir la ruta<\/strong> si por alg\u00fan motivo la aplicaci\u00f3n muestra una ubicaci\u00f3n err\u00f3nea.<\/p>\n<p>Sin embargo, Google <a href=\"https:\/\/support.google.com\/maps\/answer\/6258979?co=GENIE.Platform%3DiOS&amp;hl=es&amp;oco=1\">advierte<\/a>\u00a0de que a\u00fan no se puede ver la cronolog\u00eda en la aplicaci\u00f3n Google Maps para iPhone o iPad y que, por el momento, hay que utilizar el ordenador para seguirla.<\/p>\n<h3>\u00bfC\u00f3mo me aseguro de que Google Maps no me rastrea?<\/h3>\n<p>Si esta funci\u00f3n le asusta y tiene\u00a0miedo de que Google pueda seguir todos sus pasos, tambi\u00e9n es posible desactivar la funci\u00f3n que guarda este tipo de informaci\u00f3n o eliminar los datos ya guardados. Para hacerlo, solo hay que abrir Ajustes y all\u00ed elegir qu\u00e9 tipo de informaci\u00f3n puede la aplicaci\u00f3n guardar (tambi\u00e9n puede no guardar ninguna)\u00a0y eliminar cualquier dato registrado durante un\u00a0per\u00edodo de tiempo concreto (o todos los existentes).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google ha incorporado una\u00a0funci\u00f3n llamada Timeline en su aplicaci\u00f3n Google Maps para los dispositivos iOS, lo que permitir\u00e1 a sus usuarios ver todos los lugares y localizaciones donde han estado.<\/p>\n","protected":false},"author":12,"featured_media":65747,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-65746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=65746"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65746\/revisions"}],"predecessor-version":[{"id":65749,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65746\/revisions\/65749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/65747"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=65746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=65746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=65746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}