{"id":65858,"date":"2017-04-23T17:47:46","date_gmt":"2017-04-23T21:47:46","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=65858"},"modified":"2017-04-23T17:59:22","modified_gmt":"2017-04-23T21:59:22","slug":"base-aerea-puerto-plata-participa-en-varios-operativos-mixtos-en-sosua","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/base-aerea-puerto-plata-participa-en-varios-operativos-mixtos-en-sosua\/","title":{"rendered":"Base A\u00e9rea Puerto Plata participa en varios operativos mixtos en Sos\u00faa"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.42-PM.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-65861\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.42-PM.jpeg\" alt=\"\" width=\"418\" height=\"418\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.42-PM.jpeg 1280w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.42-PM-150x150.jpeg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.42-PM-300x300.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.42-PM-768x768.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.42-PM-1024x1024.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.42-PM-120x120.jpeg 120w\" sizes=\"auto, (max-width: 418px) 100vw, 418px\" \/><\/a>Sos\u00faa.- Por instrucciones del Comandante de la Base A\u00e9rea Puerto Plata, Coronel Piloto Juan Dar\u00edo Tejada Quintana, personal de dicha Base de la Fuerza A\u00e9rea de Rep\u00fablica Dominicana, participaron junto a miembros de la Polic\u00eda Nacional en un extenso operativo de requisici\u00f3n de documentos y veh\u00edculos.<!--more--><\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.49-PM.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-65859 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.49-PM.jpeg\" alt=\"\" width=\"215\" height=\"215\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.49-PM.jpeg 1280w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.49-PM-150x150.jpeg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.49-PM-300x300.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.49-PM-768x768.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.49-PM-1024x1024.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.49-PM-120x120.jpeg 120w\" sizes=\"auto, (max-width: 215px) 100vw, 215px\" \/><\/a> Esta jornada inici\u00f3 a las 3 de la madrugada, extendi\u00e9ndose por diferentes zonas del municipio de Sos\u00faa donde fueron apresadas 4 personas para fines de investigaci\u00f3n, 50 motocicletas requisadas, 5 motocicletas detenidas por falta de documentos y 35 veh\u00edculos de cuatro ruedas requisados en un promedio de 3 horas.<\/p>\n<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.46-PM.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-65860 alignright\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.46-PM.jpeg\" alt=\"\" width=\"171\" height=\"170\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.46-PM.jpeg 1280w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.46-PM-150x150.jpeg 150w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.46-PM-300x300.jpeg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.46-PM-768x768.jpeg 768w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.46-PM-1024x1024.jpeg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/WhatsApp-Image-2017-04-23-at-5.31.46-PM-120x120.jpeg 120w\" sizes=\"auto, (max-width: 171px) 100vw, 171px\" \/><\/a>El objetivo de estos operativos es trabajar apegados al llamado realizado por el Se\u00f1or Ministro de Defensa, Teniente General ERD Ruben Dar\u00edo Paulino Sem, en apoyo al Plan de Seguridad Interna y Ciudadana dispuesto por el Excelent\u00edsimo Se\u00f1or Presidente de la Rep\u00fablica, Lic. Danilo Medina S\u00e1nchez, que se desarrolla conjuntamente con los dem\u00e1s organismos y agencias de seguridad, para contribuir a mejorar el clima de seguridad en la sociedad.<\/p>\n<p>Por: Odil Beato<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sos\u00faa.- Por instrucciones del Comandante de la Base A\u00e9rea Puerto Plata, Coronel Piloto Juan Dar\u00edo Tejada Quintana, personal de dicha Base de la Fuerza A\u00e9rea de Rep\u00fablica Dominicana, participaron junto a miembros de la Polic\u00eda Nacional en un extenso operativo de requisici\u00f3n de documentos y veh\u00edculos.<\/p>\n","protected":false},"author":12,"featured_media":65861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-65858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sosua-en-el-mundo"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=65858"}],"version-history":[{"count":3,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65858\/revisions"}],"predecessor-version":[{"id":65864,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65858\/revisions\/65864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/65861"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=65858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=65858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=65858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}