{"id":65940,"date":"2017-04-26T09:45:49","date_gmt":"2017-04-26T13:45:49","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=65940"},"modified":"2017-04-26T09:45:49","modified_gmt":"2017-04-26T13:45:49","slug":"receta-del-dia-pechuga-de-pollo-en-salsa-de-coco","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/receta-del-dia-pechuga-de-pollo-en-salsa-de-coco\/","title":{"rendered":"Receta del d\u00eda: pechuga de pollo en salsa de coco"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/pechuga-en-salsa-de-coco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-65941\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/pechuga-en-salsa-de-coco.jpg\" alt=\"\" width=\"642\" height=\"398\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/pechuga-en-salsa-de-coco.jpg 642w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/pechuga-en-salsa-de-coco-300x186.jpg 300w\" sizes=\"auto, (max-width: 642px) 100vw, 642px\" \/><\/a>Preparar una pechuga de una forma diferente, sabrosa y saludable no tiene que ser un dolor de cabeza ni conllevar procedimientos extensos.<!--more--><\/p>\n<p>Sigue estos sencillos pasos y sorprende con esta receta.<\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<p>1 cucharada de aceite de oliva<\/p>\n<p>1 pechuga de pollo<\/p>\n<p>sal y pimienta, a gusto<\/p>\n<p>\u00bc de cebolla picada<\/p>\n<p>\u00bc taza de vino<\/p>\n<p>\u00bd taza de leche de coco<\/p>\n<p>\u00bc taza de\u00a0crema de coco<\/p>\n<p>1 cucharadita de ajo molido<\/p>\n<p>\u00bd lim\u00f3n verde<\/p>\n<p>1 cucharada de mantequilla<\/p>\n<p><strong>Procedimiento:<\/strong><\/p>\n<ol>\n<li>\n<p>Calienta aceite de oliva en un sart\u00e9n.<\/p>\n<\/li>\n<li>\n<p>A\u00f1ade la pechuga.<\/p>\n<\/li>\n<li>\n<p>\u00c9chale sal y pimienta, a gusto, y hasta que selle por cada lado.<img decoding=\"async\" id=\"plcAd-01\" class=\"b-lazy placeAdImg\" src=\"data:image\/gif;base64,R0lGODlhAQABAID\/AMDAwAAAACH5BAEAAAAALAAAAAABAAEAAAICRAEAOw==\" data-src=\"data:image\/gif;base64,R0lGODlhAQABAID\/AMDAwAAAACH5BAEAAAAALAAAAAABAAEAAAICRAEAOw==\" data-div-src=\"oas_x71\" \/><\/p>\n<\/li>\n<li>\n<p>Precalienta el horno convencional a 400 grados.<\/p>\n<\/li>\n<li>\n<p>Pon la pechuga en el horno y deja cocinar durante 10 minutos.<\/p>\n<\/li>\n<li>\n<p>Retira la pechuga.<\/p>\n<\/li>\n<li>\n<p>En el mismo sart\u00e9n, con los jugos de la pechuga, sofr\u00ede la cebolla a fuego mediano.<\/p>\n<\/li>\n<li>\n<p>A\u00f1ade vino, baja a fuego lento y mezcla.<\/p>\n<\/li>\n<li>\n<p>Echa ajo molido y lim\u00f3n, y mezcla.<\/p>\n<\/li>\n<li>\n<p>Incorpora la leche y la crema de coco.<\/p>\n<\/li>\n<li>\n<p>Echa ralladura de lim\u00f3n y mezcla.<\/p>\n<\/li>\n<li>\n<p>A\u00f1ade la mantequilla y cocina, agitando hasta que se derrita.<\/p>\n<\/li>\n<li>\n<p>Retira la mezcla del fuego.<\/p>\n<\/li>\n<li>\n<p>Pica la pechuga en trozos y sirve en un plato.<\/p>\n<\/li>\n<li>\n<p>Vierte la salsa de coco y adorna, a gusto.<\/p>\n<\/li>\n<li>\n<p>Buen provecho.<\/p>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>Preparar una pechuga de una forma diferente, sabrosa y saludable no tiene que ser un dolor de cabeza ni conllevar procedimientos extensos.<\/p>\n","protected":false},"author":12,"featured_media":65941,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-65940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cocina"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=65940"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65940\/revisions"}],"predecessor-version":[{"id":65942,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65940\/revisions\/65942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/65941"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=65940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=65940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=65940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}