{"id":65956,"date":"2017-04-26T14:00:34","date_gmt":"2017-04-26T18:00:34","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=65956"},"modified":"2017-04-26T14:00:34","modified_gmt":"2017-04-26T18:00:34","slug":"informan-77-comunidades-estan-aisladas","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/informan-77-comunidades-estan-aisladas\/","title":{"rendered":"Informan 77 comunidades est\u00e1n aisladas"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/crecida-de-rio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-65964\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/crecida-de-rio.jpg\" alt=\"\" width=\"643\" height=\"435\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/crecida-de-rio.jpg 643w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/crecida-de-rio-300x203.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/04\/crecida-de-rio-75x52.jpg 75w\" sizes=\"auto, (max-width: 643px) 100vw, 643px\" \/><\/a>Las lluvias disminuyeron en gran parte del pa\u00eds, pero los desplazados de sus viviendas aumentaron a 17,560, entre ellos 415 personas fueron asistidas durante la noche y la ma\u00f1ana por la crecidas de r\u00edos y 328 personas han sido rescatadas al quedar atrapadas por las corrientes, seg\u00fan el \u00faltimo reporte del Centro de Operaciones de Emergencias (COE) y la Oficina Nacional de Meteorolog\u00eda (Onamet).<!--more--><br \/>\nAyer en horas de la tarde se report\u00f3 17,145 desplazados aumentando hoy a 17,560; 77 comunidades incomunicadas; 3,500 viviendas afectadas, 39 acueductos afectados, seg\u00fan se inform\u00f3.<br \/>\nEn las \u00faltimas horas la mayor cantidad de operaciones de los socorristas se ha realizado en la provincia Duarte por la crecida del r\u00edo Yuna en horas de la ma\u00f1ana rescatando personas atrapadas por las corrientes en las comunidades de Juana Rodr\u00edguez, Loma Colora, Acicate, La Barca, La Barca, La Jabiela, La Isleta, Cerrej\u00f3n, El Toro, seg\u00fan confirm\u00f3 el general Juan Manuel M\u00e9ndez Garc\u00eda.<br \/>\nDebido a esa situaci\u00f3n el COE mantiene 22 provincias en alerta, entre ellas est\u00e1n en alerta roja Mar\u00eda Trinidad S\u00e1nchez, Duarte, en especial la zona del Bajo Yuna; S\u00e1nchez Ram\u00edrez y San Crist\u00f3bal en especial Villa Altagracia.<br \/>\nMeteorolog\u00eda anunci\u00f3 hoy que las lluvias disminuir\u00e1n en gran parte del pa\u00eds debido a que una masa de aire con poco contenido de humedad ha comenzado a incidir en el \u00e1rea de pron\u00f3stico.<br \/>\nSin embargo el COE mantiene vigente la recomendaci\u00f3n para que las personas deben abstenerse de cruzar r\u00edos, arroyos y ca\u00f1adas que contin\u00faen presentando alto contenido de agua.<br \/>\nTambi\u00e9n se le advirti\u00f3 a las personas que viven en terrenos de altas pendientes en las provincias en alerta que deben permanecer alerta porque pueden ocurrir deslizamientos de tierra.<br \/>\n<strong>El tiempo<\/strong><br \/>\nMeteorolog\u00eda inform\u00f3 que el calor diurno se combinar\u00e1 para producir despu\u00e9s del mediod\u00eda aguaceros con tormentas el\u00e9ctricas en las regiones suroeste, fronteriza, Los Haitises y la cordillera Central, seg\u00fan el predictor Francisco Holgu\u00edn.<br \/>\nSanto Domingo permanecer\u00e1 medio nublado con aguaceros dispersos en el transcurso de la tarde.<br \/>\nTambi\u00e9n ocurrir\u00e1n aguaceros en Santiago, Puerto Plata, Duarte, Peravia, San Pedro de Macor\u00eds, La Vega, Monse\u00f1or Nouel, San Crist\u00f3bal, Saman\u00e1, Montecristi, Azua, San Juan de la Maguana y La Altagracia.<br \/>\nSin embargo, ma\u00f1ana otra vaguada comenzar\u00e1 a incidir en el \u00e1rea del pron\u00f3stico para producir aguaceros con tormentas el\u00e9ctricas en las regiones nordeste, norte y el centro del pa\u00eds.<\/p>\n<blockquote><p><strong>Un Apunte<\/strong><\/p>\n<p><strong>Vuelven las lluvias<\/strong><\/p>\n<p>A partir de ma\u00f1ana otra vaguada volver\u00e1 incidir en las condiciones del tiempo produciendo aguaceros con tormentas el\u00e9ctricas en las regiones noroeste, norte y la porci\u00f3n central del territorio nacional, seg\u00fan el pron\u00f3stico de la Oficina Nacional de Meteorolog\u00eda.<\/p><\/blockquote>\n<p><strong>Alertas<\/strong><br \/>\nEl COE contin\u00faa con alertas para San Pedro de Macor\u00eds, La Romana y La Altagracia.<br \/>\nContinuaban en amarilla Espaillat, Hermanas Mirabal, Monse\u00f1or Nouel, La Vega, San Pedro de Macor\u00eds, y Gran Santo Domingo, San Jos\u00e9 de Ocoa, Peravia, Azua, Barahona y Monte Plata.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las lluvias disminuyeron en gran parte del pa\u00eds, pero los desplazados de sus viviendas aumentaron a 17,560, entre ellos 415 personas fueron asistidas durante la noche y la ma\u00f1ana por la crecidas de r\u00edos y 328 personas han sido rescatadas al quedar atrapadas por las corrientes, seg\u00fan el \u00faltimo reporte del Centro de Operaciones de Emergencias (COE) y la Oficina Nacional de Meteorolog\u00eda (Onamet).<\/p>\n","protected":false},"author":12,"featured_media":65964,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-65956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=65956"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65956\/revisions"}],"predecessor-version":[{"id":65965,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/65956\/revisions\/65965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/65964"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=65956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=65956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=65956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}