{"id":66051,"date":"2017-05-01T09:52:43","date_gmt":"2017-05-01T13:52:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=66051"},"modified":"2017-05-01T09:52:43","modified_gmt":"2017-05-01T13:52:43","slug":"google-celebra-el-dia-del-trabajo-con-un-doodle","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/google-celebra-el-dia-del-trabajo-con-un-doodle\/","title":{"rendered":"Google celebra el D\u00eda del Trabajo con un Doodle"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/trabahjoo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66054\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/trabahjoo.jpg\" alt=\"\" width=\"787\" height=\"313\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/trabahjoo.jpg 787w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/trabahjoo-300x119.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/trabahjoo-768x305.jpg 768w\" sizes=\"auto, (max-width: 787px) 100vw, 787px\" \/><\/a>La p\u00e1gina de inicio de Google est\u00e1 dedicada al D\u00eda Internacional de los Trabajadores, conocido tambi\u00e9n como D\u00eda del Trabajo o Primero de mayo.<!--more--><\/p>\n<p>El doodle muestra un campo, una f\u00e1brica y edificios en construcci\u00f3n para rendir homenaje a los trabajadores.<\/p>\n<p>El origen de este d\u00eda se remonta a 1886. Trabajadores estadounidenses iniciaron una huelga para luchar por la jornada laboral de ocho horas (ocho horas para trabajar, ocho para dormir y ocho de ocio).<\/p>\n<p>Ahora, cada 1 de mayo se rinde homenaje a los llamados \u2018m\u00e1rtires de Chicago\u2019, ciudad donde se produjeron enfrentamientos violentos entre los trabajadores y las fuerzas de seguridad.<\/p>\n<p>En Estados Unidos y en Canad\u00e1 el D\u00eda del Trabajo se celebra el primer lunes de septiembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La p\u00e1gina de inicio de Google est\u00e1 dedicada al D\u00eda Internacional de los Trabajadores, conocido tambi\u00e9n como D\u00eda del Trabajo o Primero de mayo.<\/p>\n","protected":false},"author":12,"featured_media":66054,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-66051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=66051"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66051\/revisions"}],"predecessor-version":[{"id":66055,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66051\/revisions\/66055"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/66054"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=66051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=66051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=66051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}