{"id":6621,"date":"2014-07-26T18:32:43","date_gmt":"2014-07-26T22:32:43","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=6621"},"modified":"2014-07-26T12:35:53","modified_gmt":"2014-07-26T16:35:53","slug":"juguete-sexual-quedo-atrapado-en-su-vagina-por-10-anos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/juguete-sexual-quedo-atrapado-en-su-vagina-por-10-anos\/","title":{"rendered":"Juguete sexual qued\u00f3 atrapado en su vagina por 10 a\u00f1os"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/165622_1027sex2_principal.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6622 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/165622_1027sex2_principal-300x200.jpg\" alt=\"165622_1027sex2_principal\" width=\"300\" height=\"200\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/165622_1027sex2_principal-300x200.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2014\/07\/165622_1027sex2_principal.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>La\u00a0<label style=\"color: #0000ff;\">mujer<\/label>\u00a0dijo a los m\u00e9dicos que podr\u00eda tratarse de un juguete sexual que dej\u00f3 hace 10 a\u00f1os dentro de su vagina, luego de un\u00a0<label style=\"color: #0000ff;\">encuentro<\/label>\u00a0sexual muy apasionado mientras se encontraba totalmente borracha.<!--more--><\/p>\n<p>Para los que nos acusen de que esta\u00a0<label style=\"color: #0000ff;\">historia<\/label>\u00a0es falsa, pues no, es muy seria y de hecho apareci\u00f3 publicada como caso m\u00e9dico en la edici\u00f3n de junio de la revista especializada: Journal of Sexual Medicine.<\/p>\n<p>Una mujer de 38 a\u00f1os de edad, residente en Escocia, acudi\u00f3 al m\u00e9dico reportando que sufr\u00eda c\u00f3licos contundentes, incontinencia y severa p\u00e9rdida de peso; pero lo que en realidad le suced\u00eda es que un juguete sexual hab\u00eda quedado atrapado desde hace 10 a\u00f1os en su vagina.<\/p>\n<p>La mujer, quien parec\u00eda estar totalmente al cien\u00a0<label style=\"color: #0000ff;\">por ciento<\/label>\u00a0de sus\u00a0<label style=\"color: #0000ff;\">facultades<\/label>, dijo a los m\u00e9dicos que podr\u00eda tratarse de un juguete sexual que dej\u00f3 hace 10 a\u00f1os dentro de su vagina, luego de un encuentro sexual muy apasionado mientras se encontraba totalmente borracha, lo que habr\u00eda provocado que olvidara sac\u00e1rselo.<\/p>\n<p>El juguete sexual de unos 12 cent\u00edmetros de longitud, caus\u00f3 una obstrucci\u00f3n en la vejiga que habr\u00eda provocado el desarrollo de varias afectaciones en las v\u00edas urinarias de la paciente, adem\u00e1s de una fisura vesico-vaginal, que imped\u00eda la adecuada circulaci\u00f3n de la orina.<\/p>\n<p>El objeto inapropiadamente insertado en la vagina, le fue extirpado y ahora la mujer est\u00e1 en recuperaci\u00f3n.<\/p>\n<p>Fuente:\u00a0<a style=\"color: #006e94;\" href=\"http:\/\/www.sdpnoticias.com\/sorprendente\/2014\/07\/24\/juguete-sexual-quedo-atrapado-en-vagina-durante-10-anos\" target=\"_blank\">SDP Noticias<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La\u00a0mujer\u00a0dijo a los m\u00e9dicos que podr\u00eda tratarse de un juguete sexual que dej\u00f3 hace 10 a\u00f1os dentro de su vagina, luego de un\u00a0encuentro\u00a0sexual muy apasionado mientras se encontraba totalmente borracha.<\/p>\n","protected":false},"author":3,"featured_media":6622,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-6621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=6621"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6621\/revisions"}],"predecessor-version":[{"id":6623,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/6621\/revisions\/6623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/6622"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=6621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=6621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=6621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}