{"id":66214,"date":"2017-05-08T16:07:47","date_gmt":"2017-05-08T20:07:47","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=66214"},"modified":"2017-05-08T16:07:47","modified_gmt":"2017-05-08T20:07:47","slug":"netflix-y-whatsapp-involucrados-en-engano-electronico","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/netflix-y-whatsapp-involucrados-en-engano-electronico\/","title":{"rendered":"Netflix y WhatsApp involucrados en enga\u00f1o electr\u00f3nico"},"content":{"rendered":"<p><b><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/whatsapp-y-netflix.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-66215\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/whatsapp-y-netflix.jpg\" alt=\"\" width=\"637\" height=\"423\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/whatsapp-y-netflix.jpg 1024w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/whatsapp-y-netflix-300x199.jpg 300w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/whatsapp-y-netflix-768x510.jpg 768w\" sizes=\"auto, (max-width: 637px) 100vw, 637px\" \/><\/a>Netflix<\/b> es la plataforma de video m\u00e1s popular a nivel mundial, teniendo una gran demanda a lo largo del globo. Muchas de las personas que a\u00fan no est\u00e1n suscritas al servicio de streaming buscan registrarse dentro de la misma, aunque al ser un servicio de pago mensual, no todas tienen la oportunidad de absorberlo. Eso han utilizado estafadores en diferente plataformas para salirse con la suya, como hoy es el caso en <b>WhatsApp<\/b>.<!--more--><\/p>\n<p>Se ha alertado este lunes de una falsa promoci\u00f3n que se difunde a trav\u00e9s <b>WhatsApp<\/b> en la que se promete un a\u00f1o de suscripci\u00f3n gratuita a <b>Netflix<\/b> pero en realidad esta trata de conseguir el n\u00famero de tel\u00e9fono de los usuarios para suscribirlos a servicios premium no solicitados que se cargan en su factura de tel\u00e9fono.<\/p>\n<p>Esta estafa se une a otra que fue difundida la semana pasada en la que se avisaba al usuario que solo quedaban 530 nuevas cuentas para <b>WhatsApp<\/b> y que pronto dejar\u00eda de ser un servicio gratuito por lo que llamaba a realizar un click dentro de un enlace, que tambi\u00e9n redirig\u00eda hacia enlaces con servicios premium.<\/p>\n<p>El nuevo caso de estafa afirma que \u201c<b><i>Netflix<\/i><\/b> <i>est\u00e1 regalando un a\u00f1o<\/i> <i>de<\/i> <i>suscripci\u00f3n gratuita<\/i>\u201d. Viene acompa\u00f1ado de un enlace falso en el que aparece la palabra y el logo de <b>Netflix<\/b>. Pero al hacer click no dirige al servicio del v\u00eddeo sino a otra p\u00e1gina que se hace pasar por la identidad corporativa de <b>Netflix<\/b>.<\/p>\n<p>Como ocurri\u00f3 en el anterior intento de estafa, las personas encargadas de esta estafa le piden al destinatario que comparta con 10 o m\u00e1s amigos este enlace con el objeto de poder extender esta falsa promoci\u00f3n, aprovechando la confianza de que el enlace llegue de un n\u00famero conocido.<\/p>\n<p>Tras haber pasado todo esto, el enlace solicita un tel\u00e9fono celular para poder hacer completo el proceso y as\u00ed asegurar la promoci\u00f3n, con el fin de usar el n\u00famero para realizar una serie de procesos de facturaci\u00f3n adicional que se incrementar\u00e1n en la factura. Es conocido que adem\u00e1s de realizar este tipo de cargos, los delincuentes suelen infectar los aparatos m\u00f3viles con diversos <b>malwares<\/b> (virus maliciosos).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Netflix es la plataforma de video m\u00e1s popular a nivel mundial, teniendo una gran demanda a lo largo del globo. Muchas de las personas que a\u00fan no est\u00e1n suscritas al servicio de streaming buscan registrarse dentro de la misma, aunque al ser un servicio de pago mensual, no todas tienen la oportunidad de absorberlo. Eso han utilizado estafadores en diferente plataformas para salirse con la suya, como hoy es el caso en WhatsApp.<\/p>\n","protected":false},"author":12,"featured_media":66215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-66214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia-tecnologia"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=66214"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66214\/revisions"}],"predecessor-version":[{"id":66218,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66214\/revisions\/66218"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/66215"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=66214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=66214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=66214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}