{"id":66592,"date":"2017-05-29T01:26:04","date_gmt":"2017-05-29T05:26:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=66592"},"modified":"2017-05-28T22:38:34","modified_gmt":"2017-05-29T02:38:34","slug":"kennedy-cien-anos-de-un-mito-que-aun-fascina-a-estados-unidos","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/kennedy-cien-anos-de-un-mito-que-aun-fascina-a-estados-unidos\/","title":{"rendered":"Kennedy, cien a\u00f1os de un mito que a\u00fan fascina a Estados Unidos"},"content":{"rendered":"<div><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/kennedy-cien-anos-de-un-mito-que-aun-fascina-a-estados-unidos.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-66596\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/kennedy-cien-anos-de-un-mito-que-aun-fascina-a-estados-unidos.jpeg\" alt=\"\" width=\"294\" height=\"307\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/kennedy-cien-anos-de-un-mito-que-aun-fascina-a-estados-unidos.jpeg 294w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/05\/kennedy-cien-anos-de-un-mito-que-aun-fascina-a-estados-unidos-287x300.jpeg 287w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/><\/a>Cien a\u00f1os despu\u00e9s de su nacimiento, el mito de John Fitzgerald Kennedy, conocido popularmente como JFK, sigue m\u00e1s vivo que nunca en EE.UU., donde muchos compatriotas le veneran como un s\u00edmbolo de las esperanzas y aspiraciones de su pa\u00eds.<\/div>\n<p><!--more--><\/p>\n<p>El trig\u00e9simo quinto presidente de Estados Unidos cumplir\u00eda hoy un siglo desde que naci\u00f3 en una casa relativamente modesta en Brookline, a las afueras de Boston (Massachusetts).<\/p>\n<div>Pese a una fr\u00e1gil salud, el \u00fanico mandatario cat\u00f3lico que ha ocupado la Casa Blanca no defraud\u00f3 a sus padres, de origen irland\u00e9s.<\/div>\n<div>\u00c1vido lector, reconocido donju\u00e1n y amante del deporte, Kennedy viaj\u00f3 por Europa, donde su padre fue embajador de EE.UU. en Londres; se gradu\u00f3 en Humanidades con honores en la Universidad de Harvard y combati\u00f3 en la II Guerra Mundial, de donde volvi\u00f3 como un h\u00e9roe.<\/div>\n<div style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"http:\/\/www.youtube.com\/embed\/enqcpnW8st4\" width=\"670\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<div>Tras ejercer de congresista y senador en el Capitolio de Washington, el joven John alcanz\u00f3 el cenit de su carrera pol\u00edtica el 8 de noviembre de 1960, cuando se impuso como candidato dem\u00f3crata al republicano Richard Nixon en unas re\u00f1idas elecciones presidenciales.<\/div>\n<div>Bien es sabido que durante su Presidencia Kennedy lidi\u00f3 con el fracasado intento de invasi\u00f3n de la cubana Bah\u00eda de Cochinos para derrocar a Fidel Castro (1961), la Crisis de los Misiles de Cuba (1962), que coloc\u00f3 al planeta al borde de una guerra nuclear entre EE.UU. y la Uni\u00f3n Sovi\u00e9tica, y el impulso de la carrera por la exploraci\u00f3n del espacio exterior, entre otros desaf\u00edos.<\/div>\n<div>De su legado resuena con fuerza su genial oratoria, encumbrada en la famosa frase de su discurso de investidura pronunciado el 20 de enero de 1961: \u00abNo preguntes qu\u00e9 es lo que tu pa\u00eds puede hacer por ti; pregunta qu\u00e9 es lo que t\u00fa puedes hacer por tu pa\u00eds\u00bb.<\/div>\n<div>Y todo el mundo conoce, c\u00f3mo no, el tr\u00e1gico final de JFK el 22 de noviembre de 1963, cuando recibi\u00f3 varios impactos de bala en el centro de Dallas (Texas) que segaron su vida a la edad de 46 a\u00f1os, un asesinato grabado a fuego en la memoria colectiva de EE.UU.<\/div>\n<div>Con motivo ahora de su centenario, la imagen joven y optimista de Kennedy renace en el recuerdo de los estadounidenses merced a la celebraci\u00f3n de actos conmemorativos en todo el pa\u00eds.<\/div>\n<div>Esa imagen reluce en un sello que el Servicio Postal de Estados Unidos emiti\u00f3 para celebrar los cien a\u00f1os de JFK.<\/div>\n<div>El timbre reproduce el emblem\u00e1tico retrato que el fot\u00f3grafo Ted Spiegel hizo de Kennedy en 1960 durante un acto de campa\u00f1a electoral en la Plaza de la Victoria de Seattle, en el que el entonces aspirante presidencial dem\u00f3crata, vestido para el mitin con traje y corbata, eleva la mirada con semblante pensativo y optimista.<\/div>\n<div>Tambi\u00e9n conmemora el centenario el Kennedy Center, el templo de las artes esc\u00e9nicas de Washington que toma el nombre del mandatario y rinde homenaje a su pasi\u00f3n por el arte.<\/div>\n<div>La instituci\u00f3n ha programado una serie de conciertos y espect\u00e1culos inspirados en sus ideales: el coraje, la libertad, la justicia, el servicio y la gratitud.<\/div>\n<div>A unos diez minutos a pie del centro cultural se llega a Georgetown, el barrio m\u00e1s pintoresco y elegante de Washington, donde pasear por sus calles adoquinadas supone una inmersi\u00f3n en la biograf\u00eda de John Fitzgerald Kennedy.<\/div>\n<div>No en vano, Kennedy residi\u00f3 en Georgetown en su etapa de congresista y senador, antes de mudarse a la Casa Blanca.<\/div>\n<div>JFK dej\u00f3 una huella muy especial en el c\u00e9lebre \u00abMartin&#8217;s Tavern\u00bb, un acogedor e hist\u00f3rico pub de inconfundible fachada amarilla.<\/div>\n<div>Cuenta la leyenda y, recuerdan una y otra vez los due\u00f1os del pub, que Kennedy pidi\u00f3 matrimonio en el \u00abReservado 3\u00bb a la periodista Jacqueline Bouvier (m\u00e1s conocida como Jackie) el 24 de junio de 1953, tras regresar la joven de cubrir la coronaci\u00f3n de la reina Isabel II de Inglaterra para el diario Washington Times Herald.<\/div>\n<div>\u00abCada semana tenemos aqu\u00ed dos o tres proposiciones. Quieren pedir matrimonio donde lo hizo JFK\u00bb, asegura a Efe Chrissy Gardner, responsable de mercadotecnia del establecimiento.<\/div>\n<div>Cerca del pub, JFK acud\u00eda cada domingo a la hist\u00f3rica Iglesia de la Santa Trinidad, donde vivi\u00f3 su \u00faltima misa antes de su muerte.<\/div>\n<div>Los restos de JFK yacen en el Cementerio Nacional de Arlington, a las afueras de la capital estadounidense, junto a los de Jackie, que muri\u00f3 de un c\u00e1ncer el 19 de mayo de 1994 a los 64 a\u00f1os.<\/div>\n<div>De d\u00eda y de noche, llueva o nieve, la tumba de Kennedy est\u00e1 alumbrada por la \u00abllama eterna\u00bb.<\/div>\n<div>Es un s\u00edmbolo de que su memoria sigue viva y de que, como rezaba un pasaje de su discurso de investidura, \u00abel resplandor de ese fuego puede iluminar el mundo\u00bb.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cien a\u00f1os despu\u00e9s de su nacimiento, el mito de John Fitzgerald Kennedy, conocido popularmente como JFK, sigue m\u00e1s vivo que nunca en EE.UU., donde muchos compatriotas le veneran como un s\u00edmbolo de las esperanzas y aspiraciones de su pa\u00eds.<\/p>\n","protected":false},"author":12,"featured_media":66596,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[311],"tags":[],"class_list":["post-66592","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesante-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=66592"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66592\/revisions"}],"predecessor-version":[{"id":66597,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66592\/revisions\/66597"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/66596"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=66592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=66592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=66592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}