{"id":66877,"date":"2017-06-04T22:11:31","date_gmt":"2017-06-05T02:11:31","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=66877"},"modified":"2017-06-04T22:11:31","modified_gmt":"2017-06-05T02:11:31","slug":"rihanna-vetada-por-los-warriors-tras-su-show-del-game-1","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/rihanna-vetada-por-los-warriors-tras-su-show-del-game-1\/","title":{"rendered":"Rihanna, vetada por los Warriors tras su show del Game 1"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/06\/rihanna.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-66880\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/06\/rihanna.gif\" alt=\"\" width=\"605\" height=\"403\" \/><\/a>En el primer partido de las <strong>Finales 2017<\/strong> entre <strong>Golden State Warriors<\/strong> y <strong>Cleveland Cavaliers<\/strong>, una de las celebridades que estuvo presenciando el enfrentamiento fue <strong>Rihanna<\/strong> quien hizo un show que no cay\u00f3 nada bien en la franquicia de <strong>Oakland<\/strong> y por ello fue vetada.<!--more--><\/p>\n<p>La cantante de 29 a\u00f1os es fan confesa de los Cavaliers y gran amiga de <strong>LeBron James<\/strong> a quien le hizo una reverencia durante un momento del partido. Sin embargo, el hecho por el que Rihanna fue vetada tiene que ver con el grito que ella le hizo a <strong>Kevin Durant<\/strong> cuando se dispon\u00eda a lanzar un tiro libre<strong><em>. \u201c\u00a1Brick!\u201d<\/em><\/strong> (\u00a1Ladrillo!) le dijo en voz alta al alero que minutos despu\u00e9s le lanz\u00f3 una mirada desafiante cuando meti\u00f3 un triple.<\/p>\n<p>Bueno pues los Warriors por esta raz\u00f3n han decidido vetarla. Su m\u00fasica no se escuchar\u00e1 en el vestuario pero <strong>Stephen Curry<\/strong>, quien fue consultado por el incidente fue el que lo confirm\u00f3. \u201c<strong><em>Ni siquiera era un tipo de m\u00fasica que estuviera ah\u00ed antes<\/em><\/strong>\u201c, expres\u00f3 el base de 29 a\u00f1os de Golden State.<\/p>\n<p>Seguramente las dos partes no estaban interesados en tener la m\u00fasica de Rihanna dentro del repertorio para salir motivados y concentrados a la cancha. Los Warriors porque la cantante es fan confesa de sus rivales en las <strong>Finales de la NBA<\/strong> y la propia int\u00e9rprete porque no querr\u00e1 ser quien impulse el buen juego de Golden State ante su amigo.<\/p>\n<p>Contin\u00faan entonces las decisiones por el incidente entre la celebridad y unos Warriors que intentar\u00e1n quedarse con el anillo de campe\u00f3n 2017.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el primer partido de las Finales 2017 entre Golden State Warriors y Cleveland Cavaliers, una de las celebridades que estuvo presenciando el enfrentamiento fue Rihanna quien hizo un show que no cay\u00f3 nada bien en la franquicia de Oakland y por ello fue vetada.<\/p>\n","protected":false},"author":12,"featured_media":66880,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-66877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=66877"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66877\/revisions"}],"predecessor-version":[{"id":66881,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/66877\/revisions\/66881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/66880"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=66877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=66877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=66877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}