{"id":67019,"date":"2017-06-10T19:22:56","date_gmt":"2017-06-10T23:22:56","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=67019"},"modified":"2017-06-10T19:22:56","modified_gmt":"2017-06-10T23:22:56","slug":"me-acoste-con-mi-mejor-amigo-y-ahora-que","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/me-acoste-con-mi-mejor-amigo-y-ahora-que\/","title":{"rendered":"Me acost\u00e9 con mi mejor amigo, \u00bfy ahora qu\u00e9?"},"content":{"rendered":"<p><a href=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/06\/Me-acost\u00e9-con-mi-mejor-amigo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-67020\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/06\/Me-acost\u00e9-con-mi-mejor-amigo.jpg\" alt=\"\" width=\"678\" height=\"381\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/06\/Me-acost\u00e9-con-mi-mejor-amigo.jpg 678w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/06\/Me-acost\u00e9-con-mi-mejor-amigo-300x169.jpg 300w\" sizes=\"auto, (max-width: 678px) 100vw, 678px\" \/><\/a>Pas\u00f3 hace muchos a\u00f1os, solo una vez. Pero todav\u00eda \u201cVer\u00f3nica\u201d repasa c\u00f3mo la experiencia de tener intimidad sexual con su mejor amigo cambi\u00f3 para siempre <strong>la din\u00e1mica de su relaci\u00f3n con el hombre que le hab\u00eda regalado su amistad por m\u00e1s de una d\u00e9cada<\/strong>.<!--more--><\/p>\n<p>\u201cJaime\u201d y ella se conocieron en la escuela superior. Con el pasar de los a\u00f1os, la conexi\u00f3n entre ambos creci\u00f3 cada vez m\u00e1s, al punto de confiar aspectos de su vida que inclu\u00eda lo concerniente a sus intereses amorosos con otras personas.<\/p>\n<ul>\n<li><a href=\"https:\/\/laopinion.com\/2017\/06\/07\/cuanto-sexo-tienen-parejas-normalmente\/\" rel=\"bookmark\">\u00bfCu\u00e1nto sexo tienen las parejas\u00a0normalmente?<\/a><\/li>\n<\/ul>\n<p>\u201cSal\u00edamos mucho en grupo, pero tambi\u00e9n<strong> tom\u00e1bamos momentos para salir solos los dos, sin ninguna intenci\u00f3n mayor<\/strong> que la de convivir como dos amigos\u201d, recuerda la mujer de 35 a\u00f1os, quien prefiri\u00f3 ocultar su nombre real.<\/p>\n<p>\u201cEn una de esas salidas, yo le di un raid a su casa. Los dos est\u00e1bamos pasaditos de tragos. \u00c9l me invit\u00f3 a pasar a la casa, para hablar como otras veces hac\u00edamos, pero esta vez, nos pusimos a coquetear a modo de broma, hasta que <strong>una cosa llev\u00f3 a la otra y cuando vinimos a ver, ya est\u00e1bamos en la cama<\/strong>\u201d, relata, asegurando que no recuerda qui\u00e9n de los dos comenz\u00f3 con el flirteo.<\/p>\n<p>\u201cAl otro d\u00eda, fue inc\u00f3modo cuando nos despertamos. Como que no nos atrev\u00edamos a hablar del asunto. Yo me sent\u00eda con algo de culpa, y hasta me preguntaba qu\u00e9 pasar\u00eda con nuestra amistad\u201d.<\/p>\n<p>Ver\u00f3nica, quien aclara que al momento del encuentro sexual ninguno ten\u00eda pareja, menciona que comenz\u00f3 a notar c\u00f3mo su amigo se fue alejando poco a poco.<strong> Nunca se habl\u00f3 de la situaci\u00f3n. Compart\u00edan con su grupo de amistades acostumbrado<\/strong>, pero \u00e9l mostraba mayor distanciamiento. Incluso, lleg\u00f3 el momento en que se enteraba sobre la vida de Jaime a trav\u00e9s de terceros. Nada volvi\u00f3 a ser como antes.<\/p>\n<p>\u201cLa verdad que me choc\u00f3 bastante\u201d. Y de paso confiesa que fue luego que reconoci\u00f3 que se sent\u00eda atra\u00edda hacia \u00e9l, \u201cpero era algo que yo hab\u00eda preferido dejar como algo plat\u00f3nico\u201d. Tras su experiencia, reflexiona que \u201cno debi\u00f3 haber pasado. <strong>Perd\u00ed a un gran amigo. Lo echo de menos<\/strong>\u201d.<\/p>\n<div id=\"fsk_splitbox_502_onscreen\"><\/div>\n<h2>Todo depende<\/h2>\n<p>En tiempos modernos no es extra\u00f1o que se d\u00e9 una din\u00e1mica de atracci\u00f3n entre dos personas que acuerden ser amigos con privilegios. \u00bfPero <strong>qu\u00e9 pasa cuando el encuentro \u00edntimo se da de modo casual entre dos personas<\/strong> que estaban \u201cseguras\u201d de que no hab\u00eda mayor atractivo que el de una amistad?<\/p>\n<p>\u201cEso puede ocurrir con mucha frecuencia\u201d, aclara el psic\u00f3logo cl\u00ednico Carlos Sosa. \u201cPosiblemente 30 o 20 a\u00f1os atr\u00e1s eso era lo m\u00e1s grande del mundo, pero hoy d\u00eda hay m\u00e1s flexibilidad\u201d.<\/p>\n<p>El experto en conducta humana observa que \u201c<strong>hoy d\u00eda las normas est\u00e1n bien flexibles y el concepto de lo moral ha cambiado<\/strong>. Esas din\u00e1micas se dan con m\u00e1s facilidad y se puede procesar alejado de los sentimientos de culpa\u201d.<\/p>\n<p>Sin embargo, a la hora de manejar este \u201cdesliz\u201d, Sosa aclara que <strong>\u201ctodo depende de la salud mental que tengamos para enfrentarlo<\/strong>, porque si una pareja es consciente de que esas cosas pueden ocurrir, y la madurez mental determina que \u2018somos amigos y aqu\u00ed no ha pasado nada\u2019, se puede seguir adelante en la amistad\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-1017323\" src=\"https:\/\/eldiariony.files.wordpress.com\/2016\/05\/shutterstock_257038960.jpg?quality=60&amp;strip=all&amp;w=940&amp;strip=all\" alt=\"sexo oral\" width=\"940\" height=\"627\" data-attachment-id=\"1017323\" data-permalink=\"https:\/\/eldiariony.com\/2017\/04\/11\/tips-tao-sexual-placer-total\/shutterstock_257038960\/\" data-orig-file=\"https:\/\/eldiariony.files.wordpress.com\/2016\/05\/shutterstock_257038960.jpg?quality=60&amp;strip=all\" data-orig-size=\"1000,667\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"sexo oral\" data-image-description=\"\" data-medium-file=\"https:\/\/eldiariony.files.wordpress.com\/2016\/05\/shutterstock_257038960.jpg?quality=60&amp;strip=all&amp;w=300\" data-large-file=\"https:\/\/eldiariony.files.wordpress.com\/2016\/05\/shutterstock_257038960.jpg?quality=60&amp;strip=all&amp;w=940\" data-lazy-loaded=\"true\" \/><\/p>\n<p>En el caso espec\u00edfico de Ver\u00f3nica, analiza que \u201cposiblemente el amigo se alej\u00f3 porque quiz\u00e1s solamente la valoraba como<strong> una buena amiga y entiende que cruz\u00f3 una l\u00ednea que no debi\u00f3 haber cruzado<\/strong>, se sinti\u00f3 inc\u00f3modo. Posiblemente le ten\u00eda miedo a alg\u00fan tipo de consecuencia que pudiera surgir con ese tipo de comportamiento\u201d.<\/p>\n<p>Incluso, es posible que le preocupara que ella se sintiera atra\u00edda hacia \u00e9l. \u201cCabe la posibilidad de que \u00e9l temiera que ella pudiera haber quedado con expectativas tras el encuentro, cuando en realidad \u00e9l no sent\u00eda que pod\u00eda corresponderle. Eso puede ser una raz\u00f3n\u201d.<\/p>\n<h2>Varias las circunstancias<\/h2>\n<p>Al abundar sobre las razones que pueden llevar a que ocurra una experiencia sexual entre amigos, el doctor es enf\u00e1tico en que \u201c<strong>no necesariamente significa que haya una atracci\u00f3n f\u00edsica o amor<\/strong>. Puede que hayan mediado otras circunstancias\u201d.<\/p>\n<p>Si bien aborda que \u201c<strong>un hombre y una mujer pueden ser amigos sin que medie un inter\u00e9s rom\u00e1ntico<\/strong>\u201d, tambi\u00e9n aclara que existen varias razones que pueden motivar a que surja un encuentro sexual entre ambos.<\/p>\n<p>\u201cPuede surgir como resultado de varias situaciones. A lo mejor la persona se encuentra un poco deprimida, necesita una muestra de cari\u00f1o, y a veces, pues cruzan un umbral que no esperaban cruzar en un momento dado\u201d, menciona a modo de ejemplo.<\/p>\n<p>Tambi\u00e9n, quiz\u00e1s \u201c<strong>estaban de fiesta, estaban de humor, hab\u00eda algunos traguitos de m\u00e1s, se sent\u00edan muy relajados<\/strong> y posiblemente empezaron a coquetear como parte de un jueguito, pero luego que se involucraron y terminaron en el acto, con la acci\u00f3n\u201d.<\/p>\n<p>Por su parte, la psic\u00f3loga Omayra Rivera Rivera destaca que \u201cla cercan\u00eda, el tiempo que comparten, el conocimiento que cada uno tenga del otro en t\u00e9rminos de sus fortalezas y debilidades, as\u00ed como los intereses en com\u00fan, pueden <strong>precipitar el que se traspase esa barrera de amistad en el aspecto sexual<\/strong>\u201d.<\/p>\n<p>Ante la experiencia, Sosa recalca que todo depender\u00e1 \u201cde la actitud y posici\u00f3n mental con la que se interprete la experiencia. <strong>Pueden estar claros de que se puede seguir con la amistad<\/strong>, que no tiene que terminar ni tomar un rumbo diferente\u201d.<\/p>\n<h2>Hay que dialogar<\/h2>\n<p>El doctor menciona que si ambos lo creen conveniente, \u201ces bueno <strong>hablarlo porque la comunicaci\u00f3n siempre es el mejor instrumento para clarificar<\/strong> y llegar a acuerdo positivos para todo tipo de relaci\u00f3n. A veces no es necesario ni hablarlo porque con la actitud se puede ver que pas\u00f3 y ah\u00ed qued\u00f3. Es una pena que se pierda una amistad por una situaci\u00f3n que se puede interpretar de una manera m\u00e1s madura para seguir para adelante\u201d.<\/p>\n<p>Del mismo modo, Rivera Rivera destaca que \u201cla comunicaci\u00f3n es clave y determinar\u00e1 el curso de la relaci\u00f3n. Solo con el di\u00e1logo pudiera cada uno <strong>expresar su sentir y dejar claro las razones que provocaron dicho encuentro<\/strong>, as\u00ed como los pasos a seguir luego de esto\u201d.<\/p>\n<p>De hecho, \u201cignorar lo que pas\u00f3 puede abrir la puerta a especulaciones, malos entendidos y en el peor de los casos, poner fin a la relaci\u00f3n de amistad\u201d.<\/p>\n<p>La doctora a\u00f1ade que \u201c<strong>una vez dialogado el asunto, y de no haber alg\u00fan inter\u00e9s m\u00e1s de all\u00e1 de la amistad por parte de ambos, deben intentar seguir la amistad como acostumbraban<\/strong>. Definitivamente, la madurez y la solidez de la relaci\u00f3n juega un factor fundamental para que dichos lazos contin\u00faen\u201d.<\/p>\n<p>Ahora bien, si uno de los dos entiende que est\u00e1 enamorado del otro, Sosa advierte que \u201chay una variable nueva y va a haber dificultades porque en una relaci\u00f3n de pareja tienen que estar de acuerdo los dos.<strong> T\u00fa no puedes pretender que una persona est\u00e9 contigo si no siente la misma atracci\u00f3n por ti<\/strong>. Entonces tienes que aprender a manejar eso de una forma efectiva, aprender a tomar decisiones emocionales\u201d que abarquen la realidad de no ser correspondido y la posibilidad de ver a esa persona feliz con otra pareja.<\/p>\n<p>A su vez, la psic\u00f3loga se\u00f1ala que \u201ces muy com\u00fan que alguna de las partes pueda enamorarse dado al tiempo que comparten y los intereses en com\u00fan.<strong> Es importante destacar que un mejor amigo o amiga es alguien que escogemos por lo similar que es a nosotros<\/strong>, por tal raz\u00f3n esas mismas caracter\u00edsticas tambi\u00e9n las buscamos en una pareja. Es muy com\u00fan que alguna de las partes comience a sentirse atra\u00edda emocionalmente m\u00e1s all\u00e1 de una amistad\u201d.<\/p>\n<p>\u2013 Rosa Escribano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pas\u00f3 hace muchos a\u00f1os, solo una vez. Pero todav\u00eda \u201cVer\u00f3nica\u201d repasa c\u00f3mo la experiencia de tener intimidad sexual con su mejor amigo cambi\u00f3 para siempre la din\u00e1mica de su relaci\u00f3n con el hombre que le hab\u00eda regalado su amistad por m\u00e1s de una d\u00e9cada.<\/p>\n","protected":false},"author":12,"featured_media":67020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[312],"tags":[],"class_list":["post-67019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comentando-online"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/67019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=67019"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/67019\/revisions"}],"predecessor-version":[{"id":67021,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/67019\/revisions\/67021"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/67020"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=67019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=67019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=67019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}