{"id":67512,"date":"2017-07-17T09:14:04","date_gmt":"2017-07-17T13:14:04","guid":{"rendered":"http:\/\/sosuaonline.net\/inicio\/?p=67512"},"modified":"2017-07-17T09:14:04","modified_gmt":"2017-07-17T13:14:04","slug":"procurador-general-dominicano-coordina-con-departamento-de-justicia-eeuu-acciones-contra-delitos-transnacionales","status":"publish","type":"post","link":"https:\/\/sosuaonline.net\/inicio\/procurador-general-dominicano-coordina-con-departamento-de-justicia-eeuu-acciones-contra-delitos-transnacionales\/","title":{"rendered":"Procurador General dominicano coordina con Departamento de Justicia EEUU acciones contra delitos transnacionales"},"content":{"rendered":"<p class=\"DETALLE_N_titulo \"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-67513 alignleft\" src=\"http:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/07\/i00007-m6ao6xsejpg.jpg\" alt=\"\" width=\"287\" height=\"191\" srcset=\"https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/07\/i00007-m6ao6xsejpg.jpg 500w, https:\/\/sosuaonline.net\/inicio\/wp-content\/uploads\/2017\/07\/i00007-m6ao6xsejpg-300x200.jpg 300w\" sizes=\"auto, (max-width: 287px) 100vw, 287px\" \/>Santo Domingo (EFE).- Representantes de la Procuradur\u00eda General dominicana y del Departamento de Justicia de Estados Unidos se reunieron en Santo Domingo para coordinar acciones que permitan una mayor colaboraci\u00f3n en la persecuci\u00f3n de delitos transnacionales, inform\u00f3 el organismo del pa\u00eds caribe\u00f1o.<!--more--><\/p>\n<div id=\"texto\" class=\"texto_txt\">\n<div class=\"DETALLE_N_texto \">\n<p><span id=\"ctl14_lblMostra\">La delegaci\u00f3n estadounidense estuvo encabezada por Magdalena Boynton, directora de la Oficina de Asuntos Internacionales del Departamento de Justicia, quien se reuni\u00f3 con el procurador general dominicano, Jean Alain Rodr\u00edguez.<\/span><\/p>\n<p>Rodr\u00edguez explic\u00f3 que durante este encuentro se trat\u00f3 la lucha contra la corrupci\u00f3n, el narcotr\u00e1fico, el lavado de activos, el tr\u00e1fico de armas y la trata de personas.<\/p>\n<p>Tambi\u00e9n se abord\u00f3 la tramitaci\u00f3n de extradiciones entre ambos pa\u00edses, entre otros temas, seg\u00fan un comunicado emitido por la Procuradur\u00eda General de la Rep\u00fablica (PGR).<\/p>\n<p>Boynton expres\u00f3 \u201csatisfacci\u00f3n en torno al manejo que la Procuradur\u00eda General de la Rep\u00fablica est\u00e1 dando a las investigaciones que desarrolla y, en particular, ponder\u00f3 los avances en la lucha contra la corrupci\u00f3n\u201d, seg\u00fan el documento.<\/p>\n<p>La funcionaria reiter\u00f3 \u201cel firme\u201d apoyo del Gobierno de Estados Unidos al trabajo que realiza esta dependencia.<\/p>\n<p>Rodr\u00edguez agradeci\u00f3 la disposici\u00f3n del Departamento de Justicia de Estados Unidos para incrementar la colaboraci\u00f3n bilateral con el Ministerio P\u00fablico dominicano e indic\u00f3 que esto se enmarca en la continuidad de los temas tratados durante la visita que realiz\u00f3 en mayo pasado al fiscal general de EE.UU, Jeff Sessions.<\/p>\n<p>La cooperaci\u00f3n incluye el rastreo y la localizaci\u00f3n de dinero de implicados en casos de corrupci\u00f3n, narcotr\u00e1fico y lavado, dijo. EFE<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Santo Domingo (EFE).- Representantes de la Procuradur\u00eda General dominicana y del Departamento de Justicia de Estados Unidos se reunieron en Santo Domingo para coordinar acciones que permitan una mayor colaboraci\u00f3n en la persecuci\u00f3n de delitos transnacionales, inform\u00f3 el organismo del pa\u00eds caribe\u00f1o.<\/p>\n","protected":false},"author":9,"featured_media":67513,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[88],"tags":[],"class_list":["post-67512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/67512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/comments?post=67512"}],"version-history":[{"count":1,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/67512\/revisions"}],"predecessor-version":[{"id":67514,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/posts\/67512\/revisions\/67514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media\/67513"}],"wp:attachment":[{"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/media?parent=67512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/categories?post=67512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sosuaonline.net\/inicio\/wp-json\/wp\/v2\/tags?post=67512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}